{"id":10390,"date":"2022-08-10T18:21:03","date_gmt":"2022-08-10T23:21:03","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=10390"},"modified":"2022-08-10T18:21:04","modified_gmt":"2022-08-10T23:21:04","slug":"se-debe-declarar-la-nulidad-de-la-eleccion-en-tamaulipas-por-el-financiamiento-ilegal-julen-rementeria","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/08\/10\/se-debe-declarar-la-nulidad-de-la-eleccion-en-tamaulipas-por-el-financiamiento-ilegal-julen-rementeria\/","title":{"rendered":"SE DEBE DECLARAR LA NULIDAD DE LA ELECCI\u00d3N EN TAMAULIPAS POR EL FINANCIAMIENTO ILEGAL: JULEN REMENTER\u00cdA."},"content":{"rendered":"\n<p>El coordinador de senadores de Acci\u00f3n Nacional, Julen Rementer\u00eda del Puerto, precis\u00f3 que se debe declarar la nulidad en la elecci\u00f3n de Tamaulipas, como se est\u00e1 demandando en los tribunales, por el financiamiento ilegal que hubo en la campa\u00f1a del gobernador electo.<\/p>\n\n\n\n<p>\u201cHay claras muestras de que en Tamaulipas intervino el financiamiento ilegal y lo que se tiene que hacer es anular esa elecci\u00f3n\u2026 Hace un par de d\u00edas pudimos conocer de manera p\u00fablica la evidencia que vincula a la campa\u00f1a de Tamaulipas, al Gobierno del estado, del pasado 5 de junio, con el \u201cfamoso\u201d Rey del Huachicol, Sergio Carmona, ya fallecido\u201d, indic\u00f3.<\/p>\n\n\n\n<p>El senador Rementer\u00eda se\u00f1al\u00f3 que las evidencias expuestas p\u00fablicamente, a trav\u00e9s de una investigaci\u00f3n period\u00edstica, muestra claramente la colusi\u00f3n de Morena por el financiamiento ilegal, hay conversaciones con Sergio Carmona, declaraciones del piloto involucran al hoy gobernador electo de Tamaulipas, as\u00ed como la documentaci\u00f3n del financiamiento a campa\u00f1as para el partido en el poder.<\/p>\n\n\n\n<p>\u201cNo se puede permitir que en este pa\u00eds haya este tipo de pr\u00e1cticas y menos que queden impunes, s\u00ed las hay, porque transgreden la ley, tiene que haber una instancia en la v\u00eda jurisdiccional que la aplique la sanci\u00f3n que corresponde en este caso, aqu\u00ed es la nulidad de la elecci\u00f3n, como se est\u00e1 solicitando en los tribunales\u201d.<\/p>\n\n\n\n<p>Rementer\u00eda del Puerto reprob\u00f3 que estas acciones de financiamiento ilegal, no solamente se realiz\u00f3 en Tamaulipas, sino que hay pruebas que demuestran que hubo \u201capoyo\u201d ilegal a otros estados donde gobierna y gobernar\u00e1 Morena.<\/p>\n\n\n\n<p>\u201cDesde la C\u00e1mara Alta, solicitamos de manera p\u00fablica a la autoridad electoral que se decrete la nulidad de esa campa\u00f1a y se convoque a nuevos comicios, es lo que en justicia corresponde\u201d, finaliz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coordinador de senadores de Acci\u00f3n Nacional, Julen Rementer\u00eda del Puerto, precis\u00f3 que se debe declarar la nulidad en la elecci\u00f3n de Tamaulipas, como se est\u00e1 demandando en los tribunales, por el financiamiento ilegal que hubo en la campa\u00f1a del gobernador electo. \u201cHay claras muestras de que en Tamaulipas intervino el financiamiento ilegal y lo que se tiene que hacer es anular esa elecci\u00f3n\u2026 Hace un par de d\u00edas pudimos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,51],"tags":[],"class_list":["post-10390","post","type-post","status-publish","format-standard","hentry","category-pan","category-senado","wpcat-17-id","wpcat-51-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=10390"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10390\/revisions"}],"predecessor-version":[{"id":10391,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10390\/revisions\/10391"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=10390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=10390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=10390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}