{"id":10605,"date":"2022-08-22T20:15:40","date_gmt":"2022-08-23T01:15:40","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=10605"},"modified":"2022-08-22T20:15:41","modified_gmt":"2022-08-23T01:15:41","slug":"desmantelamiento-de-planta-en-dinamita-en-su-fase-final-osg","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/08\/22\/desmantelamiento-de-planta-en-dinamita-en-su-fase-final-osg\/","title":{"rendered":"DESMANTELAMIENTO DE PLANTA EN DINAMITA EN SU FASE FINAL: OSG."},"content":{"rendered":"\n<p>Comarca Lagunera.- Al medio d\u00eda, en el poblado de Dinamita, Durango; se llev\u00f3 a<br>cabo la reuni\u00f3n de seguimiento a la fase de desmantelamiento de infraestructura y<br>maquinar\u00eda de la planta instalada en esta zona, entre los pobladores, directivos de la<br>empresa Draslovka, funcionarios municipales de G\u00f3mez Palacio y el subsecretario de<br>gobierno en la regi\u00f3n Laguna, Oswaldo Santib\u00e1\u00f1ez Garc\u00eda.<\/p>\n\n\n\n<p>Al respecto, Oswaldo Santib\u00e1\u00f1ez Garc\u00eda, coment\u00f3 que, de esta forma, se cumple<br>la instrucci\u00f3n del gobernador del Estado de Durango, Jos\u00e9 Rosas Aispuro Torres,<br>de acompa\u00f1ar en este proceso a los directivos de Draslovka, a fin de que todo se<br>realice en un marco de seguridad para los involucrados.<\/p>\n\n\n\n<p>El subsecretario de Gobierno en La Laguna de Durango, record\u00f3 que el pasado<br>mes de julio estuvieron en Dinamita t\u00e9cnicos especializados para recorrer las<br>instalaciones y valoraron las mejores alternativas para el desmantelamiento de la<br>infraestructura y maquinaria; y hoy, la empresa checa se encuentra en condiciones<br>de iniciar con la etapa final de dicho proceso.<\/p>\n\n\n\n<p>Finalmente, reiter\u00f3 que es inter\u00e9s del Gobierno del Estado de Durango, que todo<br>continu\u00e9 como a la fecha, en un entorno de respeto mutuo, de di\u00e1logo y en un marco<br>de seguridad para quienes participan en estas tareas de desmantelamiento de la<br>planta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comarca Lagunera.- Al medio d\u00eda, en el poblado de Dinamita, Durango; se llev\u00f3 acabo la reuni\u00f3n de seguimiento a la fase de desmantelamiento de infraestructura ymaquinar\u00eda de la planta instalada en esta zona, entre los pobladores, directivos de laempresa Draslovka, funcionarios municipales de G\u00f3mez Palacio y el subsecretario degobierno en la regi\u00f3n Laguna, Oswaldo Santib\u00e1\u00f1ez Garc\u00eda. Al respecto, Oswaldo Santib\u00e1\u00f1ez Garc\u00eda, coment\u00f3 que, de esta forma, se cumplela instrucci\u00f3n del&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,64,28],"tags":[],"class_list":["post-10605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durango","category-gobierno-de-durango","category-la-laguna","wpcat-40-id","wpcat-64-id","wpcat-28-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=10605"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10605\/revisions"}],"predecessor-version":[{"id":10607,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10605\/revisions\/10607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/10606"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=10605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=10605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=10605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}