{"id":10608,"date":"2022-08-22T20:17:08","date_gmt":"2022-08-23T01:17:08","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=10608"},"modified":"2022-08-22T20:17:08","modified_gmt":"2022-08-23T01:17:08","slug":"mantiene-coahuila-primeros-lugares-en-exportacion-de-becerros-a-eu","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/08\/22\/mantiene-coahuila-primeros-lugares-en-exportacion-de-becerros-a-eu\/","title":{"rendered":"MANTIENE COAHUILA PRIMEROS LUGARES EN EXPORTACI\u00d3N DE BECERROS A EU."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 22 de Agosto de 2022.-\u00a0 El Servicio de Informaci\u00f3n Agroalimentaria y Pesquera (SIAP) ubic\u00f3 a Coahuila en los primeros lugares en M\u00e9xico en exportaci\u00f3n de becerros a Estados Unidos, con\u00a0 20 mil 326 cabezas entre enero y junio de este a\u00f1o, inform\u00f3 el Secretario de Desarrollo Rural del Estado, Jos\u00e9 Luis Flores M\u00e9ndez.<\/p>\n\n\n\n<p>El \u00f3rgano desconcentrado de la Secretar\u00eda de Agricultura y Desarrollo Rural (SADER) destac\u00f3 que tan s\u00f3lo en junio se comercializaron desde Coahuila en el mercado norteamericano 4 mil 458 animales, de los cuales 3 mil 444 fueron becerros (el 77.3 por ciento) y los restantes mil 14 correspondieron a vaquillas.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que el SIAP presenta trimestralmente estad\u00edsticas en torno a la exportaci\u00f3n de ganado bovino en pie a Estados Unidos, y en los correspondientes a los primeros seis meses del a\u00f1o registr\u00f3 la comercializaci\u00f3n de 20 mil 326 ejemplares en el mercado norteamericano.<\/p>\n\n\n\n<p>\u201cEl Ganado Tipo Coahuila\u201d, resultado de las permanentes campa\u00f1as de mejoramiento gen\u00e9tico que se lleva a cabo en el Estado, tiene gran demanda en Estados Unidos por su alta calidad, refiri\u00f3 el titular de Desarrollo Rural coahuilense.<\/p>\n\n\n\n<p>Sobre el particular, destac\u00f3 que el a\u00f1o pasado productores de Coahuila llevaron al vecino pa\u00eds del norte alrededor de 60 mil cabezas de ganado bovino, para ubicarse en el cuarto lugar nacional.<\/p>\n\n\n\n<p><strong>CUMPLE CON TODOS LOS REQUERIMIENTOS DE SANIDAD<\/strong><\/p>\n\n\n\n<p>Por otra parte, el titular de la SDR en Coahuila destac\u00f3 que los becerros que se exportan al mercado del vecino pa\u00eds del norte cumplen con todos los requerimientos sanitarios que exige el Servicio Nacional de Sanidad, Inocuidad y Calidad Alimentaria (SENASICA), dependiente de la SADER.<\/p>\n\n\n\n<p>Asimismo, del Departamento de Agricultura de los Estados Unidos (USDA, por sus siglas en ingl\u00e9s) y de los Servicios de Inspecci\u00f3n Sanitaria de Animales y Plantas (APHIS),&nbsp; organismo de esa instituci\u00f3n norteamericana.<\/p>\n\n\n\n<p><strong>CENTRO DE ACOPIO PARA BECERROS DE EXPORTACI\u00d3N EN SIERRA MOJADA<\/strong><\/p>\n\n\n\n<p>En ese contexto, el Secretario de Desarrollo Rural de Coahuila record\u00f3 que en d\u00edas pasados se inaugur\u00f3 el Centro de Acopio para Exportaci\u00f3n en el ejido La Gloria, de Sierra Mojada, con la salida del primer embarque de 107 animales (hembras castradas), que se llevaron al mercado norteamericano.<\/p>\n\n\n\n<p>Este lugar, dijo, se suma a los m\u00e1s de 50 centros de acopio que operan en Coahuila, los que cuentan con la infraestructura necesaria para garantizar su plena condici\u00f3n de salud y libres de par\u00e1sitos o de enfermedades para su segura comercializaci\u00f3n en el mercado norteamericano.<\/p>\n\n\n\n<p>\u201cSer\u00e1 de gran beneficio para ganaderos de Ocampo y Sierra Mojada, quienes, adem\u00e1s, se ahorrar\u00e1n gastos por el traslado de sus animales a la cuarentenaria de Ciudad Acu\u00f1a.<\/p>\n\n\n\n<p>\u201cAhora utilizar\u00e1n la de Ojinaga, en Chihuahua, m\u00e1s cercana y que tambi\u00e9n cumple con todos los requerimientos que demandan las autoridades correspondientes\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 22 de Agosto de 2022.-\u00a0 El Servicio de Informaci\u00f3n Agroalimentaria y Pesquera (SIAP) ubic\u00f3 a Coahuila en los primeros lugares en M\u00e9xico en exportaci\u00f3n de becerros a Estados Unidos, con\u00a0 20 mil 326 cabezas entre enero y junio de este a\u00f1o, inform\u00f3 el Secretario de Desarrollo Rural del Estado, Jos\u00e9 Luis Flores M\u00e9ndez. El \u00f3rgano desconcentrado de la Secretar\u00eda de Agricultura y Desarrollo Rural (SADER)&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,91,15],"tags":[],"class_list":["post-10608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-ganaderia","category-gobierno-de-coahuila","wpcat-5-id","wpcat-91-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=10608"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10608\/revisions"}],"predecessor-version":[{"id":10610,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10608\/revisions\/10610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/10609"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=10608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=10608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=10608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}