{"id":10872,"date":"2022-09-02T15:30:58","date_gmt":"2022-09-02T20:30:58","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=10872"},"modified":"2022-09-02T15:30:59","modified_gmt":"2022-09-02T20:30:59","slug":"invita-uadec-a-sus-universitarios-a-ser-voluntarios-en-el-boteo-teleton","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/09\/02\/invita-uadec-a-sus-universitarios-a-ser-voluntarios-en-el-boteo-teleton\/","title":{"rendered":"Invita UAdeC a sus Universitarios a ser Voluntarios en el Boteo Telet\u00f3n."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 2 de septiembre de 2022.- La Coordinaci\u00f3n General de<br>Extensi\u00f3n Universitaria de la Universidad Aut\u00f3noma de Coahuila, convoca a<br>alumnos, docentes y trabajadores de la instituci\u00f3n a unirse al boteo para apoyar al<br>Telet\u00f3n, el cual se estar\u00e1 realizando del 5 de septiembre al 17 de diciembre de<br>2022.<\/p>\n\n\n\n<p>El subcoordinador de Servicios de Extensi\u00f3n de la Coordinaci\u00f3n General de<br>Extensi\u00f3n Universitaria, Juan de Labra coment\u00f3 que se espera que los<br>interesados se inscriban durante el mes de septiembre, proceso que deber\u00e1n de<br>realizar en el siguiente enlace <a href=\"https:\/\/forms.gle\/ioYuYBC3NQ5LQWh7\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.gle\/ioYuYBC3NQ5LQWh7<\/a> o<br>escaneando el c\u00f3digo QR que se encuentra publicado en la p\u00e1gina de Facebook<br>Extensi\u00f3n Universitaria UAdeC.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que personal del Telet\u00f3n se acerc\u00f3 a la Universidad para solicitar apoyo en<br>el boteo, propuesta que la instituci\u00f3n acept\u00f3 con gusto, ya que la m\u00e1xima casa de<br>estudios tiene el deber de colaborar con la sociedad y es una oportunidad para<br>que los universitarios conozcan la realidad del entorno que los rodea.<\/p>\n\n\n\n<p>Al momento de que los estudiantes o trabajadores se inscriban, deber\u00e1n de<br>proporcionar su matr\u00edcula o expediente, ya que, al entregarles las alcanc\u00edas, estas<br>tendr\u00e1n un folio de identificaci\u00f3n, lo que brinda seguridad y transparencia durante<br>la colecta.<\/p>\n\n\n\n<p>Los voluntarios de la Unidad Saltillo recoger\u00e1n las alcanc\u00edas en las oficinas de la<br>Coordinaci\u00f3n General de Extensi\u00f3n Universitaria, en Unidad Torre\u00f3n en el<br>Departamento de Extensi\u00f3n de la Coordinaci\u00f3n de Unidad y en la Unidad Norte de<br>igual manera en el Departamento de Extensi\u00f3n.<\/p>\n\n\n\n<p>Cada voluntario podr\u00e1 hacer entrega de lo colectado en el CRIT Saltillo o a trav\u00e9s<br>de dep\u00f3sito bancario; para m\u00e1s informaci\u00f3n comunicarse a los tel\u00e9fonos (844) 414<br>9011 y (844) 414-1852 o visitar la p\u00e1gina de Facebook Extensi\u00f3n Universitaria<br>UAdeC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 2 de septiembre de 2022.- La Coordinaci\u00f3n General deExtensi\u00f3n Universitaria de la Universidad Aut\u00f3noma de Coahuila, convoca aalumnos, docentes y trabajadores de la instituci\u00f3n a unirse al boteo para apoyar alTelet\u00f3n, el cual se estar\u00e1 realizando del 5 de septiembre al 17 de diciembre de2022. El subcoordinador de Servicios de Extensi\u00f3n de la Coordinaci\u00f3n General deExtensi\u00f3n Universitaria, Juan de Labra coment\u00f3 que se espera que losinteresados se inscriban&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-10872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=10872"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10872\/revisions"}],"predecessor-version":[{"id":10874,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10872\/revisions\/10874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/10873"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=10872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=10872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=10872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}