{"id":10954,"date":"2022-09-06T17:20:22","date_gmt":"2022-09-06T22:20:22","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=10954"},"modified":"2022-09-06T17:20:23","modified_gmt":"2022-09-06T22:20:23","slug":"alcalde-habilita-centros-de-acopio-para-ayudar-a-los-municipios-de-la-laguna-afectados-por-las-lluvias","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/09\/06\/alcalde-habilita-centros-de-acopio-para-ayudar-a-los-municipios-de-la-laguna-afectados-por-las-lluvias\/","title":{"rendered":"Alcalde habilita centros de acopio para ayudar a los municipios de La Laguna afectados por las lluvias."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 06 de septiembre de 2022.<\/p>\n\n\n\n<p>El Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, hace un llamado a la ciudadan\u00eda a<br>ser solidarios y donar art\u00edculos no perecederos, de higiene personal y limpieza del<br>hogar, en los distintos centros de acopio habilitados en Torre\u00f3n, con el objetivo de<br>ayudar a las personas afectadas por las lluvias en el Ca\u00f1\u00f3n de Jimulco,<br>Matamoros y Viesca.<\/p>\n\n\n\n<p>Esta ma\u00f1ana, el Presidente Municipal dio instrucciones a diferentes dependencias<br>para coordinarse en los distintos centros de acopio, para hacer llegar la ayuda al<br>Ca\u00f1\u00f3n de Jimulco, ubicado en Torre\u00f3n, as\u00ed como a los municipios de Matamoros y<br>Viesca.<\/p>\n\n\n\n<p>Los centros de acopio habilitados son: Multideportivo Oriente, Auditorio Municipal,<br>Cruz Roja de Torre\u00f3n, Plaza Mayor, y las Sorianas Constituci\u00f3n, Independencia,<br>Oriente, Triana, Fundadores, y Aurora.<\/p>\n\n\n\n<p>De art\u00edculos no perecederos se recibe: agua embotellada, leche en polvo, latas de<br>at\u00fan, arroz, sopa de pasta, aceite, az\u00facar, entre otros.<\/p>\n\n\n\n<p>De art\u00edculos de higiene personal: toallas sanitarias, papel higi\u00e9nico, champ\u00fa,<br>pa\u00f1ales desechables, pasta dental, jab\u00f3n, entre otros.<\/p>\n\n\n\n<p>En art\u00edculos de limpieza y hogar: jab\u00f3n en polvo, escobas, cloro, cubetas,<br>colchonetas, cobijas y palas.<\/p>\n\n\n\n<p>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez se\u00f1al\u00f3 que, tras las intensas lluvias registradas<br>en diferentes municipios de Coahuila, es momento de sumar esfuerzos y<br>solidarizarse con las personas afectadas.<\/p>\n\n\n\n<p>Los art\u00edculos que se reciban en los centros de acopio habilitados se har\u00e1n llegar<br>de manera inmediata y coordinada con las autoridades de Matamoros y Viesca, al<br>igual que al Ca\u00f1\u00f3n de Jimulco, ubicado en Torre\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 06 de septiembre de 2022. El Alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, hace un llamado a la ciudadan\u00eda aser solidarios y donar art\u00edculos no perecederos, de higiene personal y limpieza delhogar, en los distintos centros de acopio habilitados en Torre\u00f3n, con el objetivo deayudar a las personas afectadas por las lluvias en el Ca\u00f1\u00f3n de Jimulco,Matamoros y Viesca. Esta ma\u00f1ana, el Presidente Municipal dio instrucciones a diferentes dependenciaspara&#8230;<\/p>\n","protected":false},"author":1,"featured_media":10955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5,28,7],"tags":[],"class_list":["post-10954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","category-coahuila","category-la-laguna","category-torreon","wpcat-27-id","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=10954"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10954\/revisions"}],"predecessor-version":[{"id":10956,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/10954\/revisions\/10956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/10955"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=10954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=10954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=10954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}