{"id":11281,"date":"2022-09-25T19:15:13","date_gmt":"2022-09-26T00:15:13","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=11281"},"modified":"2022-09-25T19:15:14","modified_gmt":"2022-09-26T00:15:14","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-450","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/09\/25\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-450\/","title":{"rendered":"REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID- 19."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 24 de septiembre del 2022.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al d\u00eda de hoy se registran 26 nuevos casos en Coahuila sin registrarse defunciones.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS<\/p>\n\n\n\n<p>11 TORRE\u00d3N<\/p>\n\n\n\n<p>4 SALTILLO<\/p>\n\n\n\n<p>3 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>3 MONCLOVA<\/p>\n\n\n\n<p>2 ZARAGOZA<\/p>\n\n\n\n<p>1 FRONTERA<\/p>\n\n\n\n<p>1 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>1 SAN PEDRO<\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 237&nbsp;&nbsp; casos activos de COVID \u2013 19<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Saltillo 117<\/p>\n\n\n\n<p>-Torre\u00f3n 44<\/p>\n\n\n\n<p>-Monclova 17<\/p>\n\n\n\n<p>-Piedras Negras 13<\/p>\n\n\n\n<p>-Frontera 11<\/p>\n\n\n\n<p>-San Pedro 9<\/p>\n\n\n\n<p>-Matamoros 3<\/p>\n\n\n\n<p>-Nava 2<\/p>\n\n\n\n<p>-Ramos Arizpe 2<\/p>\n\n\n\n<p>-Parras de la Fuente 2<\/p>\n\n\n\n<p>-Acu\u00f1a 2<\/p>\n\n\n\n<p>-Arteaga 2<\/p>\n\n\n\n<p>-General Cepeda 2<\/p>\n\n\n\n<p>-Sabinas 2<\/p>\n\n\n\n<p>-Zaragoza 2<\/p>\n\n\n\n<p>-Casta\u00f1os 2<\/p>\n\n\n\n<p>-Nadadores 1<\/p>\n\n\n\n<p>-San Buenaventura 1<\/p>\n\n\n\n<p>-Morelos 1<\/p>\n\n\n\n<p>-Francisco I. Madero 1<\/p>\n\n\n\n<p>-San Juan de Sabinas 1<\/p>\n\n\n\n<p>-Juarez 0<\/p>\n\n\n\n<p>-Ocampo 0<\/p>\n\n\n\n<p>-Allende 0<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 0<\/p>\n\n\n\n<p>-M\u00fazquiz 0<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 0<\/p>\n\n\n\n<p>-Viesca 0<\/p>\n\n\n\n<p>-Sacramento 0<\/p>\n\n\n\n<p>-Candela 0<\/p>\n\n\n\n<p>-Lamadrid 0<\/p>\n\n\n\n<p>-Escobedo 0<\/p>\n\n\n\n<p>-Jim\u00e9nez 0<\/p>\n\n\n\n<p>-Progreso 0<\/p>\n\n\n\n<p>-Guerrero 0<\/p>\n\n\n\n<p>-Sierra Mojada 0<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>-Abasolo 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 182,670 casos, incluidos 8,946 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 4<\/p>\n\n\n\n<p>Torre\u00f3n 2<\/p>\n\n\n\n<p>Saltillo 2<\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 173,487<\/p>\n\n\n\n<p>47,707 SALTILLO<\/p>\n\n\n\n<p>34,795 TORRE\u00d3N<\/p>\n\n\n\n<p>17,384 MONCLOVA<\/p>\n\n\n\n<p>14,275 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>7,752 ACU\u00d1A<\/p>\n\n\n\n<p>5,182 FRONTERA<\/p>\n\n\n\n<p>5,025 SABINAS<\/p>\n\n\n\n<p>4,776 RAMOS ARIZPE<\/p>\n\n\n\n<p>4,299 SAN PEDRO<\/p>\n\n\n\n<p>4,104 M\u00daZQUIZ<\/p>\n\n\n\n<p>3,806 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>3,745 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>3,070 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>3,124 MATAMOROS<\/p>\n\n\n\n<p>2,265 NAVA<\/p>\n\n\n\n<p>2,145 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>1,960 SAN BUENAVENTURA<\/p>\n\n\n\n<p>1,531 CASTA\u00d1OS<\/p>\n\n\n\n<p>1,357 ALLENDE<\/p>\n\n\n\n<p>867 ZARAGOZA<\/p>\n\n\n\n<p>773&nbsp; ARTEAGA<\/p>\n\n\n\n<p>586 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>446 NADADORES<\/p>\n\n\n\n<p>466 GENERAL CEPEDA<\/p>\n\n\n\n<p>458 MORELOS<\/p>\n\n\n\n<p>320 OCAMPO<\/p>\n\n\n\n<p>306 SACRAMENTO<\/p>\n\n\n\n<p>220 LAMADRID<\/p>\n\n\n\n<p>177 VIESCA<\/p>\n\n\n\n<p>124 PROGRESO<\/p>\n\n\n\n<p>89 JIM\u00c9NEZ<\/p>\n\n\n\n<p>79 SIERRA MOJADA<\/p>\n\n\n\n<p>70 GUERRERO<\/p>\n\n\n\n<p>56 CANDELA<\/p>\n\n\n\n<p>46 ESCOBEDO<\/p>\n\n\n\n<p>42 ABASOLO<\/p>\n\n\n\n<p>34 JU\u00c1REZ<\/p>\n\n\n\n<p>26 HIDALGO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 24 de septiembre del 2022.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al d\u00eda de hoy se registran 26 nuevos casos en Coahuila sin registrarse defunciones. DISTRIBUCI\u00d3N DE CASOS 11 TORRE\u00d3N 4 SALTILLO 3 PIEDRAS NEGRAS 3 MONCLOVA 2 ZARAGOZA 1 FRONTERA 1&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-11281","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=11281"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11281\/revisions"}],"predecessor-version":[{"id":11282,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11281\/revisions\/11282"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=11281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=11281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=11281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}