{"id":11821,"date":"2022-10-21T19:50:40","date_gmt":"2022-10-22T00:50:40","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=11821"},"modified":"2022-10-21T19:50:41","modified_gmt":"2022-10-22T00:50:41","slug":"embajador-de-estados-unidos-ken-salazar-visita-crih-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/10\/21\/embajador-de-estados-unidos-ken-salazar-visita-crih-coahuila\/","title":{"rendered":"EMBAJADOR DE ESTADOS UNIDOS, KEN SALAZAR, VISITA CRIH COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 21 de Octubre de 2022.- El Gobernador del Estado de Coahuila, Miguel \u00c1ngel Riquelme Sol\u00eds, recorri\u00f3 el Centro Regional de Identificaci\u00f3n Humana (CRIH) de la Comisi\u00f3n de B\u00fasqueda del Estado con el Embajador de Estados Unidos en M\u00e9xico, Kenneth Lee Salazar, a fin de dar a conocer la metodolog\u00eda con enfoque masivo aplicada en Coahuila en el tema de b\u00fasqueda forense.<\/p>\n\n\n\n<p>Durante el recorrido, el Embajador fue acompa\u00f1ado por el Subsecretario de Derechos Humanos, Poblaci\u00f3n y Migraci\u00f3n de la SEGOB, Alejandro Encinas Rodr\u00edguez, y de la Comisionada Nacional de B\u00fasqueda de Personas Desaparecidas, Karla Quintana Osuna.<\/p>\n\n\n\n<p>El Comisionado Estatal de B\u00fasqueda, Ricardo Mart\u00ednez Loyola, y la Coordinadora General del CRIH, Yezka Garza Ram\u00edrez, guiaron el recorrido por las instalaciones para explicar el trabajo que realizan en cada \u00e1rea forense que integran el centro.<\/p>\n\n\n\n<p>La Coordinadora General del CRIH, Yezka Garza Ram\u00edrez, mencion\u00f3 que con esta visita se reafirma el compromiso adquirido por las autoridades en tema de b\u00fasqueda forense e identificaci\u00f3n.<\/p>\n\n\n\n<p>\u201cGracias al trabajo en conjunto y a la voluntad del Gobierno de Estados Unidos es que se materializan resultados. USAID es nuestro donante m\u00e1s importante de insumos utilizados para el funcionamiento del Centro\u201d, dijo Garza Ram\u00edrez.<\/p>\n\n\n\n<p>Asimismo, el Embajador y las autoridades estatales sostuvieron una reuni\u00f3n con representantes de los 8 colectivos de Coahuila con el objetivo de intercambiar opiniones en temas de b\u00fasqueda e identificaci\u00f3n humana.<\/p>\n\n\n\n<p>Estuvieron presentes este d\u00eda, la Directora General de la Academia Interamericana de Derechos Humanos, Irene Spigno; el investigador de la AIDH Jos\u00e9 Luis Vald\u00e9s Rivera, y el Director General de la Unidad de Derechos Humanos del Estado, Jos\u00e9 \u00c1ngel Rodr\u00edguez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 21 de Octubre de 2022.- El Gobernador del Estado de Coahuila, Miguel \u00c1ngel Riquelme Sol\u00eds, recorri\u00f3 el Centro Regional de Identificaci\u00f3n Humana (CRIH) de la Comisi\u00f3n de B\u00fasqueda del Estado con el Embajador de Estados Unidos en M\u00e9xico, Kenneth Lee Salazar, a fin de dar a conocer la metodolog\u00eda con enfoque masivo aplicada en Coahuila en el tema de b\u00fasqueda forense. Durante el recorrido, el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,24],"tags":[],"class_list":["post-11821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-seguridad","wpcat-5-id","wpcat-15-id","wpcat-24-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=11821"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11821\/revisions"}],"predecessor-version":[{"id":11823,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11821\/revisions\/11823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/11822"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=11821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=11821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=11821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}