{"id":11859,"date":"2022-10-23T18:09:17","date_gmt":"2022-10-23T23:09:17","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=11859"},"modified":"2022-10-23T18:09:17","modified_gmt":"2022-10-23T23:09:17","slug":"aqui-laguna-175","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/10\/23\/aqui-laguna-175\/","title":{"rendered":"Aqu\u00ed Laguna."},"content":{"rendered":"\n<p>\u00a1Ah\u00ed te hablan Mejia Berdeja!\u00a0 Y banda que lo acompa\u00f1a, seg\u00fan &#8220;charla&#8221;\u00a0 la\u00a0 Guacamaya, el 72 %\u00a0 del territorio nacional, se encuentra en estas fechas bajo\u00a0 la presencia de alguna de las bandas de la\u00a0 m\u00e1s que\u00a0 bien\u00a0 la\u00a0 muy emprendedora\u00a0 delincuencia organizada, suma que\u00a0 revela que a la fecha, la estrategia\u00a0 bajo la que era el sistema de seguridad nacional, no da resultados, no se avanza\u00a0 y no los\u00a0 dar\u00e1\u00a0 en\u00a0 el corto tiempo que le resta al actual sexenio federal, en tanto sus responsables de su\u00a0 dise\u00f1o y ejecuci\u00f3n, sigan como hasta hoy, siguiendo el m\u00e9todo de la\u00a0 avestruz y el hampa cobra, un d\u00eda si y el otro tambi\u00e9n,\u00a0 la\u00a0 abultada suma que en costo humano,\u00a0 v\u00edctimas y sus victimarios, los cuales dejan a sus deudos, a sus familias \u00a0rotas,\u00a0 afectadas, con destinos por dem\u00e1s inciertos. Y en tanto aumenta\u00a0 en percepci\u00f3n directa, no\u00a0 solo\u00a0 la percepci\u00f3n de\u00a0 seguridad, sino\u00a0 que\u00a0 de paso,\u00a0 la percepci\u00f3n de que en este pa\u00eds,\u00a0 y sus sistemas de\u00a0 procuraci\u00f3n\u00a0 \u00a0 y m\u00e1s a\u00fan de impartici\u00f3n de justicia tambi\u00e9n va en aumento, m\u00e1s all\u00e1 de lo que se nos diga a trav\u00e9s de la l\u00facida ret\u00f3rica de sus responsables. El tal escenario como es posible\u00a0 en este r\u00e9gimen federal, que un funcionario de nivel del ex lagunero y avecindado acapulque\u00f1o, tenga\u00a0 tiempo para distraer sus responsabilidades como Subsecretario de Seguridad P\u00fablica, pase\u00e1ndose, sobre quien se deje, el territorio\u00a0 estatal \u00a0 donde pretende\u00a0 gobernar de ser\u00a0 \u00a0 \u00a0 considerado, primero candidato del hoy &#8220;partido oficial&#8221; y de\u00a0 ganar la elecci\u00f3n de junio pr\u00f3ximo, Gobernar Coahuila, las credenciales que porta y ha podido construir en el actual sexenio, no dan para mucho, sobre todo \u00a0 por el hecho de lo que\u00a0 haya realizado como saltimbanqui\u00a0 partidista, tras su abandono de las siglas del PRI,\u00a0 quien le cobijara y proporcionara\u00a0 las oportunidades para iniciar su carrera de pol\u00edtico,\u00a0 y en la cual viviera la experiencia,\u00a0 para muchos de los que formaron parte de su generaci\u00f3n\u00a0 y compartieron ilusiones \u00a0 gestadas\u00a0 con la designaci\u00f3n de Luis Donaldo Colossio, \u00a0 trataba de sobresalir\u00a0 \u00a0 como\u00a0 uno de los reclutadores locales\u00a0 de &#8220;M\u00e9xico Nuevo&#8221;, a \u00a0 potenciales l\u00edderes pol\u00edticos entre\u00a0 los entonces laguneros laguneros, en los que participa incluso Guillermo Anaya Llamas, no sin desaprovechar,  la oportunidad que\u00a0 le abriera como diputado local, el entonces Gobernador Rogelio Montemayor Seguy, contra quien\u00a0 por cierto, escribi\u00f3\u00a0 luego en el desencanto un libraco, y\u00a0 luego, no dando para mas, en la siguiente administraci\u00f3n estatal, logr\u00f3 colarse \u00a0 como polic\u00eda chino en\u00a0 la gubernatura a cargo del Licenciado Enrique Mart\u00ednez y Mart\u00ednez, bajo el mando del\u00a0 Jorge Luis Mor\u00e1n y ya no dio para mas, asi que al t\u00e9rmino de tal sexenio tom\u00f3 las de Villadiego y se nos perdi\u00f3, por entre 15 y 20 a\u00f1os de vista\u00a0 por estas tierras, a donde hoy, cual hijo prodigo retorna\u00a0 y quiere\u00a0 competir\u00a0 por la grande\u00a0 de Coahuila.<\/p>\n\n\n\n<p>Al parecer el citado aspirante, tiene\u00a0 una obvia\u00a0 inclinaci\u00f3n por hacer amigos o compinches que\u00a0 proceden de las \u00e1reas oscuras del sistema, como se dec\u00eda, antes y\u00a0 ya ven a nivel nacional se le imputa una cercana amistad y relaciones de trabajo pol\u00edtico que le dejaba su tiempo libre, como funcionario de la administraci\u00f3n morenista de Vallarta, Jalisco \u00a0 con el asesinado  funcionario p\u00fablico del municipio de Vallarta,\u00a0 Salvador Llamas Urbina en un restaurante de Zapopan,\u00a0 Jalisco,\u00a0 y a cuya muerte, de inmediato se le\u00a0 identific\u00f3 como miembro de un grupo criminal, seg\u00fan twitteo \u00a0 John Ackerman, con un escueto, pero demoledor\u00a0 &#8220;es\u00a0 un\u00a0 Narco de\u00a0 Vallarta,\u00a0 gente fina pues&#8221;.<\/p>\n\n\n\n<p>Y diremos que Mej\u00eda Berdeja puede andar de dia\u00a0 de campo en este Estado, gracias a que Coahuila es hoy por\u00a0 hoy el Estado mas seguro del pa\u00eds, y esto, como se sabe y consta, no es de a gratis, pues\u00a0 se puede perder, el amago, el acoso criminal se resiste y bien, gracias a la dif\u00edcil, pero posible conjunci\u00f3n de sociedad y gobierno,\u00a0 de recursos humanos y voluntad pol\u00edtica&#8230;<\/p>\n\n\n\n<p>Positiva\u00a0 result\u00f3\u00a0 la visita del\u00a0 Embajador Ken Salazar a estas tierras, siendo anfitri\u00f3n, no solo el Gobernador\u00a0 Miguel Angel\u00a0 Riquelme Solis, sino tambi\u00e9n el Rector de la UAdeC, Ingeniero Salvador Hern\u00e1ndez Velez, destacando en la breve estancia del singular\u00a0 visitante,\u00a0 en el Centro de\u00a0 Nacional de Identificaci\u00f3n Humana,\u00a0 \u00e1rea de trabajo que tan bien\u00a0 dirige la Licenciada Yeska Garza \u00a0 y que constituye la vanguardia destinada a\u00a0 lograr la identificaci\u00f3n de\u00a0 personas desaparecidas, asignatura pendiente en este M\u00e9xico nuestro\u2026<\/p>\n\n\n\n<p>Por Cierto, honrar, honra, y vaya que la UAdeC\u00a0 concedi\u00f3 \u00a0 su Grado \u00a0 M\u00e1ximo que  como Maestro Ad Vitam al Doctor\u00a0 Virgilio\u00a0 Verduzco Ros\u00e1n fincado en su larga trayectoria de servicio como acad\u00e9mico en tal instituci\u00f3n, \u00a0 y de paso nos hizo\u00a0 recordar su fruct\u00edfero paso\u00a0 por el servicio p\u00fablico, en el que mostr\u00f3 a cabalidad\u00a0 su entrega a alta\u00a0 misi\u00f3n de su profesi\u00f3n. \u00a1Felicidades!..<\/p>\n\n\n\n<p>Y en puerta, la presentaci\u00f3n de un\u00a0 libro de la autor\u00eda del Secretario de Salud en Coahuila, el Doctor Roberto Bernal G\u00f3mez, cuya tem\u00e1tica versar\u00e1 sobre su invaluable experiencia que como m\u00e9dico,\u00a0 y\u00a0 como\u00a0 servidor p\u00fablico\u00a0 le gener\u00f3\u00a0 los\u00a0 trabajos desempe\u00f1ado para enfrentar la pandemia de Covid-19, in\u00e9dito proceso que bien a bien no\u00a0 est\u00e1 aun acabado, pero que resulta importante registrar y contar con tal herramienta\u00a0 de lo vivido en primeras fila \u00a0 que\u00a0 deja ya \u00a0 tal flagelo\u00a0 y que ocasion\u00f3, solo en Coahuila mas de\u00a0 8,000 decesos y cuyos impactos est\u00e1n aun por conocerse y sobre todo evaluar entre los coahuilenses que resultaron infectados y han vivido para contarlo\u2026<\/p>\n\n\n\n<p>Y aterrizando en esta comarca, el lamentable deceso, registrado este fin de semana, en la capital del pa\u00eds, del reconocido y multipremiado\u00a0 escritor Gilberto Prado Gal\u00e1n, cuya obra, no estar\u00eda de mas, fuera reeditada\u00a0 y difundida entre sus\u00a0 a pares y j\u00f3venes estudiantes de letras y carreras afines&#8230;<\/p>\n\n\n\n<p>Este d\u00eda,\u00a0 m\u00e1s de tres\u00a0 miembros de la clase pol\u00edtica\u00a0 lagunera \u2013no\u00a0 solo priista-, se\u00a0 dirigir\u00e1n a Saltillo capital, con el objetivo de \u00a0 estar presente en\u00a0el Informe de resultados\u00a0 que como Diputado Federal, rendir\u00e1, ante representantes de su Distrito, y otras autoridades, Jeric\u00f3 Abramo Masso, que definido ya como\u00a0 militante institucional de su partido, el PRI, se sumar\u00e1 a las decisiones\u00a0 que\u00a0 ya est\u00e1n\u00a0 m\u00e1s que perfiladas\u00a0 seg\u00fan se percibe en el ambiente, en torno a a quien ser\u00e1 el candidato priista\u00a0 a Gobernador de Coahuila\u00a0 \u00a0 y que deber\u00e1\u00a0 \u00a0 convalidarse, luego entre los partidos que seg\u00fan se concrete \u00a0 la\u00a0 alianza para\u00a0 enfrentar al que designen los de enfrente. Claro es que Jeric\u00f3 Abramo Masso ha expresado con leg\u00edtimo derecho\u00a0 a \u00a0 aspiraciones expresadas\u00a0 y abanderarlas \u00a0 bajo las siglas del partido de su militancia, donde surgi\u00f3 y cuaj\u00f3 como\u00a0 elemento destacado, de no ser as\u00ed, ni para que ande sumando a fila alguna a nadie, pero realista, conocedor de la entra\u00f1a del\u00a0 poder\u00a0 al que ha aspirado, a su sucesi\u00f3n pues y\u00a0 a las facultades discrecionales,\u00a0 de quienes\u00a0 toman las decisiones ha mostrado ya\u00a0 su talante de militante, de hombre de bien, que no da pu\u00f1aladas por la espalda. Bien por \u00e9l, pues se honra a s\u00ed mismo, pero m\u00e1s a\u00fan a la estirpe pol\u00edtica de la que\u00a0 su familia\u00a0 forma parte, en especial en este\u00a0 s\u00f3rdido\u00a0 tiempo de canallas&#8230;<\/p>\n\n\n\n<p>Y vaya que el diputado Rodrigo Fuentes Avila, no descansa y cuando lo hace, hace adobes y as\u00ed este domingo lo vimos como en un singular esfuerzo\u00a0 literal y figuradamente trajo a la Privada Esparza, en pleno coraz\u00f3n de Torre\u00f3n, los olores, los sabores, las expresiones culturales y habilidades art\u00edsticas\u00a0 cual\u00a0 caudal cultural que poseen los habitantes de la cuenca del Aguanaval\u00a0 del mero\u00a0 Ca\u00f1\u00f3n de Jimulco, territorio del cual es oriundo,\u00a0 misma que exhibe orgullosamente, en compa\u00f1\u00eda de sus habitantes\u00a0 con los que exhibe estrecha cercan\u00eda. En esta acci\u00f3n, reconoci\u00f3 que fue posible gracias al inter\u00e9s y apoyo obtenido del alcalde Rom\u00e1n Alberto Cepeda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ah\u00ed te hablan Mejia Berdeja!\u00a0 Y banda que lo acompa\u00f1a, seg\u00fan &#8220;charla&#8221;\u00a0 la\u00a0 Guacamaya, el 72 %\u00a0 del territorio nacional, se encuentra en estas fechas bajo\u00a0 la presencia de alguna de las bandas de la\u00a0 m\u00e1s que\u00a0 bien\u00a0 la\u00a0 muy emprendedora\u00a0 delincuencia organizada, suma que\u00a0 revela que a la fecha, la estrategia\u00a0 bajo la que era el sistema de seguridad nacional, no da resultados, no se avanza\u00a0 y no los\u00a0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11859","post","type-post","status-publish","format-standard","hentry","category-aqui-laguna","wpcat-8-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=11859"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11859\/revisions"}],"predecessor-version":[{"id":11860,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11859\/revisions\/11860"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=11859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=11859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=11859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}