{"id":11867,"date":"2022-10-24T18:14:54","date_gmt":"2022-10-24T23:14:54","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=11867"},"modified":"2022-10-24T18:14:55","modified_gmt":"2022-10-24T23:14:55","slug":"gana-la-tuna-universitaria-de-saltillo-de-la-uadec-el-premio-a-la-mejor-pasacalles-en-el-festival-internacional-de-tunas-monterrey-2022","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/10\/24\/gana-la-tuna-universitaria-de-saltillo-de-la-uadec-el-premio-a-la-mejor-pasacalles-en-el-festival-internacional-de-tunas-monterrey-2022\/","title":{"rendered":"Gana la Tuna Universitaria de Saltillo de la UAdeC el Premio a la Mejor Pasacalles en el Festival Internacional de Tunas Monterrey 2022."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 24 de octubre de 2022. La Tuna Universitaria de Saltillo de<br>la Universidad Aut\u00f3noma de Coahuila, obtuvo el premio como Mejor Pasacalles<br>del Festival Internacional de Tunas de Monterrey 2022, organizado por la Facultad<br>de Ingenier\u00eda Mec\u00e1nica El\u00e9ctrica de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n, en<br>el marco de su 55 Aniversario los d\u00edas 21 y 22 de octubre.<\/p>\n\n\n\n<p>El pasacalle es una forma musical de ritmo vivo y de origen popular espa\u00f1ol de<br>principios del siglo XVII, interpretada originalmente por m\u00fasicos ambulantes, como<br>lo refleja su etimolog\u00eda (pasar por la calle), y en esta categor\u00eda lo recibieron los<br>integrantes de la Tuna Universitaria de Saltillo de la UAdeC al realizar esta<br>actividad en la Avenida Morelos del Barrio Antiguo de Monterrey.<\/p>\n\n\n\n<p>Los universitarios de la m\u00e1xima casa de estudio que participaron en el Festival<br>son: Luis Roberto Contreras Mart\u00ednez, Fausto Castillo Escobedo, Gregorio Enrique<br>Torres Landeros, Fernando Mart\u00ednez Aguilar, Santiago Padilla Sifuentes, Gustavo<br>Malacara Vald\u00e9s, Christian Oziel Garc\u00eda Ortiz, Oscar Daniel Cuellar Toledo.<\/p>\n\n\n\n<p>Adem\u00e1s de Jes\u00fas David Garc\u00eda Ortiz. Luis Alberto Ponce Mart\u00ednez, Karolt<br>Mart\u00ednez Gonz\u00e1lez, Erick Eduardo Figueroa Rodr\u00edguez, Jorge Antonio Carbajal<br>Aguilar, Jos\u00e9 Fernando Velasco Varela, Osiel Alejandro Garc\u00eda Contreras, Sergio<br>Aldape Gonz\u00e1lez, Hern\u00e1n Isaak Reyes Saucedo y Gerardo Heriberto Hern\u00e1ndez<br>Cueto.<\/p>\n\n\n\n<p>En el Festival tambi\u00e9n participaron la Tuna de la Universidad Polit\u00e9cnica del Valle<br>de M\u00e9xico (Tuna UPVM); La Tuna de la Universidad de Tarapac\u00e1 de Chile; la<br>Tuna UAA de la Benem\u00e9rita Universidad Aut\u00f3noma de Aguascalientes, y la TUNA<br>FIME de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n.<\/p>\n\n\n\n<p>Las categor\u00edas del Festival fueron: Primera Mejor Tuna, Mejor Serenata, Mejor<br>Solista, Mejor Baile de Pandereta, Mejor Baile de Bandera, Mejor Pieza<br>Instrumental, Tuna m\u00e1s Tuna, Pasacalles y Mejor Solista Vocal.<\/p>\n\n\n\n<p>La difusi\u00f3n de la cultura es uno de los ejes de la m\u00e1xima casa de estudios, por lo<br>cual el trabajo, constancia, y compromiso de nuestros grupos representativos se<br>refleja en esta ocasi\u00f3n en el que han sido reconocidos los alumnos de la Tuna<br>Universitaria de Saltillo de la Universidad Aut\u00f3noma de Coahuila en este<br>importante Festival.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 24 de octubre de 2022. La Tuna Universitaria de Saltillo dela Universidad Aut\u00f3noma de Coahuila, obtuvo el premio como Mejor Pasacallesdel Festival Internacional de Tunas de Monterrey 2022, organizado por la Facultadde Ingenier\u00eda Mec\u00e1nica El\u00e9ctrica de la Universidad Aut\u00f3noma de Nuevo Le\u00f3n, enel marco de su 55 Aniversario los d\u00edas 21 y 22 de octubre. El pasacalle es una forma musical de ritmo vivo y de origen popular&#8230;<\/p>\n","protected":false},"author":1,"featured_media":11868,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-11867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=11867"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11867\/revisions"}],"predecessor-version":[{"id":11869,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/11867\/revisions\/11869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/11868"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=11867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=11867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=11867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}