{"id":12814,"date":"2022-12-19T18:34:10","date_gmt":"2022-12-20T00:34:10","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=12814"},"modified":"2022-12-19T18:34:10","modified_gmt":"2022-12-20T00:34:10","slug":"se-gradua-la-primera-generacion-de-la-maestria-en-ciencia-de-datos-y-optimizacion-del-cima-de-la-uadec","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2022\/12\/19\/se-gradua-la-primera-generacion-de-la-maestria-en-ciencia-de-datos-y-optimizacion-del-cima-de-la-uadec\/","title":{"rendered":"Se Grad\u00faa la Primera Generaci\u00f3n de la Maestr\u00eda en Ciencia de Datos y Optimizaci\u00f3n del CIMA de la UAdeC."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 19 de diciembre de 2022. El pasado viernes se llev\u00f3 a cabo<br>la ceremonia de graduaci\u00f3n de la primera generaci\u00f3n de la Maestr\u00eda en Ciencia de<br>Datos y Optimizaci\u00f3n, programa acad\u00e9mico que ofrece el Centro de Investigaci\u00f3n<br>en Matem\u00e1ticas Aplicadas (CIMA) de la Universidad Aut\u00f3noma de Coahuila.<\/p>\n\n\n\n<p>En la Sala de Seminarios \u201cEmilio J. Talam\u00e1s\u201d de la Unidad Camporredondo,<br>asistieron en representaci\u00f3n del rector, Salvador Hern\u00e1ndez V\u00e9lez, el coordinador<br>de la Unidad Saltillo, Julio Saucedo Zul, la directora del CIMA, Irma Delia Garc\u00eda<br>Calvillo, en representaci\u00f3n de la coordinadora del Posgrado del CIMA, Yajaira<br>Cardona, el Dr. F\u00e9lix Saucedo Zendejo, maestros investigadores, familiares y<br>graduandos.<\/p>\n\n\n\n<p>En su mensaje, la directora del Centro de Investigaci\u00f3n en Matem\u00e1ticas Aplicadas,<br>Irma Delia Garc\u00eda Calvillo felicit\u00f3 y agradeci\u00f3 a los reci\u00e9n egresados por confiar en<br>el proyecto acad\u00e9mico en tiempos de pandemia, ya que inici\u00f3 actividades en 2020,<br>por lo que tuvieron que adaptarse e iniciar clases en l\u00ednea.<\/p>\n\n\n\n<p>Les reiter\u00f3 que son un referente para futuras generaciones, al constatar su<br>crecimiento acad\u00e9mico, no solo en la parte te\u00f3rica o algor\u00edtmica, sino en un<br>crecimiento completo que les dejar\u00e1 aprendizajes para la vida; as\u00ed mismo resalt\u00f3<br>el trabajo de los profesores investigadores del CIMA, quienes, con su dedicaci\u00f3n,<br>horas de trabajo y calidad acad\u00e9mica lograron el egreso de esta primera<br>generaci\u00f3n de la Maestr\u00eda.<\/p>\n\n\n\n<p>Esta primera generaci\u00f3n recibi\u00f3 profesionistas egresados de la Facultad de<br>Econom\u00eda, y de la Facultad de Ciencias F\u00edsico Matem\u00e1ticas (FCFM) de la UAdeC,<br>as\u00ed como del Instituto Tecnol\u00f3gico de Saltillo (ITS); agradeci\u00f3 el apoyo de las<br>autoridades universitarias, quienes, con su gesti\u00f3n, lograron que el CIMA cuente<br>hoy con instalaciones dignas y apropiadas que permiten lograr la calidad<br>acad\u00e9mica.<\/p>\n\n\n\n<p>El coordinador de la Unidad Saltillo, Julio Saucedo Zul, felicit\u00f3 a los egresados de<br>la maestr\u00eda en Ciencias, hecho del que dijo existe compromiso como pa\u00eds en<br>aportar en aquellas necesidades que se deben atender desde la Educaci\u00f3n en las<br>ciencias, as\u00ed como la aplicaci\u00f3n de la misma, ya que M\u00e9xico a\u00fan necesita m\u00e1s<br>cient\u00edficos.<\/p>\n\n\n\n<p>Exhort\u00f3 a la comunidad universitaria a seguirse preparando y compartiendo<br>conocimiento, siempre pensando en el bien de la sociedad \u201cya que, si le va bien a<br>nuestra Universidad, le va a ir bien a nuestro estado y por consecuencia, a<br>nosotros mismos\u201d.<\/p>\n\n\n\n<p>En representaci\u00f3n de los graduados, dirigi\u00f3 un mensaje Wbaldo Valdez Rivera,<br>quien dijo sentirse honrado por haber sido elegido para compartir un mensaje en el<br>cu\u00e1l agradeci\u00f3 a los docentes que impartieron clases durante el posgrado y se\u00f1al\u00f3<br>que les brindaron grandes aprendizajes y permanente apoyo.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que los cient\u00edficos de datos no solo son expertos en trabajar con lo mismo,<br>sino son quienes aprecian los datos como un producto de primera clase como lo<br>es la informaci\u00f3n, por lo que les corresponde manejarla con cuidado y<br>responsabilidad.<\/p>\n\n\n\n<p>Los graduados de esta primera generaci\u00f3n de la Maestr\u00eda en ciencia de datos:<br>fueron Elyasib Natanael Luna Calamaco, H\u00e9ctor Iv\u00e1n De La Rosa De Le\u00f3n, Jes\u00fas<br>Eduardo Reyes Hernandez, Jos\u00e9 Alberto Sol\u00eds Villareal, Sergio Humberto Castillo<br>S\u00e1nchez, y Wbaldo Valdez Rivera.<\/p>\n\n\n\n<p>La Maestr\u00eda en Ciencia de Datos y Optimizaci\u00f3n es un programa acad\u00e9mico<br>dirigido a egresados a nivel licenciatura af\u00edn a las \u00e1reas de matem\u00e1ticas aplicadas,<br>f\u00edsica, qu\u00edmica, ingenier\u00eda, econom\u00eda o administraci\u00f3n y tiene como objetivo formar<br>recursos humanos de calidad, con amplio sentido \u00e9tico, capaces de analizar,<br>sistematizar y modelar datos generados en forma masiva a partir de procesos<br>realizados en los campos de la Ciencia y de la Ingenier\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 19 de diciembre de 2022. El pasado viernes se llev\u00f3 a cabola ceremonia de graduaci\u00f3n de la primera generaci\u00f3n de la Maestr\u00eda en Ciencia deDatos y Optimizaci\u00f3n, programa acad\u00e9mico que ofrece el Centro de Investigaci\u00f3nen Matem\u00e1ticas Aplicadas (CIMA) de la Universidad Aut\u00f3noma de Coahuila. En la Sala de Seminarios \u201cEmilio J. Talam\u00e1s\u201d de la Unidad Camporredondo,asistieron en representaci\u00f3n del rector, Salvador Hern\u00e1ndez V\u00e9lez, el coordinadorde la Unidad Saltillo,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":12815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-12814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/12814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=12814"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/12814\/revisions"}],"predecessor-version":[{"id":12816,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/12814\/revisions\/12816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/12815"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=12814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=12814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=12814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}