{"id":13018,"date":"2023-01-08T19:00:20","date_gmt":"2023-01-09T01:00:20","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=13018"},"modified":"2023-01-08T19:00:21","modified_gmt":"2023-01-09T01:00:21","slug":"reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-521","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/01\/08\/reporte-coahuila-del-plan-estatal-de-prevencion-y-control-covid-19-521\/","title":{"rendered":"<strong>REPORTE COAHUILA DEL PLAN ESTATAL DE PREVENCI\u00d3N Y CONTROL COVID- 19<\/strong>"},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 8 de enero del 2023.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa:<\/p>\n\n\n\n<p>1.- Al d\u00eda de hoy se registran 18 nuevos casos en Coahuila, sin registrarse defunciones.<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N<\/p>\n\n\n\n<p>12 SALTILLO<\/p>\n\n\n\n<p>2 TORRE\u00d3N<\/p>\n\n\n\n<p>2 ACU\u00d1A<\/p>\n\n\n\n<p>2 M\u00daZQUIZ<\/p>\n\n\n\n<p>2.- Existen AHORA en Coahuila 764 casos activos de COVID \u2013 19<\/p>\n\n\n\n<p>DISTRIBUCI\u00d3N DE CASOS ACTIVOS<\/p>\n\n\n\n<p>-Saltillo 357<\/p>\n\n\n\n<p>-Torre\u00f3n 210<\/p>\n\n\n\n<p>-Monclova 49<\/p>\n\n\n\n<p>-Piedras Negras 39<\/p>\n\n\n\n<p>-San Pedro 11<\/p>\n\n\n\n<p>-Francisco I. Madero 11<\/p>\n\n\n\n<p>-Frontera 11<\/p>\n\n\n\n<p>-Parras de la Fuente 11<\/p>\n\n\n\n<p>-Matamoros 10<\/p>\n\n\n\n<p>-Acu\u00f1a 10<\/p>\n\n\n\n<p>-Cuatro Ci\u00e9negas 7<\/p>\n\n\n\n<p>-Sabinas 7<\/p>\n\n\n\n<p>-Nava 6<\/p>\n\n\n\n<p>-M\u00fazquiz 5<\/p>\n\n\n\n<p>-San Juan de Sabinas 3<\/p>\n\n\n\n<p>-Arteaga 3<\/p>\n\n\n\n<p>-Allende 3<\/p>\n\n\n\n<p>-Villa Uni\u00f3n 3<\/p>\n\n\n\n<p>-Casta\u00f1os 1<\/p>\n\n\n\n<p>-Ramos Arizpe 1<\/p>\n\n\n\n<p>-Zaragoza 1<\/p>\n\n\n\n<p>-Escobedo 1<\/p>\n\n\n\n<p>-Viesca 1<\/p>\n\n\n\n<p>-Morelos 1<\/p>\n\n\n\n<p>-Nadadores 1<\/p>\n\n\n\n<p>-Guerrero 1<\/p>\n\n\n\n<p>-Ocampo 0<\/p>\n\n\n\n<p>-General Cepeda 0<\/p>\n\n\n\n<p>-San Buenaventura 0<\/p>\n\n\n\n<p>-Abasolo 0<\/p>\n\n\n\n<p>-Ju\u00e1rez 0<\/p>\n\n\n\n<p>-Sierra Mojada 0<\/p>\n\n\n\n<p>-Sacramento 0<\/p>\n\n\n\n<p>-Candela 0<\/p>\n\n\n\n<p>-Lamadrid 0<\/p>\n\n\n\n<p>-Jim\u00e9nez 0<\/p>\n\n\n\n<p>-Progreso 0<\/p>\n\n\n\n<p>-Hidalgo 0<\/p>\n\n\n\n<p>3.- Al d\u00eda de hoy, se contabilizan en Coahuila EN TOTAL 185,287 casos, incluidos 8,972 decesos.<\/p>\n\n\n\n<p>4.- HOSPITALIZADOS: 39<\/p>\n\n\n\n<p>Torre\u00f3n 22<\/p>\n\n\n\n<p>Monclova 1<\/p>\n\n\n\n<p>Saltillo 10<\/p>\n\n\n\n<p>Acu\u00f1a 1<\/p>\n\n\n\n<p>Piedras Negras 2<\/p>\n\n\n\n<p>San Juan de Sabinas 2<\/p>\n\n\n\n<p>Ramos Arizpe 1<\/p>\n\n\n\n<p>5.- TOTAL DE RECUPERADOS: 175,521<\/p>\n\n\n\n<p>48,405 SALTILLO<\/p>\n\n\n\n<p>35,515 TORRE\u00d3N<\/p>\n\n\n\n<p>17,493 MONCLOVA<\/p>\n\n\n\n<p>14,383 PIEDRAS NEGRAS<\/p>\n\n\n\n<p>7,766 ACU\u00d1A<\/p>\n\n\n\n<p>5,239 FRONTERA<\/p>\n\n\n\n<p>5,046 SABINAS<\/p>\n\n\n\n<p>4,786 RAMOS ARIZPE<\/p>\n\n\n\n<p>4,331 SAN PEDRO<\/p>\n\n\n\n<p>4,110 M\u00daZQUIZ<\/p>\n\n\n\n<p>3,815 PARRAS DE LA FUENTE<\/p>\n\n\n\n<p>3,776 SAN JUAN DE SABINAS<\/p>\n\n\n\n<p>3,102 FRANCISCO I. MADERO<\/p>\n\n\n\n<p>3,150 MATAMOROS<\/p>\n\n\n\n<p>2,301 NAVA<\/p>\n\n\n\n<p>2,150 CUATRO CI\u00c9NEGAS<\/p>\n\n\n\n<p>1,967 SAN BUENAVENTURA<\/p>\n\n\n\n<p>1,550 CASTA\u00d1OS<\/p>\n\n\n\n<p>1,413 ALLENDE<\/p>\n\n\n\n<p>882 ZARAGOZA<\/p>\n\n\n\n<p>778 ARTEAGA<\/p>\n\n\n\n<p>608 VILLA UNI\u00d3N<\/p>\n\n\n\n<p>448 NADADORES<\/p>\n\n\n\n<p>478 GENERAL CEPEDA<\/p>\n\n\n\n<p>462 MORELOS<\/p>\n\n\n\n<p>323 OCAMPO<\/p>\n\n\n\n<p>306 SACRAMENTO<\/p>\n\n\n\n<p>220 LAMADRID<\/p>\n\n\n\n<p>177 VIESCA<\/p>\n\n\n\n<p>124 PROGRESO<\/p>\n\n\n\n<p>89 JIM\u00c9NEZ<\/p>\n\n\n\n<p>80 SIERRA MOJADA<\/p>\n\n\n\n<p>72 GUERRERO<\/p>\n\n\n\n<p>56 CANDELA<\/p>\n\n\n\n<p>46 ESCOBEDO<\/p>\n\n\n\n<p>43 ABASOLO<\/p>\n\n\n\n<p>35 JU\u00c1REZ<\/p>\n\n\n\n<p>26 HIDALGO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 8 de enero del 2023.- Con motivo de mantener a la poblaci\u00f3n informada de los principales avances del Plan Estatal de Prevenci\u00f3n y Control COVID-19, la Secretar\u00eda de Salud de Coahuila (SS) informa: 1.- Al d\u00eda de hoy se registran 18 nuevos casos en Coahuila, sin registrarse defunciones. DISTRIBUCI\u00d3N 12 SALTILLO 2 TORRE\u00d3N 2 ACU\u00d1A 2 M\u00daZQUIZ 2.- Existen AHORA en Coahuila 764 casos activos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-13018","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-covid","wpcat-5-id","wpcat-4-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=13018"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13018\/revisions"}],"predecessor-version":[{"id":13019,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13018\/revisions\/13019"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=13018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=13018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=13018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}