{"id":13084,"date":"2023-01-12T17:22:15","date_gmt":"2023-01-12T23:22:15","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=13084"},"modified":"2023-01-12T17:22:16","modified_gmt":"2023-01-12T23:22:16","slug":"invita-cultura-coahuila-a-visitar-los-museos-del-estado","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/01\/12\/invita-cultura-coahuila-a-visitar-los-museos-del-estado\/","title":{"rendered":"INVITA CULTURA COAHUILA A VISITAR LOS MUSEOS DEL ESTADO."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0Invita a las y los coahuilenses a disfrutar las actividades y exposiciones de los recintos culturales del Estado<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 11 de Enero de 2023.- Con el inicio del a\u00f1o, el Gobierno del Estado de Coahuila, a trav\u00e9s de su Secretar\u00eda de Cultura (SC), invita al p\u00fablico a empezar con una experiencia cultural y de alto valor hist\u00f3rico visitando los museos de nuestro estado.<\/p>\n\n\n\n<p>Los recintos muse\u00edsticos que existen en Coahuila tienen en sus variadas colecciones innumerables piezas de valor hist\u00f3rico que son parte del Patrimonio Cultural coahuilense, mismas que maravillan a los visitantes cuando se encuentran con ellas.<\/p>\n\n\n\n<p>En el caso de&nbsp; los espacios que forman parte del Sistema Nacional de Museos, se encuentran el Museo del Normalismo, Museo de Artes Gr\u00e1ficas, Museo del Sarape, Salas Carranza, Museo Taurino, Museo de los Presidentes, Museo de la Revoluci\u00f3n, Museo de Palacio, Museo de las Momias, Museo Casa Carranza, Museo Francisco Villa y el Museo Cultural de Nadadores, que son completamente gratuitos y est\u00e1n abiertos todo el a\u00f1o de martes a domingo de las 10:00 a las 18:00 horas, contando adem\u00e1s con diversos talleres y actividades para los visitantes&nbsp; y presentaciones especiales, cuyos horarios pueden ser consultados en las redes sociales oficiales de la SC.<\/p>\n\n\n\n<p>\u201cNuestros museos reciben una gran cantidad de visitantes locales y extranjeros cada a\u00f1o, y nos da mucho gusto recibir a familias y grupos de estudiantes, \u00a1Todos son bienvenidos!\u201d, agreg\u00f3 Ana Sof\u00eda Garc\u00eda Camil, titular de Cultura del Estado.<\/p>\n\n\n\n<p>Por su parte, el Director General de Museos, Historias y Patrimonio Cultural del Estado, Andr\u00e9s Mendoza Salas, coment\u00f3 que los espacios est\u00e1n habilitados para recibir la visita de centros educativos, exhortando a las autoridades escolares a programar recorridos guiados para acercar a la comunidad estudiantil a la historia y museograf\u00eda coahuilense, complementando as\u00ed sus aprendizajes adquiridos en el aula.<\/p>\n\n\n\n<p>Para agendar visitas escolares o de grupos, se invita a la poblaci\u00f3n a acercarse a cada museo y solicitar mayor informaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Invita a las y los coahuilenses a disfrutar las actividades y exposiciones de los recintos culturales del Estado Saltillo, Coahuila de Zaragoza; a 11 de Enero de 2023.- Con el inicio del a\u00f1o, el Gobierno del Estado de Coahuila, a trav\u00e9s de su Secretar\u00eda de Cultura (SC), invita al p\u00fablico a empezar con una experiencia cultural y de alto valor hist\u00f3rico visitando los museos de nuestro estado. Los recintos muse\u00edsticos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12,15],"tags":[],"class_list":["post-13084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-cultura","category-gobierno-de-coahuila","wpcat-5-id","wpcat-12-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=13084"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13084\/revisions"}],"predecessor-version":[{"id":13086,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13084\/revisions\/13086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/13085"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=13084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=13084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=13084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}