{"id":13398,"date":"2023-01-30T17:05:36","date_gmt":"2023-01-30T23:05:36","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=13398"},"modified":"2023-01-30T17:05:36","modified_gmt":"2023-01-30T23:05:36","slug":"direccion-de-medio-ambiente-realiza-primer-reciclaje-de-residuos-del-ano","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/01\/30\/direccion-de-medio-ambiente-realiza-primer-reciclaje-de-residuos-del-ano\/","title":{"rendered":"Direcci\u00f3n de Medio Ambiente realiza primer reciclaje de residuos del a\u00f1o."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 30 de enero de 2023.<\/p>\n\n\n\n<p>Se llev\u00f3 a cabo la primera actividad del programa \u201cReciclaje de residuos\u201d, a cargo<br>de la Direcci\u00f3n General de Medio Ambiente (DGMA), en conjunto con el Grupo<br>AlEn, la cual tiene como objetivo promover el uso correcto de los desechos<br>pl\u00e1sticos.<\/p>\n\n\n\n<p>Desde 2022, este programa se realiza cada \u00faltimo viernes del mes y forma parte<br>de las estrategias para el cuidado del medio ambiente, adem\u00e1s busca con ello<br>apoyar en la econom\u00eda de las familias, pues por cada kilogramo de material de<br>reciclaje, se entregan diferentes productos de limpieza.<\/p>\n\n\n\n<p>La actividad se llev\u00f3 a cabo en la explanada de la Plaza Mayor el pasado viernes<br>27 de enero, de 09:00 a 13:00 horas, con la finalidad de invitar a las personas a<br>que separen sus residuos reciclables y que \u00e9stos sean de nuevo incorporados a<br>un ciclo de vida \u00fatil.<\/p>\n\n\n\n<p>Los residuos recibidos para reciclar fueron botellas PET, de agua, refresco y jugo;<br>PEAD como envases de leche, yogur y champ\u00fa; PP que corresponden a<br>taparroscas y sueros orales, adem\u00e1s de aluminio como latas de refresco, jugos y<br>bebidas.<\/p>\n\n\n\n<p>De esa manera la Direcci\u00f3n de Medio ambiente, en conjunto con empresas y otras<br>organizaciones, implementa estrategias que contribuyen a crear una cultura de<br>separaci\u00f3n, valorizaci\u00f3n y reciclaje para el envase de sus productos.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n los ciudadanos interesados en sumarse pueden<br>comunicarse a la DGMA, al tel\u00e9fono 871 500 700 00, extensi\u00f3n 1437.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 30 de enero de 2023. Se llev\u00f3 a cabo la primera actividad del programa \u201cReciclaje de residuos\u201d, a cargode la Direcci\u00f3n General de Medio Ambiente (DGMA), en conjunto con el GrupoAlEn, la cual tiene como objetivo promover el uso correcto de los desechospl\u00e1sticos. Desde 2022, este programa se realiza cada \u00faltimo viernes del mes y forma partede las estrategias para el cuidado del medio ambiente, adem\u00e1s busca&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-13398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=13398"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13398\/revisions"}],"predecessor-version":[{"id":13400,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13398\/revisions\/13400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/13399"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=13398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=13398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=13398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}