{"id":13753,"date":"2023-02-17T19:16:07","date_gmt":"2023-02-18T01:16:07","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=13753"},"modified":"2023-02-17T19:16:08","modified_gmt":"2023-02-18T01:16:08","slug":"el-ejercito-mexicano-es-decisivo-en-la-gobernabilidad-y-la-paz-mars","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/02\/17\/el-ejercito-mexicano-es-decisivo-en-la-gobernabilidad-y-la-paz-mars\/","title":{"rendered":"EL EJ\u00c9RCITO MEXICANO ES DECISIVO EN LA GOBERNABILIDAD\u00a0\u00a0Y LA\u00a0\u00a0PAZ: MARS."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0El gobernador Miguel Riquelme asiste a la Sesi\u00f3n Solemne del Congreso para conmemorar el 110 Aniversario de su creaci\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 17 de Febrero de 2023.- Luego de reconocer el respaldo del Ej\u00e9rcito Mexicano, que naci\u00f3 hace 110 a\u00f1os en Coahuila, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds destac\u00f3 la lealtad, el patriotismo y el respaldo de los elementos que conforman la instituci\u00f3n castrense: \u201cFactor decisivo de la gobernabilidad, la paz y los equilibrios sociales que prevalecen en todo nuestro territorio\u201d.<\/p>\n\n\n\n<p>El Mandatario estatal asisti\u00f3 a la Sesi\u00f3n Solemne del Congreso del Estado donde se conmemor\u00f3 el D\u00eda del Ej\u00e9rcito (19 de febrero de 1913), junto a los titulares de los Poderes Legislativo y Judicial: el diputado Eduardo Olmos Castro y el magistrado Miguel Felipe Mery Ayup.<\/p>\n\n\n\n<p>Ante los Comandantes de la XI Regi\u00f3n Militar y de la VI Zona Militar, generales Eufemio Alberto Ibarra Flores y Gabriel Mart\u00ednez Garc\u00eda, respectivamente; legisladores locales y federales; alcaldesas y alcaldes; representantes del sector privado e integrantes de Cabildos, Riquelme Sol\u00eds resalt\u00f3 que el Ej\u00e9rcito Mexicano naci\u00f3 y tiene su casa en Coahuila.<\/p>\n\n\n\n<p>Despu\u00e9s de hacer una remembranza de los hechos hist\u00f3ricos que llevaron al entonces Gobernador de Coahuila, Venustiano Carranza, a crear el Ej\u00e9rcito Mexicano, dijo que a lo largo de 110 a\u00f1os desarroll\u00f3 una extraordinaria capacidad de preparaci\u00f3n, estrategia, profesionalismo y uso de las tecnolog\u00edas para responder a los desaf\u00edos que enfrenta el Pa\u00eds.<\/p>\n\n\n\n<p>\u201cEs la instituci\u00f3n m\u00e1s querida y admirada del pueblo mexicano. Es garante de la soberan\u00eda, defensor de la independencia nacional y pilar central de las estrategias de seguridad interior\u201d, dijo.<\/p>\n\n\n\n<p>Asimismo, Miguel Riquelme extern\u00f3 que con el acompa\u00f1amiento solidario del Ej\u00e9rcito Mexicano, Coahuila logr\u00f3 trascender una de las etapas m\u00e1s convulsas del M\u00e9xico moderno.<\/p>\n\n\n\n<p>\u201cEl esfuerzo iniciado en 2011 entre el Ej\u00e9rcito, los gobiernos estatales de Coahuila y Durango, as\u00ed como de los municipios que integran la Zona Metropolitana de La Laguna, fue el parteaguas para la estrategia de seguridad implementada en todo nuestro territorio\u201d, record\u00f3.<\/p>\n\n\n\n<p>\u201cEl marco operativo de reacci\u00f3n que a\u00f1os atr\u00e1s se realiz\u00f3 como \u2018Sellamiento Nazas\u2019, a\u00fan funciona bajo la denominaci\u00f3n Mando Especial de La Laguna y se mantiene como ejemplo para el resto del Pa\u00eds\u201d.<\/p>\n\n\n\n<p>Luego, Riquelme Sol\u00eds reiter\u00f3 el reconocimiento al Ej\u00e9rcito Mexicano, porque siempre acude al auxilio de la poblaci\u00f3n damnificada por desastres naturales.<\/p>\n\n\n\n<p>Adem\u00e1s, reconoci\u00f3 que la vacunaci\u00f3n en Coahuila se inici\u00f3 con \u00e9xito gracias a la coordinaci\u00f3n entre el Gobierno del Estado y la SEDENA, lo que nos permiti\u00f3 ser de las primeras entidades en recobrar el dinamismo social, educativo, cultural y econ\u00f3mico, ante la contingencia sanitaria por el Covid-19.<\/p>\n\n\n\n<p>\u201cHoy, el Ej\u00e9rcito Nacional es factor decisivo de la gobernabilidad, la paz y los equilibrios sociales que prevalecen en todo nuestro territorio\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p><strong>LA COORDINACI\u00d3N AFIANZA BLINDAJE CONTRA LA DELINCUENCIA<\/strong><\/p>\n\n\n\n<p>Por otra parte, el Gobernador refiri\u00f3 que con las estrategias coordinadas entre los tres \u00f3rdenes de Gobierno con el Ej\u00e9rcito Mexicano y la Guardia Nacional, es posible afianzar un blindaje contra la delincuencia y el crimen en Coahuila.<\/p>\n\n\n\n<p>\u201cSu presencia, acompa\u00f1amiento y trabajo, se han extendido a los esfuerzos coordinados que realizamos con los 38 Ayuntamientos y est\u00e1n sumados en el seno del Consejo Estatal de Seguridad P\u00fablica\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s destac\u00f3 que la fuerza y despliegue de la XI Regi\u00f3n Militar, as\u00ed como de la VI y de la 47 Zona Militar, ampliaron la visi\u00f3n y los alcances de las l\u00edneas de acci\u00f3n para enfrentar los retos y cambiantes situaciones de la realidad que impone el mundo globalizado e interconectado.<\/p>\n\n\n\n<p>&nbsp;\u201cNuestra alianza con el Ej\u00e9rcito nos permite avanzar gradual y permanentemente en la disminuci\u00f3n de los \u00edndices delictivos de alto impacto\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>En ese sentido, Miguel Riquelme ratific\u00f3 que su gratitud y colaboraci\u00f3n con las Fuerzas Armadas se tradujo en mayor infraestructura militar en la entidad.<\/p>\n\n\n\n<p>\u201cFortaleci\u00f3 su presencia en todo el estado; nos llena de orgullo recalcar que somos la Cuna y la Casa del Ej\u00e9rcito Mexicano\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p>Sobre el particular, detall\u00f3 que actualmente Coahuila cuenta con 17 cuarteles, con capacidad para 7 mil efectivos, as\u00ed como el Hospital Militar de Torre\u00f3n.<\/p>\n\n\n\n<p>El a\u00f1o pasado, refiri\u00f3, comenz\u00f3 operaciones el cuartel de Ciudad Acu\u00f1a, que cierra con fuerza el cerco de protecci\u00f3n y es clave para las estrategias de seguridad en la frontera norte del estado.<\/p>\n\n\n\n<p>Por otra parte, Miguel Riquelme se\u00f1al\u00f3 que esta colaboraci\u00f3n con la SEDENA se extendi\u00f3 al proyecto de ampliaci\u00f3n en la Aduana de Piedras Negras, para aumentar el dinamismo comercial y productivo de la franja fronteriza.<\/p>\n\n\n\n<p>El Gobernador de Coahuila indic\u00f3 que por estos y otros muchos motivos, adem\u00e1s de recordar al Ej\u00e9rcito en los inicios de su historia, \u201cesta fecha nos obliga a agradecer su permanencia y resultados en nuestra tierra\u201d.<\/p>\n\n\n\n<p>\u201cComo consecuencia del entorno de seguridad y orden p\u00fablico, aunado a nuestras ventajas competitivas y de conexi\u00f3n con los puertos mar\u00edtimos y los mercados internacionales, Coahuila se consolida a\u00f1o con a\u00f1o como un destino de inversi\u00f3n de primer orden y una potencia econ\u00f3mica\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>En ese sentido, Riquelme Sol\u00eds record\u00f3 que mes por mes llegan a la entidad un promedio de tres nuevos proyectos de inversi\u00f3n o de ampliaciones de otras, que generan mayor sinergia de desarrollo y de crecimiento para la poblaci\u00f3n de Coahuila.<\/p>\n\n\n\n<p>Cit\u00f3 que la entidad, al ser de las m\u00e1s seguras de M\u00e9xico, tambi\u00e9n le lleva a ser de las m\u00e1s competitivas, de las m\u00e1s exportadoras y de las m\u00e1s atractivas para la inversi\u00f3n.<\/p>\n\n\n\n<p>\u201cHoy, formamos parte de las 10 entidades federativas que m\u00e1s contribuyen al crecimiento de M\u00e9xico\u2026 no obstante la p\u00e9rdida de m\u00e1s de 19 mil empleos durante la pandemia, hoy generamos m\u00e1s de 67 mil fuentes laborales\u201d, apunt\u00f3.<\/p>\n\n\n\n<p><strong>RECONOCE APOYO DEL EJ\u00c9RCITO<\/strong><\/p>\n\n\n\n<p>&nbsp;Al t\u00e9rmino de su intervenci\u00f3n, Miguel Riquelme reconoci\u00f3 la coordinaci\u00f3n del Ej\u00e9rcito Mexicano con las fuerzas de seguridad del Estado, que permiten evitar intentos de civiles armados por ingresar a nuestro territorio.<\/p>\n\n\n\n<p>\u201cCon el compromiso, esfuerzo y permanencia del Ej\u00e9rcito y la Guardia Nacional, afianzamos un modelo de seguridad que se sostiene como referencia nacional de coordinaci\u00f3n, eficiencia y efectividad\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Previamente, la diputada local Luz Natalia Vigil Orona, a nombre de las y los integrantes de la LXII Legislatura, dio lectura a la posici\u00f3n del Congreso, en la que tambi\u00e9n destac\u00f3 la labor de las Fuerzas Armadas en Coahuila.<\/p>\n\n\n\n<p>En tanto, el General Ejufemio Alberto Ibarra Flores, Comandante de la XI Regi\u00f3n Militar, hizo una rese\u00f1a de la historia del Ej\u00e9rcito Mexicano y de su labor en beneficio de la poblaci\u00f3n y en la salvaguardia de la soberan\u00eda nacional.<\/p>\n\n\n\n<p>De la misma forma, reiter\u00f3 la disposici\u00f3n de la instituci\u00f3n de mantener su coordinaci\u00f3n, trabajo estrecho y permanente, con lealtad y patriotismo, con las autoridades de la entidad y de todo el Pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0El gobernador Miguel Riquelme asiste a la Sesi\u00f3n Solemne del Congreso para conmemorar el 110 Aniversario de su creaci\u00f3n. Saltillo, Coahuila de Zaragoza; a 17 de Febrero de 2023.- Luego de reconocer el respaldo del Ej\u00e9rcito Mexicano, que naci\u00f3 hace 110 a\u00f1os en Coahuila, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds destac\u00f3 la lealtad, el patriotismo y el respaldo de los elementos que conforman la instituci\u00f3n castrense: \u201cFactor decisivo de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13754,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,24],"tags":[],"class_list":["post-13753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-seguridad","wpcat-5-id","wpcat-15-id","wpcat-24-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=13753"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13753\/revisions"}],"predecessor-version":[{"id":13755,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13753\/revisions\/13755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/13754"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=13753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=13753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=13753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}