{"id":13780,"date":"2023-02-20T19:11:07","date_gmt":"2023-02-21T01:11:07","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=13780"},"modified":"2023-02-20T19:11:07","modified_gmt":"2023-02-21T01:11:07","slug":"la-comunidad-estudiantil-es-prioridad-para-mi-gobierno-mars","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/02\/20\/la-comunidad-estudiantil-es-prioridad-para-mi-gobierno-mars\/","title":{"rendered":"LA COMUNIDAD ESTUDIANTIL ES PRIORIDAD PARA MI GOBIERNO: MARS."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>Entrega gobernador Miguel Riquelme equipo educativo en el Conalep Torre\u00f3n.<\/em><\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>Firma como Testigo de Honor el convenio de colaboraci\u00f3n entre Conalep-Coparmex.<\/em><\/strong><\/p>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 20 de Febrero de 2023.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds encabez\u00f3 la ceremonia de inicio del Ciclo Escolar 2022-2023 en el Conalep de esta ciudad, en donde adem\u00e1s entreg\u00f3 equipo educativo y firm\u00f3, como Testigo de Honor, un convenio de colaboraci\u00f3n entre esta instituci\u00f3n y la Coparmex.<\/p>\n\n\n\n<p>En su discurso, destac\u00f3 que este plantel es orgullo de Coahuila en la fuerza laboral, y record\u00f3 que hace algunos meses se entreg\u00f3 la techumbre y hoy se entrega infraestructura educativa.<\/p>\n\n\n\n<p>Mencion\u00f3 que hoy Coahuila es el segundo estado m\u00e1s seguro del Pa\u00eds, y que es de los que m\u00e1s empleos ofrece a su gente: \u201cCuando termin\u00e9 la carrera, la principal preocupaci\u00f3n era a d\u00f3nde nos \u00edbamos a ir a trabajar; pero hoy ustedes van a tener lo mejor, que es no alejarse de su tierra y aqu\u00ed mismo tienen oportunidad de progresar\u201d.<\/p>\n\n\n\n<p>Riquelme Sol\u00eds se\u00f1al\u00f3 que una ventaja del Estado es la actualizaci\u00f3n de carreras para poder mejorar la oferta; record\u00f3 que este a\u00f1o se empezaron a armar los autos el\u00e9ctricos y que las \u00e1reas de oportunidad se extienden a esa rama, por lo que hay que estar preparados.<\/p>\n\n\n\n<p>Adem\u00e1s, expres\u00f3 que uno de los objetivos de su Gobierno fue extender la din\u00e1mica productiva a todas las regiones, y advirti\u00f3 que hoy la entidad est\u00e1 bien, pero toca dejar sentadas las bases en materia de seguridad para que siempre, como sociedad, se goce de la tranquilidad.<\/p>\n\n\n\n<p>Miguel Riquelme recalc\u00f3 que la comunidad estudiantil es muy importante para la entidad, a quienes exhort\u00f3 a seguirse preparando.<\/p>\n\n\n\n<p>En su mensaje, Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, Presidente Municipal de Torre\u00f3n, mencion\u00f3 que para su Administraci\u00f3n este evento es muy importante, ya que desea que los cerca de 1,500 alumnos con los que cuenta esta instituci\u00f3n tengan las mejores condiciones para enfrentar mejor el mundo.<\/p>\n\n\n\n<p>\u201cLa firma de este convenio es un compromiso, pues tiene qu\u00e9 ver con construir una sociedad m\u00e1s justa, con planteles dignos, plasmados en infraestructura y equipamiento\u201d, dijo, por lo que agradeci\u00f3 a quienes lo hace posible, la Coparmex.<\/p>\n\n\n\n<p>Asimismo, Alfio Vega de la Pe\u00f1a, Director General de Conalep, coment\u00f3 que hoy regresan a clases poco m\u00e1s de 10 mil alumnos en Coahuila en los diversos planteles de la entidad: \u201cUsted, Gobernador, nos ha instruido a que estemos vinculados a organismos empresariales y que resolvamos las demandas t\u00e9cnicas, por las nuevas empresas que se instalan en la entidad y que los j\u00f3venes cuenten con las herramientas necesarias\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Dijo que con este convenio con Coparmex Laguna, que lleva la firma de su presidente, Jos\u00e9 Leopoldo Reyes, se da inicio al Programa del Aula Industrial Coparmex, con un primer grupo de 60 alumnos de Conalep Torre\u00f3n, mismo que ser\u00e1 incrementado hasta llegar a 180 estudiantes de Mecatr\u00f3nica dentro de este Sistema.<\/p>\n\n\n\n<p>Cit\u00f3 adem\u00e1s, que el d\u00eda de hoy reciben equipos de alta tecnolog\u00eda, que ayudar\u00e1n en la capacitaci\u00f3n para fabricaci\u00f3n de piezas met\u00e1licas con gran precisi\u00f3n en los planteles de Saltillo San Pedro y Torre\u00f3n.&nbsp;<\/p>\n\n\n\n<p>\u201cSon tres m\u00e1quinas fresadoras de control num\u00e9rico que ser\u00e1n de gran utilidad para el entrenamiento de los alumnos de las carreras M\u00e1quinas de Herramientas y Electromec\u00e1nica Industrial\u201d, inform\u00f3.<\/p>\n\n\n\n<p>De la misma manera, Vega coment\u00f3 que hoy tambi\u00e9n se hace la entrega del Programa \u201cAbre tu Libro\u201d, con un poco m\u00e1s de 29,348 ejemplares que en el Sistema Conalep ser\u00e1n de gran apoyo para su consulta.&nbsp;<\/p>\n\n\n\n<p>\u201cCabe resaltar que en estos \u00faltimos cuatro a\u00f1os, con este exitoso programa hemos entregado 244,138 libros\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, Jorge Leopoldo Reyes Casas, presidente de Coparmex Laguna, dijo que la educaci\u00f3n ayuda a la persona a aprender a hacer lo que es capaz de ser, por lo que gustoso agradeci\u00f3 a la gente de Conalep el confiar en ellos.<\/p>\n\n\n\n<p>Record\u00f3 que la Formaci\u00f3n Dual en 2013 dio inicio y se gener\u00f3 un c\u00edrculo virtuoso para insertar a los j\u00f3venes en el mercado laboral, que consiste en que se integren dentro de la empresa y que al final cumplan con los est\u00e1ndares del sector productivo.<\/p>\n\n\n\n<p>\u201cAqu\u00ed en La Laguna se tiene el reto de convertirnos en la joya industrial de M\u00e9xico, y se tienen tres caracter\u00edsticas: Talento humano; bono poblacional (de o a 18 a\u00f1os), y certeza; es decir, que vean a la regi\u00f3n por considerarla un lugar para quedarse, lo que le agradecemos al gobernador Miguel Riquelme\u201d, expuso.<\/p>\n\n\n\n<p>Luna Ang\u00e9lica S\u00e1nchez Salazar agradeci\u00f3, a nombre de las y los estudiantes del Conalep, por el equipo y la firma del convenio, y mencion\u00f3 que son afortunados de pertenecer a esta instituci\u00f3n que prepara alumnos de calidad y con docentes comprometidos.<\/p>\n\n\n\n<p>\u201cDejamos de manifiesto nuestro agradecimiento a usted, se\u00f1or gobernador Miguel Riquelme. Hoy se nos entregan 9,994 libros, antes una techumbre y dentro del Modelo de Formaci\u00f3n Dual contamos con casi 300 egresados que forman parte del mercado laboral\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>En esta ceremonia estuvieron presentes, adem\u00e1s, Ver\u00f3nica Mart\u00ednez Garc\u00eda, senadora de la Rep\u00fablica; Jos\u00e9 Antonio Guti\u00e9rrez Jard\u00f3n, diputado federal; Mario Cepeda Ram\u00edrez, diputado local; Francisco Saracho Navarro, Secretario de Educaci\u00f3n; Irma Mayela Adame Aguayo, Directora del plantel, y funcionarios estatales, municipales, as\u00ed como alumnos, alumnas y padres de familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Entrega gobernador Miguel Riquelme equipo educativo en el Conalep Torre\u00f3n. \u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Firma como Testigo de Honor el convenio de colaboraci\u00f3n entre Conalep-Coparmex. Torre\u00f3n, Coahuila de Zaragoza; a 20 de Febrero de 2023.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds encabez\u00f3 la ceremonia de inicio del Ciclo Escolar 2022-2023 en el Conalep de esta ciudad, en donde adem\u00e1s entreg\u00f3 equipo educativo y firm\u00f3, como Testigo de Honor, un convenio de colaboraci\u00f3n entre esta&#8230;<\/p>\n","protected":false},"author":1,"featured_media":13781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,93,9,15,28,7],"tags":[],"class_list":["post-13780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-conalep","category-educacion","category-gobierno-de-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-93-id","wpcat-9-id","wpcat-15-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=13780"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13780\/revisions"}],"predecessor-version":[{"id":13782,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/13780\/revisions\/13782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/13781"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=13780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=13780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=13780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}