{"id":14285,"date":"2023-03-16T21:09:14","date_gmt":"2023-03-17T03:09:14","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=14285"},"modified":"2023-03-16T21:09:16","modified_gmt":"2023-03-17T03:09:16","slug":"cursa-en-la-uadec-la-maestria-en-promocion-y-desarrollo-cultural","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/03\/16\/cursa-en-la-uadec-la-maestria-en-promocion-y-desarrollo-cultural\/","title":{"rendered":"Cursa en la UAdeC la Maestr\u00eda en Promoci\u00f3n y Desarrollo Cultural."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 16 de marzo de 2023. El Centro de Estudios e<br>Investigaciones Interdisciplinarias de la Universidad Aut\u00f3noma de Coahuila,<br>convoca a profesionales de organizaciones culturales, funcionarios, docentes, y<br>promotores culturales, vinculados al desarrollo cultural, ciencias sociales, artes y<br>humanidades a cursar la Maestr\u00eda en Promoci\u00f3n y Desarrollo Cultural cuyas<br>clases iniciar\u00e1n en agosto de 2023.<\/p>\n\n\n\n<p>El objetivo del programa es formar profesionales en los procedimientos y<br>herramientas te\u00f3rico-metodol\u00f3gicos de la gesti\u00f3n cultural y las pol\u00edticas culturales,<br>con base en un enfoque intercultural, estrat\u00e9gico, comunitario, profesionalizante y<br>orientado a la transformaci\u00f3n de problemas socioculturales en los territorios, las<br>organizaciones y las comunidades en las cuales interact\u00faan.<\/p>\n\n\n\n<p>El registro de aspirantes se har\u00e1 en <a href=\"http:\/\/www.uadec.mx\/admisiones\" target=\"_blank\" rel=\"noreferrer noopener\">www.uadec.mx\/admisiones<\/a>\/ y estar\u00e1 abierto<br>hasta el 31 de mayo de 2023, el examen de admisi\u00f3n se aplicar\u00e1 el 9 de junio, las<br>entrevistas de admisi\u00f3n se realizar\u00e1n el 19 y 20 de junio, la publicaci\u00f3n de<br>resultados se har\u00e1 el 23 de junio y las clases iniciar\u00e1n el 16 de agosto.<\/p>\n\n\n\n<p>La Maestr\u00eda es profesionalizante, en modalidad mixta con clases virtuales y una<br>semana presencial al a\u00f1o; el programa est\u00e1 estructurado en periodos semestrales<br>y se sustenta a partir de ejes tem\u00e1ticos que permiten abordar problem\u00e1ticas<br>centrales y necesidades espec\u00edficas, temas obligados en la formaci\u00f3n del<br>trabajador de la cultura, as\u00ed como l\u00edneas de contenido que propicien la obtenci\u00f3n y<br>el manejo del instrumental necesario para el ejercicio de la pr\u00e1ctica profesional<br>desde una perspectiva interdisciplinaria.<\/p>\n\n\n\n<p>El egresado tendr\u00e1 la capacidad de analizar conceptual y operativamente la<br>pr\u00e1ctica de la cultura en distintos niveles y \u00e1mbitos de incidencia, desde la gesti\u00f3n<br>comunitaria, p\u00fablica y privada; dise\u00f1ar\u00e1, planificar\u00e1 y ejecutar\u00e1 pol\u00edticas y<br>proyectos culturales con base en sus conocimientos y en su habilidad en el<br>manejo metodol\u00f3gico de la macro y micro planeaci\u00f3n de la cultura y en la gesti\u00f3n<br>de acciones para la ejecuci\u00f3n y administraci\u00f3n de programas y proyectos<br>culturales.<\/p>\n\n\n\n<p>Los interesados deber\u00e1n de cubrir los siguientes requisitos: contar con t\u00edtulo y<br>c\u00e9dula de licenciatura, promedio m\u00ednimo de 80 o su equivalente en su \u00faltimo grado<br>de estudios, comprobante de ingl\u00e9s u otra lengua, carta de motivos, aprobar el<br>proceso de admisi\u00f3n y propuesta de investigaci\u00f3n.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n comunicarse con la coordinadora de la Maestr\u00eda, Dra. Ana<br>Isabel P\u00e9rez Gavil\u00e1n al correo mpdc@uadec.edu.mx, visitar la p\u00e1gina<br>http:\/\/www.uadec.mx\/ceii\/ o llamar a los tel\u00e9fonos (844) 689 10 56 y (844) 659 10<br>58.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 16 de marzo de 2023. El Centro de Estudios eInvestigaciones Interdisciplinarias de la Universidad Aut\u00f3noma de Coahuila,convoca a profesionales de organizaciones culturales, funcionarios, docentes, ypromotores culturales, vinculados al desarrollo cultural, ciencias sociales, artes yhumanidades a cursar la Maestr\u00eda en Promoci\u00f3n y Desarrollo Cultural cuyasclases iniciar\u00e1n en agosto de 2023. El objetivo del programa es formar profesionales en los procedimientos yherramientas te\u00f3rico-metodol\u00f3gicos de la gesti\u00f3n cultural y las pol\u00edticas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14286,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-14285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=14285"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14285\/revisions"}],"predecessor-version":[{"id":14287,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14285\/revisions\/14287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/14286"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=14285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=14285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=14285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}