{"id":14515,"date":"2023-03-31T18:15:25","date_gmt":"2023-04-01T00:15:25","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=14515"},"modified":"2023-03-31T18:15:25","modified_gmt":"2023-04-01T00:15:25","slug":"invita-uadec-al-primer-bazar-arteartesania-del-1-al-16-de-abril","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/03\/31\/invita-uadec-al-primer-bazar-arteartesania-del-1-al-16-de-abril\/","title":{"rendered":"Invita UAdeC al \u201cPrimer Bazar ArteArtesan\u00eda\u201d del 1 al 16 de Abril."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 31 de marzo de 2023. La Universidad Aut\u00f3noma de<br>Coahuila a trav\u00e9s de la Coordinaci\u00f3n General de Difusi\u00f3n y Patrimonio Cultural<br>(DPC), invitan a la comunidad universitaria y p\u00fablico en general al \u201cPrimer Bazar<br>ArteArtesan\u00eda\u201d que se llevar\u00e1 a cabo del 1 al 16 de abril, de 10:00 a 18: horas, en<br>el Recinto del Patrimonio Cultural Universitario, ubicado en Hidalgo Norte 211 en<br>el Centro Hist\u00f3rico de Saltillo.<\/p>\n\n\n\n<p>Diana Zamora Cort\u00e9s, colaboradora de la DPC y encargada de difusi\u00f3n del<br>evento, comparti\u00f3 que el Bazar es una plataforma para dar a conocer el talento<br>universitario de las y los estudiantes de la Escuela de Artes Pl\u00e1sticas \u201cProf. Rub\u00e9n<br>Herrera\u201d, y de las diferentes Escuelas, Facultades e Institutos de la UAdeC para<br>que expongan y comercialicen sus obras.<\/p>\n\n\n\n<p>Agreg\u00f3 que, adem\u00e1s de los estudiantes de la m\u00e1xima casa de estudios, se<br>contar\u00e1 con la participaci\u00f3n de diferentes artistas coahuilenses ya posicionados y<br>reconocidos, para que en pr\u00f3ximas ediciones se sumen m\u00e1s artistas de la<br>comunidad universitaria y del estado.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que la respuesta de los artistas ha sido favorable y se han estado<br>acercando a la dependencia para pedir oportunidad de exponer su obra, entre los<br>confirmados se encuentran: Armando Meza, Graciela Alc\u00e1zar, Gustavo M\u00f6ller,<br>Griselda Tamez, Gloria M\u00e9ndez, Monserrat Ruiz, Dewalli Ascacio, Fernando<br>L\u00f3pez, Eleazar Montejano, Lidia Gonz\u00e1lez, Rosy Ayala, Z\u00e9nen Vizca\u00edno, Ricardo<br>Mata e Irma Alvarado.<\/p>\n\n\n\n<p>El Bazar contar\u00e1 con la exposici\u00f3n y venta de artesan\u00edas, pinturas al \u00f3leo, acr\u00edlico,<br>jabones artesanales, pulseras, entre otras; tambi\u00e9n habr\u00e1 participaci\u00f3n art\u00edstica de<br>alumnas y alumnos de la Escuela de M\u00fasica y micr\u00f3fono abierto para toda<br>persona que desee expresarse mediante un poema o un texto breve.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n del evento llamar al tel\u00e9fono del Recinto Cultural<br>Universitario: (844) 410 97 05 o visitar las redes sociales de la Coordinaci\u00f3n de<br>Difusi\u00f3n y Patrimonio Cultural de la UAdeC: en Twitter como @dpcuadec, en<br>Facebook como \u201cDpc UAdeC\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 31 de marzo de 2023. La Universidad Aut\u00f3noma deCoahuila a trav\u00e9s de la Coordinaci\u00f3n General de Difusi\u00f3n y Patrimonio Cultural(DPC), invitan a la comunidad universitaria y p\u00fablico en general al \u201cPrimer BazarArteArtesan\u00eda\u201d que se llevar\u00e1 a cabo del 1 al 16 de abril, de 10:00 a 18: horas, enel Recinto del Patrimonio Cultural Universitario, ubicado en Hidalgo Norte 211 enel Centro Hist\u00f3rico de Saltillo. Diana Zamora Cort\u00e9s, colaboradora&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-14515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=14515"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14515\/revisions"}],"predecessor-version":[{"id":14517,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/14515\/revisions\/14517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/14516"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=14515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=14515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=14515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}