{"id":1462,"date":"2021-04-09T18:30:16","date_gmt":"2021-04-09T23:30:16","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=1462"},"modified":"2021-04-09T18:30:16","modified_gmt":"2021-04-09T23:30:16","slug":"realiza-salud-coahuila-primer-trasplante-exitoso-de-rinon-del-ano","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/04\/09\/realiza-salud-coahuila-primer-trasplante-exitoso-de-rinon-del-ano\/","title":{"rendered":"REALIZA SALUD COAHUILA PRIMER TRASPLANTE EXITOSO DE RI\u00d1\u00d3N DEL A\u00d1O."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>\u00a0Paciente padeci\u00f3 Covid-19 y se recupera satisfactoriamente.<\/em><\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>&nbsp;Hospital General de Saltillo llev\u00f3 a cabo la intervenci\u00f3n quir\u00fargica sin ning\u00fan contratiempo.<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 9 de Abril de 2021.- Como un \u00e9xito fue registrado el primer trasplante de ri\u00f1\u00f3n llevado a cabo en 2021 en el Hospital General de Saltillo, a trav\u00e9s de las manos de personal m\u00e9dico especializado e instalaciones propias de la Secretar\u00eda de Salud del Estado.<\/p>\n\n\n\n<p>En una visita encabezada por la Presidenta Honoraria del Sistema DIF, Marcela Gorg\u00f3n, y el Secretario de Salud del Estado, Roberto Bernal G\u00f3mez, se sostuvo un encuentro con el paciente beneficiado, Edmundo Arredondo L\u00f3pez, y m\u00e9dicos tratantes.&nbsp;<\/p>\n\n\n\n<p>Esta intervenci\u00f3n se logra gracias a la certificaci\u00f3n que obtuvo el nosocomio a nivel nacional para desarrollar este tipo de procedimientos para fortalecer la cultura de la donaci\u00f3n de \u00f3rganos y tejidos.<\/p>\n\n\n\n<p>\u201cLos dos pacientes hombres reaccionaron bien a las intervenciones, tanto el donador como el receptor del \u00f3rgano, quienes tras la operaci\u00f3n continuaron con atenci\u00f3n m\u00e9dica y de observaci\u00f3n en el Hospital General. Por nuestra parte, continuaremos llevando a cabo acciones y estrategias que tienen como \u00fanico fin el generar conciencia entre la poblaci\u00f3n de esta acci\u00f3n humanista\u201d, asegur\u00f3 Bernal G\u00f3mez.<\/p>\n\n\n\n<p>Jorge Bill Soto Almaguer, Director del Hospital General, apunt\u00f3 que el paciente tiene como antecedente haber padecido Covid-19, situaci\u00f3n que le gener\u00f3 una insuficiencia renal que afortunadamente se atendi\u00f3.<\/p>\n\n\n\n<p>\u201cLa cirug\u00eda, que normalmente tiene un alto costo, se realiza en una instituci\u00f3n p\u00fablica con personal preparado\u201d, dijo.<\/p>\n\n\n\n<p>Para lograr esta acci\u00f3n, la Secretar\u00eda de Salud cuenta con el apoyo del DIF Coahuila y del Centro Estatal de Trasplantes (CEETRA) de Coahuila.<\/p>\n\n\n\n<p>En el tema de procuraciones de \u00f3rganos y tejidos en hospitales de la Secretar\u00eda de Salud, se han registrado 15 desde 2020 a la fecha.<\/p>\n\n\n\n<p>Mientras que en el Registro Nacional de Donadores Coahuila se encuentra en el 9\u00b0 lugar nacional, con 3 mil 500 donadores voluntarios que se encuentra debidamente registrados en la entidad.<\/p>\n\n\n\n<p>Explic\u00f3 adem\u00e1s que Coahuila tiene registradas licencias para la procuraci\u00f3n de \u00f3rganos, as\u00ed como de trasplante y la de la procuraci\u00f3n de \u00f3rganos para el Hospital General de Saltillo, obtenida en septiembre de 2018; la de licencia de procuraci\u00f3n para el Hospital General de Torre\u00f3n, obtenida en agosto de 2019.<\/p>\n\n\n\n<p>As\u00ed como la licencia de trasplantes para las ciudades de Saltillo y Torre\u00f3n, obtenidas en febrero y marzo 2020 respectivamente; la de procuraci\u00f3n de \u00f3rganos y tejidos para los hospitales generales de Monclova y Piedras Negras, que se encuentran actualmente en tr\u00e1mite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Paciente padeci\u00f3 Covid-19 y se recupera satisfactoriamente. \u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Hospital General de Saltillo llev\u00f3 a cabo la intervenci\u00f3n quir\u00fargica sin ning\u00fan contratiempo. Saltillo, Coahuila de Zaragoza; a 9 de Abril de 2021.- Como un \u00e9xito fue registrado el primer trasplante de ri\u00f1\u00f3n llevado a cabo en 2021 en el Hospital General de Saltillo, a trav\u00e9s de las manos de personal m\u00e9dico especializado e instalaciones propias de la Secretar\u00eda de Salud del Estado&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":1463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,14],"tags":[],"class_list":["post-1462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-salud","wpcat-5-id","wpcat-15-id","wpcat-14-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=1462"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1462\/revisions"}],"predecessor-version":[{"id":1464,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1462\/revisions\/1464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=1462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=1462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=1462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}