{"id":15225,"date":"2023-05-16T19:26:08","date_gmt":"2023-05-17T01:26:08","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=15225"},"modified":"2023-05-16T19:26:08","modified_gmt":"2023-05-17T01:26:08","slug":"congreso-del-estado-de-coahuila-informa-20","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/05\/16\/congreso-del-estado-de-coahuila-informa-20\/","title":{"rendered":"Congreso del Estado de Coahuila informa:"},"content":{"rendered":"\n<p>Las Diputadas y los Diputados de la Sexag\u00e9sima Segunda<br>Legislatura del Congreso del Estado de Coahuila de Zaragoza,<br>llevaron a efecto hoy la D\u00e9cima Primera Sesi\u00f3n del Primer Periodo<br>Ordinario, correspondiente al Tercer A\u00f1o de Ejercicio Constitucional,<br>en la cual se aprob\u00f3 la propuesta de la Junta de Gobierno, relativa a la<br>modificaci\u00f3n de la integraci\u00f3n de las Comisiones Dictaminadoras<br>Permanentes y Comit\u00e9s, de la LXII Legislatura Local.<\/p>\n\n\n\n<p>En esta Sesi\u00f3n, Diputadas y Diputados plantearon las siguientes<br>iniciativas:<\/p>\n\n\n\n<p>1.- Iniciativa con Proyecto de Decreto que plantea reformar la<br>fracci\u00f3n XI del art\u00edculo 84 de la Constituci\u00f3n Pol\u00edtica del Estado de<br>Coahuila de Zaragoza.<\/p>\n\n\n\n<p>2.- Iniciativa con Proyecto de Decreto que plantea se apruebe<br>inscribir con Letras Doradas en el Muro de Honor del Sal\u00f3n de<br>Sesiones del Congreso del Estado, el nombre de Nancy C\u00e1rdenas<br>Mart\u00ednez.<\/p>\n\n\n\n<p>3.- Iniciativa con Proyecto de Decreto para que se reforme la<br>fracci\u00f3n IV del Art\u00edculo 20, de la Ley de Protecci\u00f3n y Trato Digno a los<br>Animales para el Estado.<\/p>\n\n\n\n<p>4.- Iniciativa con Proyecto de Decreto que plantea se reforme la<br>Ley de Hacienda para el Estado.<\/p>\n\n\n\n<p>5.- Iniciativa con Proyecto de Decreto que plantea modificar el<br>contenido de la fracci\u00f3n XIII del art\u00edculo 31, de la Ley Org\u00e1nica de la<br>Administraci\u00f3n P\u00fablica del Estado.<\/p>\n\n\n\n<p>Por otra parte, las Diputadas y los Diputados aprobaron por<br>unanimidad de votos, los dict\u00e1menes siguientes:<\/p>\n\n\n\n<p>1.- Dictamen de la Comisi\u00f3n de Gobernaci\u00f3n, Puntos<br>Constitucionales y Justicia, con Proyecto de Decreto por el que se aprueba la Minuta con Proyecto de Decreto de la C\u00e1mara de<br>Senadores del H. Congreso de la Uni\u00f3n, por el que se reforman y<br>adicionan los art\u00edculos 38 y 102 de la Constituci\u00f3n Pol\u00edtica de los<br>Estados Unidos Mexicanos, en materia de suspensi\u00f3n de derechos<br>para ocupar un cargo, empleo o comisi\u00f3n del servicio p\u00fablico.<\/p>\n\n\n\n<p>En el dictamen, las Diputadas y los Diputados de la Comisi\u00f3n de<br>Gobernaci\u00f3n, Puntos Constitucionales y Justicia, consideran que esta<br>reforma atiende a las necesidades palpables que aquejan y atraviesan<br>los derechos de las mujeres d\u00eda con d\u00eda.<\/p>\n\n\n\n<p>Manifiestan que es evidente que esta reforma constitucional<br>atiende a la discriminaci\u00f3n y violencia hist\u00f3rica de las que las mujeres<br>han sido v\u00edctimas, pues m\u00e1s del 70% de 10 a\u00f1os a m\u00e1s, han sufrido<br>al menos un episodio de violencia en su vida.<\/p>\n\n\n\n<p>Asimismo, subrayan que las presiones sociales, y sobre todo, de<br>los colectivos feministas, lograron que las personas que aspiraran por<br>un cargo de elecci\u00f3n popular firmaran un formato de buena fe, sin<br>ning\u00fan efecto legal ni jur\u00eddico en caso de que no fuera cierto el dicho<br>de la persona de no ser persona deudora alimentaria morosa, no<br>haber cometido violencia familiar y\/o dom\u00e9stica o cualquier agresi\u00f3n<br>de g\u00e9nero ya sea en el \u00e1mbito p\u00fablico o privado, o bien, haber sido<br>condenado o sancionado por delitos sexuales.<\/p>\n\n\n\n<p>Siendo as\u00ed, que dicho formato era un acto social, provocando que<br>no tuviera ninguna vinculatoriedad jur\u00eddico-legal, resultando en que<br>muchas personas que estuvieran condenadas o sentenciadas por<br>dichos actos, siguieran al frente de la toma de decisiones.<\/p>\n\n\n\n<p>Tal y como lo se\u00f1al\u00f3 la exposici\u00f3n de motivos de una de las<br>iniciativas que originaron el dictamen en cuesti\u00f3n, este trabajo se debe<br>a mesas de trabajo de personas expertas, estudios de normativas<br>internacionales en la materia, parlamentos abiertos y sobre todo, la<br>voz de muchas mujeres feministas que siguen luchando por lograr la<br>igualdad sustantiva en sus derechos.<\/p>\n\n\n\n<p>La Ley 3 de 3 contra la violencia sin duda alguna abona a la lucha<br>feminista, pero sobre todo, otorga la certeza y las herramientas para<br>lograr procesos electorales libres de violencia y discriminaci\u00f3n, pues<br>solo as\u00ed se garantizar\u00e1 que las personas que nos representan, no sean<br>a la vez personas victimarias, violentas, y ajenas al cumplimiento de<br>sus obligaciones, se\u00f1alan las Diputadas y los Diputados en la<br>exposici\u00f3n de motivos.<\/p>\n\n\n\n<p>Se dispuso remitir el presente Decreto al Congreso de la Uni\u00f3n<br>para efectos de lo consignado en el art\u00edculo 135 de la Constituci\u00f3n<br>Pol\u00edtica de los Estados Unidos Mexicanos, as\u00ed como su env\u00edo al<br>Ejecutivo del Estado para su promulgaci\u00f3n y su publicaci\u00f3n el<br>Peri\u00f3dico Oficial del Gobierno del Estado.<\/p>\n\n\n\n<p>2.-Dictamen\u00a0de la Comisi\u00f3n de Gobernaci\u00f3n, Puntos<br>Constitucionales y Justicia, con Proyecto de Decreto por el que se<br>aprueba la Minuta con Proyecto de Decreto de la C\u00e1mara de<br>Senadores del H. Congreso de la Uni\u00f3n, por el que se reforman los<br>art\u00edculos 55 y 91 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos<br>Mexicanos, en materia de edad m\u00ednima para ocupar un cargo p\u00fablico.<\/p>\n\n\n\n<p>Se dispuso remitir el presente Decreto al Congreso de la Uni\u00f3n<br>para efectos de lo consignado en el art\u00edculo 135 de la Constituci\u00f3n<br>Pol\u00edtica de los Estados Unidos Mexicanos, as\u00ed como su env\u00edo al<br>Ejecutivo del Estado para su promulgaci\u00f3n y su publicaci\u00f3n el<br>Peri\u00f3dico Oficial del Gobierno del Estado.<\/p>\n\n\n\n<p>3.- Dictamen de la Comisi\u00f3n de Finanzas con Proyecto de<br>Decreto, por el que se autoriza al Ejecutivo del Estado a<br>desincorporar del dominio p\u00fablico tres bienes inmuebles identificados<br>como: Lote 2 C fracci\u00f3n 1, propiedad del Gobierno del Estado; Lote 2<br>A fracci\u00f3n 1, Lote 2 B fracci\u00f3n 1, ambos propiedad del Organismo<br>P\u00fablico Descentralizado de la Administraci\u00f3n P\u00fablica del Estado,<br>denominado Promotora Inmobiliaria para el Desarrollo Econ\u00f3mico del<br>Estado de Coahuila de Zaragoza (PIDECO), los tres predios ubicados<br>en el Municipio de Monclova, con el fin de enajenarlos a favor de la<br>empresa denominada LIDDELL, S.A. DE C.V., con objeto de llevar a cabo la construcci\u00f3n, instalaci\u00f3n y operaci\u00f3n de una planta dedicada a<br>la fabricaci\u00f3n de remolques y plantas concreteras, el cual generar\u00e1<br>nuevos empleos directos en la regi\u00f3n.<\/p>\n\n\n\n<p>4.- Dictamen de la Comisi\u00f3n de Finanzas con Proyecto de Decreto<br>por el que se autoriza al Organismo P\u00fablico Descentralizado de la<br>Administraci\u00f3n P\u00fablica del Estado, denominado Promotora Inmobiliaria<br>para el Desarrollo Econ\u00f3mico de Coahuila (PIDECO), para que<br>desincorpore del dominio p\u00fablico un inmueble de su propiedad<br>identificado como el Lote 2 B Fracci\u00f3n 2, ubicado en el Ejido San Juan<br>Bautista en el Municipio de Monclova, con el fin de enajenarlo con<br>reserva de dominio a favor de la empresa denominada \u201cGrupo<br>Metelmex, S.A. de C.V.\u201d , con objeto de que se destine \u00fanica y<br>exclusivamente para la construcci\u00f3n, instalaci\u00f3n y operaci\u00f3n de una<br>planta dedicada a la fabricaci\u00f3n estructural e instalaci\u00f3n industrial, en<br>el Municipio de Monclova.<\/p>\n\n\n\n<p>5.- Dictamen con Punto de Acuerdo de la Comisi\u00f3n de Asuntos<br>Municipales y Zonas Metropolitanas, para que se env\u00ede exhorto a los<br>38 Municipios del Estado, para crear programas de apoyo, ayuda y<br>concientizaci\u00f3n para las personas con discapacidad visual.<\/p>\n\n\n\n<p>6.- Dictamen con Punto de Acuerdo de la Comisi\u00f3n de Asuntos<br>Municipales y Zonas Metropolitanas, con el objeto de enviar un atento<br>exhorto a los 38 Ayuntamientos del Estado para que, en medida de<br>sus posibilidades implementen estrategias y acciones de prevenci\u00f3n,<br>con el fin de evitar afectaciones graves por las sequ\u00edas en el Estado,<br>apoyando con programas para el uso y mejora responsable del agua<br>en todo el territorio coahuilense.<\/p>\n\n\n\n<p>7.- Dictamen con Proyecto de Decreto de la Comisi\u00f3n de Asuntos<br>Municipales y Zonas Metropolitanas, con el objeto de exhortar<br>respetuosamente a los 38 Municipios del Estado para que dise\u00f1en e<br>implementen, una estrategia de capacitaci\u00f3n y difusi\u00f3n para la<br>presentaci\u00f3n de la declaraci\u00f3n patrimonial y de intereses de las y los<br>servidores p\u00fablicos adscritos a su cargo, a fin de asegurar el m\u00e1ximo cumplimiento de las disposiciones en materia de transparencia y rendici\u00f3n de cuentas.<\/p>\n\n\n\n<p>8.- Dictamen con Punto de Acuerdo de la Comisi\u00f3n de Asuntos<br>Municipales y Zonas Metropolitanas, para exhortar respetuosamente a<br>los 38 Ayuntamientos del Estado para que, en la medida de sus<br>posibilidades, fortalezcan las acciones de inspecci\u00f3n y vigilancia del<br>servicio de transporte de pasajeros de su competencia, a fin de<br>garantizar el acceso de las personas adultas mayores, personas con<br>discapacidad y con alguna condici\u00f3n. Asimismo, se les exhorta a<br>promover la capacitaci\u00f3n de las y los operadores en materia de<br>movilidad e inclusi\u00f3n.<\/p>\n\n\n\n<p>En esta Sesi\u00f3n, Diputadas y Diputados plantearon diversas<br>proposiciones con Punto de Acuerdo, de las cuales de aprobaron las<br>siguientes:<\/p>\n\n\n\n<p>1.- Proposici\u00f3n con Punto de Acuerdo a fin de solicitar<br>respetuosamente a la Secretar\u00eda de Salud del Estado, que en<br>coordinaci\u00f3n con las diferentes instituciones del sector salud, as\u00ed como<br>la Secretar\u00eda de Educaci\u00f3n, para que en el \u00e1mbito de su competencia,<br>se lleve a cabo una brigada de salud mental en las instituciones<br>p\u00fablicas de educaci\u00f3n primaria, con el objetivo de prevenir el suicidio<br>infantil<\/p>\n\n\n\n<p>2.- Proposici\u00f3n con Punto de Acuerdo para exhortar a la<br>Secretar\u00eda de Salud Federal que informe al Congreso del Estado cu\u00e1l<br>es actualmente la cobertura de medicamentos en el sistema de salud<br>nacional, en cifras reales, incluyendo los tratamientos para el c\u00e1ncer y<br>para enfermedades como la diabetes, la hipertensi\u00f3n y los males<br>renales.<\/p>\n\n\n\n<p>3.- Proposici\u00f3n con Punto de Acuerdo para exhortar<br>respetuosamente a la Secretar\u00eda de Educaci\u00f3n del Estado que incluya<br>en el plan estatal educativo para los niveles de primaria y secundaria,<br>en la materia de formaci\u00f3n c\u00edvica, el estudio de nuestra Constituci\u00f3n<br>Pol\u00edtica de los Estados Unidos Mexicanos y la Constituci\u00f3n Pol\u00edtica del<br>Estado de Coahuila de Zaragoza, con el objeto de incentivar la incorporaci\u00f3n de un mayor n\u00famero de coahuilenses, en un futuro, a una ciudadan\u00eda participativa, informada, comprometida, responsable y<br>productiva.<\/p>\n\n\n\n<p>4.- Proposici\u00f3n con Punto de Acuerdo con el prop\u00f3sito de pedir de<br>manera respetuosa al Ayuntamiento de Saltillo que a trav\u00e9s de sus<br>direcciones de ecolog\u00eda, medio ambiente y espacios urbanos, para<br>que en el \u00e1mbito de sus atribuciones y con respeto a su autonom\u00eda, se<br>investigue y en su caso se sancione la perdida de ejemplares del<br>perico monje argentino, que habitaban en la zona de la plaza Morelos,<br>por la poda de palmeras.<\/p>\n\n\n\n<p>5.- Proposici\u00f3n con Punto de Acuerdo para exhortar a la Fiscal\u00eda<br>General del Estado a fin de que investigue con extrema diligencia y<br>cuidado el reciente caso de doble feminicidio en la Colonia Escorial en<br>Ramos Arizpe; y, al Municipio de Ramos Arizpe, para que eval\u00fae sus<br>acciones a favor de las mujeres.<\/p>\n\n\n\n<p>6.- Proposici\u00f3n con Punto de Acuerdo con objeto de exhortar a<br>los tres \u00f3rdenes de gobierno para que, a trav\u00e9s de sus dependencias<br>competentes, colaboren para dignificar el espacio educativo de la<br>escuela de educaci\u00f3n primaria sin nombre, ubicada en la Calle Pino<br>Blanco, de la Colonia Parajes de los Pinos, en la Ciudad de Ramos<br>Arizpe.<\/p>\n\n\n\n<p>7.- Proposici\u00f3n con Punto de Acuerdo con el prop\u00f3sito de solicitar<br>a la Comisi\u00f3n Estatal de Derechos Humanos que se instalen m\u00f3dulos<br>de atenci\u00f3n para migrantes en las ciudades fronterizas de Acu\u00f1a y<br>Piedras Negras, principalmente, debido al cambio de pol\u00edtica<br>migratoria en Estados Unidos.<\/p>\n\n\n\n<p>Finalmente, Diputadas y Diputados presentaron diversos<br>pronunciamientos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Diputadas y los Diputados de la Sexag\u00e9sima SegundaLegislatura del Congreso del Estado de Coahuila de Zaragoza,llevaron a efecto hoy la D\u00e9cima Primera Sesi\u00f3n del Primer PeriodoOrdinario, correspondiente al Tercer A\u00f1o de Ejercicio Constitucional,en la cual se aprob\u00f3 la propuesta de la Junta de Gobierno, relativa a lamodificaci\u00f3n de la integraci\u00f3n de las Comisiones DictaminadorasPermanentes y Comit\u00e9s, de la LXII Legislatura Local. En esta Sesi\u00f3n, Diputadas y Diputados plantearon las&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,21],"tags":[],"class_list":["post-15225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-congreso-del-estado","wpcat-5-id","wpcat-21-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=15225"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15225\/revisions"}],"predecessor-version":[{"id":15227,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15225\/revisions\/15227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/15226"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=15225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=15225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=15225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}