{"id":15738,"date":"2023-06-14T19:11:35","date_gmt":"2023-06-15T01:11:35","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=15738"},"modified":"2023-06-14T19:11:36","modified_gmt":"2023-06-15T01:11:36","slug":"acuerdan-acciones-secretarias-de-educacion-y-salud-en-prevencion-para-los-alumnos-de-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/06\/14\/acuerdan-acciones-secretarias-de-educacion-y-salud-en-prevencion-para-los-alumnos-de-coahuila\/","title":{"rendered":"ACUERDAN ACCIONES SECRETAR\u00cdAS DE EDUCACI\u00d3N Y SALUD, EN PREVENCI\u00d3N PARA LOS ALUMNOS DE COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 14 de Junio de 2023.- La Secretar\u00eda de Educaci\u00f3n del Estado informa que, en atenci\u00f3n a las recomendaciones emitidas por la Secretar\u00eda de Salud ante las condiciones climatol\u00f3gicas que se pronostican en el norte del Pa\u00eds y que afectan a Coahuila, se realizar\u00e1n las siguientes acciones:<\/p>\n\n\n\n<p><strong>CAMBIO EN HORARIOS DE CLASES<\/strong><\/p>\n\n\n\n<p>+ En los servicios educativos en el nivel de Educaci\u00f3n B\u00e1sica se eliminar\u00e1n los recreos o recesos y actividades al aire libre, lo que har\u00e1 posible recorrer los horarios escolares evitando la exposici\u00f3n de los alumnos.&nbsp;<\/p>\n\n\n\n<p>PREESCOLAR Turno Matutino de las 09:00 a las 11:00 horas.<\/p>\n\n\n\n<p>Turno Vespertino las 14:30 a las 16:30 horas:<\/p>\n\n\n\n<p>PRIMARIA Turno Matutino de las 08:00 a las 11:00 horas.<\/p>\n\n\n\n<p>Turno Vespertino de las 13:30 a&nbsp;&nbsp;&nbsp;16:30 horas.<\/p>\n\n\n\n<p>&nbsp;\u00c1rea rural de las 08:00 a las 12:00 horas.<\/p>\n\n\n\n<p>SECUNDARIA Turno Matutino de las 07:00 a las 11:00 horas, y a partir de esta hora, ser\u00e1 a distancia.<\/p>\n\n\n\n<p>Turno Vespertino de las 13:30 a las 15:00 horas a distancia, y de las 15:30 a las 19:00 horas presencial.<\/p>\n\n\n\n<p>Los padres de familia de los ni\u00f1os, ni\u00f1as o adolescentes que cuenten con alguna susceptibilidad por enfermedad, tendr\u00e1n la facultad de decidir si los env\u00edan a clase o no.<\/p>\n\n\n\n<p>RECOMENDACIONES de la Secretar\u00eda de Salud y la Subsecretar\u00eda de Protecci\u00f3n Civil:<\/p>\n\n\n\n<p>a) Mantenerse permanentemente hidratados;<\/p>\n\n\n\n<p>b) Utilizar bloqueador;<\/p>\n\n\n\n<p>c) Uso de prenda u objeto que cubra la cabeza de los rayos del sol;<\/p>\n\n\n\n<p>d) Usar ropa ligera y preferentemente clara (considerar flexibilidad en el uso del uniforme);<\/p>\n\n\n\n<p>e) Extremar precauciones con alimentos (evitar los de f\u00e1cil descomposici\u00f3n por el calor); y<\/p>\n\n\n\n<p>f) Poner especial atenci\u00f3n en los alimentos que se expenden por vendedores ambulantes afuera de las instituciones educativas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Por lo que respecta a los docentes, estos deber\u00e1n cumplir con la jornada laboral de manera regular, indic\u00e1ndoles que en las horas posteriores a los horarios antes descritos para alumnos, deber\u00e1n realizar descarga administrativa y no abandonar el plantel.<\/p>\n\n\n\n<p>Resulta indispensable que los docentes y el resto del personal de los planteles est\u00e9n atentos al comportamiento y estado f\u00edsico de los ni\u00f1os, ni\u00f1as y adolescentes.<\/p>\n\n\n\n<p>Las presentes disposiciones son aplicables del 14 al 23 de junio del presente, o bien si la situaci\u00f3n climatolog\u00eda contin\u00faa, quedando a consideraci\u00f3n de los padres de familia enviarlos o no a la escuela, sin que esto repercuta en su puntualidad y asistencia.<\/p>\n\n\n\n<p>En tanto que en el nivel de Educaci\u00f3n Media Superior&nbsp;&nbsp;COBAC, CecyTe, CONALEP, y&nbsp;&nbsp;Universidades Polit\u00e9cnicas y Tecnol\u00f3gicas, asi como las Escuelas Normales contin\u00faan con sus actividades de forma regular, conforme a su calendario<\/p>\n\n\n\n<p><strong>SI TE DROGAS, TE DA\u00d1AS<\/strong><\/p>\n\n\n\n<p>En cuanto a la jornada de actividades programadas para el 17 de junio como cierre de la estrategia federal \u201cSi te drogas, te da\u00f1as\u201d, se realzar\u00e1n en horario de las 07:00 a las 10:00 horas, y participan en ellas de manera voluntaria alumnos de secundaria y de bachillerato.<\/p>\n\n\n\n<p><strong>JUEGOS DEPORTIVOS Y CULTURALES<\/strong><\/p>\n\n\n\n<p>Se informa que los Juegos Deportivos y Culturales de Educaci\u00f3n B\u00e1sica programados a realizarse la pr\u00f3xima semana se cambian para los d\u00edas 27 y 28 de junio.<\/p>\n\n\n\n<p>De esta manera, la Secretar\u00eda de Educaci\u00f3n de Coahuila protege le integridad de los estudiantes para concluir el ciclo escolar en las mejores circunstancias a las fechas establecidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 14 de Junio de 2023.- La Secretar\u00eda de Educaci\u00f3n del Estado informa que, en atenci\u00f3n a las recomendaciones emitidas por la Secretar\u00eda de Salud ante las condiciones climatol\u00f3gicas que se pronostican en el norte del Pa\u00eds y que afectan a Coahuila, se realizar\u00e1n las siguientes acciones: CAMBIO EN HORARIOS DE CLASES + En los servicios educativos en el nivel de Educaci\u00f3n B\u00e1sica se eliminar\u00e1n los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,9,15,14],"tags":[],"class_list":["post-15738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-educacion","category-gobierno-de-coahuila","category-salud","wpcat-5-id","wpcat-9-id","wpcat-15-id","wpcat-14-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=15738"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15738\/revisions"}],"predecessor-version":[{"id":15740,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15738\/revisions\/15740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/15739"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=15738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=15738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=15738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}