{"id":15750,"date":"2023-06-15T18:55:12","date_gmt":"2023-06-16T00:55:12","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=15750"},"modified":"2023-06-15T18:55:13","modified_gmt":"2023-06-16T00:55:13","slug":"convoca-uadec-a-sus-estudiantes-a-participar-en-la-presea-lobo-2023","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/06\/15\/convoca-uadec-a-sus-estudiantes-a-participar-en-la-presea-lobo-2023\/","title":{"rendered":"Convoca UAdeC a sus Estudiantes a Participar en la Presea Lobo 2023."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 15 de junio de 2023. La Universidad Aut\u00f3noma de Coahuila<br>a trav\u00e9s de la Coordinaci\u00f3n de Unidad Saltillo, convoca a los alumnos de<br>Escuelas, Facultades e Institutos a postularse a la Presea Lobo 2023, galard\u00f3n<br>que reconoce a estudiantes destacados en diversos \u00e1mbitos.<\/p>\n\n\n\n<p>Podr\u00e1n participar las y los alumnos que se consideren con m\u00e9ritos en las<br>siguientes categor\u00edas: Actividades Acad\u00e9micas, Art\u00edsticas, Innovaci\u00f3n,<br>Compromiso Social, Protecci\u00f3n al Ambiente, Capacidades Diferentes e Integraci\u00f3n<br>Social, Liderazgo, Deportivas y Compromiso Institucional; se otorgar\u00e1 un premio<br>por categor\u00eda para cada uno de los planteles participantes de la Unidad Saltillo.<\/p>\n\n\n\n<p>Los candidatos deber\u00e1n estar inscritos desde el a\u00f1o 2022 y presentar sus<br>evidencias de acciones u obras hasta diciembre de ese a\u00f1o; ser propuestos o<br>aprobados por el Consejo Directivo de su plantel; no podr\u00e1n participar quienes<br>obtuvieron premio en alguna de las nueve categor\u00edas mencionadas.<\/p>\n\n\n\n<p>El registro de la candidatura debe solicitarse por cada Consejo Directivo ante la<br>CUS, a trav\u00e9s de una carta de propuesta emitida por dicho \u00f3rgano; la<br>documentaci\u00f3n a presentar es portada que incluya el nombre completo del<br>postulante, direcci\u00f3n, tel\u00e9fono, correo electr\u00f3nico, escuela a la que pertenece y<br>categor\u00eda para la que se le propone.<\/p>\n\n\n\n<p>Adem\u00e1s de una carta de aceptaci\u00f3n a participar y recibir personalmente el premio<br>por parte del alumno, copia de la credencial del estudiante o constancia por parte<br>de la escuela que avale su vigencia como alumno durante 2022 y curr\u00edculum<br>actualizado con informaci\u00f3n que respalde su candidatura a la Presea.<\/p>\n\n\n\n<p>Las escuelas, institutos y facultades, deber\u00e1n realizar el registro y la carga de<br>archivos en <a href=\"https:\/\/forms.office.com\/r\/ztpSevSMbd\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.office.com\/r\/ztpSevSMbd<\/a>, un registro y un archivo PDF<br>por candidato; la fecha l\u00edmite para la recepci\u00f3n de propuestas ser\u00e1 el viernes 11<br>de agosto de 2023 a las 23:59 horas.<\/p>\n\n\n\n<p>El Comit\u00e9 Evaluador de la Unidad se conformar\u00e1 por personas de amplia<br>trayectoria universitaria y con experiencia en cada una de las \u00e1reas, la<br>documentaci\u00f3n que se remita al Comit\u00e9 Evaluador ser\u00e1 manejada en forma<br>confidencial, el dictamen emitido por el Comit\u00e9 Evaluador ser\u00e1 inapelable y el<br>comit\u00e9 tendr\u00e1 la facultad de declarar desierta cualquiera de sus categor\u00edas,<br>cuando as\u00ed lo considere conveniente.<\/p>\n\n\n\n<p>Se premiar\u00e1 con la Presea Lobo y diploma firmado por el Rector de la UAdeC y el<br>Coordinador de la Unidad, a la mejor propuesta por escuela que bajo los criterios<br>de evaluaci\u00f3n, el jurado lo determine como merecedor del premio; para facultades<br>con posgrado, en las categor\u00edas de actividades acad\u00e9micas y de innovaci\u00f3n, se<br>podr\u00e1 premiar hasta dos alumnos, uno de licenciatura y uno de posgrado.<\/p>\n\n\n\n<p>La Coordinaci\u00f3n de Unidad informar\u00e1 oportunamente el resultado a los<br>participantes y a las escuelas, as\u00ed como el lugar, fecha y hora de la ceremonia; la<br>informaci\u00f3n sobre la ceremonia ser\u00e1 publicada en la p\u00e1gina <a href=\"http:\/\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.cus.uadec.mx<\/a> y<br>en Facebook @Coordinaci\u00f3nUnidadSaltillo.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n, consultar la convocatoria completa en la p\u00e1gina<br><a href=\"http:\/\/www.cus.uadec.mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.cus.uadec.mx\/<\/a>, comunicarse directamente con la Mtra. Hayd\u00e9e de la<br>Garza Rodr\u00edguez al correo haydee.garza@uadec.edu.mx y con la Mtra. Martha<br>Magdalena Adame Moncada madame@uadec.edu.mx o llamar al Departamento<br>de Asuntos Acad\u00e9micos de la CUS al tel\u00e9fono (844) 414 99 36 Ext. 107 y 117.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 15 de junio de 2023. La Universidad Aut\u00f3noma de Coahuilaa trav\u00e9s de la Coordinaci\u00f3n de Unidad Saltillo, convoca a los alumnos deEscuelas, Facultades e Institutos a postularse a la Presea Lobo 2023, galard\u00f3nque reconoce a estudiantes destacados en diversos \u00e1mbitos. Podr\u00e1n participar las y los alumnos que se consideren con m\u00e9ritos en lassiguientes categor\u00edas: Actividades Acad\u00e9micas, Art\u00edsticas, Innovaci\u00f3n,Compromiso Social, Protecci\u00f3n al Ambiente, Capacidades Diferentes e Integraci\u00f3nSocial, Liderazgo, Deportivas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":15751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-15750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=15750"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15750\/revisions"}],"predecessor-version":[{"id":15752,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/15750\/revisions\/15752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/15751"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=15750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=15750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=15750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}