{"id":16003,"date":"2023-06-29T18:13:24","date_gmt":"2023-06-30T00:13:24","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=16003"},"modified":"2023-06-29T18:13:24","modified_gmt":"2023-06-30T00:13:24","slug":"confirman-noveno-deceso-por-golpe-de-calor-en-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/06\/29\/confirman-noveno-deceso-por-golpe-de-calor-en-coahuila\/","title":{"rendered":"CONFIRMAN NOVENO DECESO POR GOLPE DE CALOR EN COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 29 de Junio del 2023.- La Secretar\u00eda de Salud de Coahuila confirm\u00f3 el noveno deceso por golpe de calor en la entidad, correspondiente al Municipio de Piedras Negras, de un hombre de 76 a\u00f1os.\u00a0<\/p>\n\n\n\n<p>Roberto Bernal G\u00f3mez, Secretario de Salud del Estado, detall\u00f3 que los nueve fallecimientos se distribuyen de la siguiente manera: 6 en Monclova, 2 en Piedras Negras y una Acu\u00f1a.<\/p>\n\n\n\n<p>La Secretar\u00eda de Salud reporta hasta el momento un total de 109 golpes de calor en la entidad, que se han detectado en los municipios de:<\/p>\n\n\n\n<p>23 Monclova<\/p>\n\n\n\n<p>19 Piedras Negras&nbsp;<\/p>\n\n\n\n<p>18 Acu\u00f1a<\/p>\n\n\n\n<p>10 Cuatro Ci\u00e9negas<\/p>\n\n\n\n<p>10 Saltillo&nbsp;<\/p>\n\n\n\n<p>5 Frontera<\/p>\n\n\n\n<p>4 Francisco I. Madero&nbsp;<\/p>\n\n\n\n<p>3 Allende<\/p>\n\n\n\n<p>3 Sacramento<\/p>\n\n\n\n<p>2 M\u00fazquiz&nbsp;<\/p>\n\n\n\n<p>2 Ocampo<\/p>\n\n\n\n<p>2 Torre\u00f3n<\/p>\n\n\n\n<p>1 Sabinas<\/p>\n\n\n\n<p>1 Nava<\/p>\n\n\n\n<p>1 San Pedro &nbsp;<\/p>\n\n\n\n<p>1 Progreso&nbsp;<\/p>\n\n\n\n<p>1 Casta\u00f1os<\/p>\n\n\n\n<p>1 Escobedo<\/p>\n\n\n\n<p>1 San Buenaventura&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, se dio a conocer que existen 7 pacientes hospitalizados: 1 Acu\u00f1a, 4 Piedras Negras, 1 San Buenaventura y 1 Monclova.<\/p>\n\n\n\n<p>Bernal G\u00f3mez, apunt\u00f3 que ante la ola de calor es necesario mantener hidratados especialmente a los menores y a los adultos mayores, sectores de la poblaci\u00f3n con mayor riesgo.<\/p>\n\n\n\n<p>El funcionario recomend\u00f3 no exponerse por tiempos prolongados a los rayos del sol, especialmente de las 11:00 a las 17:00 horas. &nbsp;<\/p>\n\n\n\n<p>\u201cAdem\u00e1s, es indispensable mantener la hidrataci\u00f3n cada dos horas\u201d, declar\u00f3.<\/p>\n\n\n\n<p>Manifest\u00f3 que las unidades de salud cuentan con sobres de vida suero oral para las familias que as\u00ed lo requieran. &nbsp;<\/p>\n\n\n\n<p>Record\u00f3 que los principales s\u00edntomas del golpe de calor son: Piel roja, caliente y seca, temperatura, respiraci\u00f3n y frecuencia cardiaca acelerada, dolor de cabeza, alteraci\u00f3n del estado mental, mareos, v\u00e9rtigos, confusi\u00f3n o p\u00e9rdida del conocimiento.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 29 de Junio del 2023.- La Secretar\u00eda de Salud de Coahuila confirm\u00f3 el noveno deceso por golpe de calor en la entidad, correspondiente al Municipio de Piedras Negras, de un hombre de 76 a\u00f1os.\u00a0 Roberto Bernal G\u00f3mez, Secretario de Salud del Estado, detall\u00f3 que los nueve fallecimientos se distribuyen de la siguiente manera: 6 en Monclova, 2 en Piedras Negras y una Acu\u00f1a. La Secretar\u00eda&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5,15,14],"tags":[],"class_list":["post-16003","post","type-post","status-publish","format-standard","hentry","category-clima","category-coahuila","category-gobierno-de-coahuila","category-salud","wpcat-27-id","wpcat-5-id","wpcat-15-id","wpcat-14-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=16003"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16003\/revisions"}],"predecessor-version":[{"id":16004,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16003\/revisions\/16004"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=16003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=16003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=16003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}