{"id":16430,"date":"2023-07-27T19:19:42","date_gmt":"2023-07-28T01:19:42","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=16430"},"modified":"2023-07-27T19:19:43","modified_gmt":"2023-07-28T01:19:43","slug":"coahuila-mantiene-el-control-de-la-seguridad-mars","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/07\/27\/coahuila-mantiene-el-control-de-la-seguridad-mars\/","title":{"rendered":"COAHUILA MANTIENE EL CONTROL DE LA SEGURIDAD: MARS"},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>Encabeza gobernador Miguel Riquelme homenaje p\u00f3stumo a oficial de la Polic\u00eda Estatal ca\u00eddo en enfrentamiento con criminales<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 27 de julio de 2023.- Al encabezar el homenaje p\u00f3stumo del polic\u00eda estatal Giovani Jahaziel, quien perdi\u00f3 la vida en enfrentamiento con civiles armados, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds expres\u00f3 que Coahuila mantiene el control de la seguridad y que prevalecer\u00e1n los operativos y acciones interinstitucionales en contra del crimen para evitar el ingreso de grupos delincuenciales a nuestro territorio.<\/p>\n\n\n\n<p>Junto al titular de la Junta de Gobierno del Congreso del Estado, diputado Eduardo Olmos Castro; del Alcalde de Saltillo, Jos\u00e9 Mar\u00eda Fraustro Siller; del Secretario de Gobierno, Fernando de las Fuentes Hern\u00e1ndez, y de la magistrada Mar\u00eda Eugenia Galindo, el Mandatario estatal transmiti\u00f3 sus condolencias a familiares, amigos cercanos y compa\u00f1eros, por conducto de su esposa, Diana.<\/p>\n\n\n\n<p>En su intervenci\u00f3n ante los jefes castrenses, generales Eufemio Ibarra Flores y Guillermo Arellano, Comandantes de la XI Regi\u00f3n Militar y de la VI Zona Militar, respectivamente, el gobernador Riquelme Sol\u00eds reiter\u00f3 que las bandas de criminales no ingresar\u00e1n a Coahuila porque aqu\u00ed enfrentar\u00e1n, las veces que sea necesario, a elementos leales, valerosos y comprometidos con la seguridad de la poblaci\u00f3n.<\/p>\n\n\n\n<p>Lament\u00f3 que una vez m\u00e1s Coahuila pierde a un valioso elemento.<\/p>\n\n\n\n<p>\u201cEn estos momentos dif\u00edciles ratificamos la unidad y que el pueblo y el Gobierno de Coahuila respaldamos a&nbsp; quienes est\u00e1n a cargo de la salvaguarda del patrimonio y la&nbsp; vida de nuestras familias\u201d, se\u00f1al\u00f3 el Gobernador.<\/p>\n\n\n\n<p>\u201cHoy honramos el patriotismo y el sacrificio de un polic\u00eda ejemplar\u201d.<\/p>\n\n\n\n<p>Al se\u00f1alar que en su Administraci\u00f3n la seguridad prevaleci\u00f3 como la principal prioridad, dijo que, sin bajar la guardia, se atendieron puntualmente todos los frentes y factores que inciden directamente en las condiciones de tranquilidad, legalidad y orden p\u00fablico.<\/p>\n\n\n\n<p>\u201cCoahuila es un Estado seguro gracias al trabajo sistem\u00e1tico y permanente que llevan a cabo la sociedad y el Gobierno\u201d, destac\u00f3.<\/p>\n\n\n\n<p>El Mandatario estatal rememor\u00f3 que en el 2012 Coahuila fue considerada una de las entidades m\u00e1s violentas del Pa\u00eds y la quinta m\u00e1s peligrosa del mundo.<\/p>\n\n\n\n<p>Sin embargo, ahora las condiciones son diametralmente opuestas: \u201cHoy, las cosas son muy distintas: se recobr\u00f3 la paz con l\u00edneas de acci\u00f3n, precisas y permanentes, con coordinaci\u00f3n interinstitucional, infraestructura militar capacitaci\u00f3n y mejor marco legal\u201d.<\/p>\n\n\n\n<p>Miguel Riquelme destac\u00f3 la coordinaci\u00f3n permanente que se tiene con el Ej\u00e9rcito Mexicano y la Guardia Nacional, que es el pilar de las estrategias de Coahuila en materia de seguridad.<\/p>\n\n\n\n<p>Sin distingo, se trabaja con los 28 Ayuntamientos. Adem\u00e1s, se reagruparon y especializaron los diferentes cuerpos policiales de la entidad de acuerdo a su estricta competencia y funciones, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Luego record\u00f3 que el Gobierno del Estado dot\u00f3 de m\u00e1s equipo vehicular, mejor equipamiento, armamento de alto calibre y de un sistema de video-inteligencia de clase mundial, a todas las corporaciones en su permanente lucha contra el crimen.<\/p>\n\n\n\n<p>\u201cParalelamente se mantuvieron cerradas las fuentes de financiamiento del crimen. Impedimos la operaci\u00f3n de los negocios de giros negros.<\/p>\n\n\n\n<p>\u201cHay estricto control en la venta de alcohol y reforzamos las estrategias para incautar estupefacientes\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>Con trabajo colegiado y mutua colaboraci\u00f3n entre el Gobierno con los diversos sectores sociales, se gener\u00f3 la sinergia que sostiene los pilares del desarrollo y el crecimiento, indic\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, Riquelme Sol\u00eds sostuvo que la seguridad es el factor primordial para mantener en ascenso los indicadores del bienestar y el progreso, por lo que Coahuila se mantiene como gran atractivo para las inversiones.<\/p>\n\n\n\n<p>\u201cNo tan s\u00f3lo por su ubicaci\u00f3n geogr\u00e1fica estrat\u00e9gica, sino tambi\u00e9n por sus logros y avances, es que intereses ajenos y factores externos pretenden venir a robar lo que mucho trabajo, esfuerzo y recursos, nos han costado a las y a los coahuilenses\u201d, apunt\u00f3.<\/p>\n\n\n\n<p>Luego, cit\u00f3 que desde el inicio de su Administraci\u00f3n las corporaciones de seguridad p\u00fablica han enfrentado y repelido sucesivos intentos de civiles armados por entrar a Coahuila.<\/p>\n\n\n\n<p>\u201cEl cerco de protecci\u00f3n de Coahuila es un muro infranqueable. La ciudadan\u00eda participa con la denuncia y se\u00f1alamiento oportuno de sujetos armados y de veh\u00edculos sospechosos\u201d, dijo.<\/p>\n\n\n\n<p>Por otra parte, Miguel Riquelme hizo un recuento de los combates que llevan las fuerzas del orden en contra de la delincuencia:<\/p>\n\n\n\n<p>\u201cEntre 2018 y este a\u00f1o se tienen registrados m\u00e1s de 60 enfrentamientos\u2026 con 13 polic\u00edas ca\u00eddos en el cumplimiento del deber y m\u00e1s de 40 elementos heridos\u201d.<\/p>\n\n\n\n<p>\u2018LA FUERZA Y EL VALOR SON M\u00c1S GRANDES QUE TODO ENEMIGO DE LA LEY\u2019<\/p>\n\n\n\n<p>En ese sentido, el gobernador Miguel Riquelme sostuvo que no cabe duda que la fuerza y el valor de nuestros polic\u00edas es mucho m\u00e1s grande que todo enemigo de la Ley.<\/p>\n\n\n\n<p>Tan s\u00f3lo en la \u00faltima semana, se registraron 7 ataques de civiles armados que infructuosamente trataron de ingresar a nuestro territorio por la Carretera Federal 2, conocida como La Ribere\u00f1a, al norte del Estado, agreg\u00f3.<\/p>\n\n\n\n<p>\u201cEn estos embates nuestros polic\u00edas han demostrado una vez m\u00e1s que est\u00e1n hechos del esp\u00edritu y el coraz\u00f3n de los grandes h\u00e9roes de Coahuila y de M\u00e9xico\u201d, asent\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, detall\u00f3 los acontecimientos de los \u00faltimos d\u00edas que dejaron dos oficiales sin vida y seis polic\u00edas m\u00e1s heridos en enfrentamientos en aquella zona.<\/p>\n\n\n\n<p>En el caso del polic\u00eda Giovvani Jahaziel, se\u00f1al\u00f3, desde hace 10 a\u00f1os pertenec\u00eda al Agrupamiento de la Polic\u00eda de Acci\u00f3n y Reacci\u00f3n (PAR), donde destac\u00f3 por su valor, honor, lealtad, patriotismo, empe\u00f1o y compromiso en el Programa de Equipamiento y Profesionalizaci\u00f3n.<\/p>\n\n\n\n<p>Particip\u00f3, con gran valent\u00eda, en los enfrentamientos derivados del ataque al Municipio de Villa Uni\u00f3n en el a\u00f1o 2019, donde result\u00f3 herido, record\u00f3 el Mandatario coahuilense.<\/p>\n\n\n\n<p>Dijo que el sacrificio del extinto oficial infunde mayor fuerza, \u00edmpetu y determinaci\u00f3n para seguir la lucha sin descanso contra los transgresores de la Ley y los enemigos de la sociedad.<\/p>\n\n\n\n<p>Resalt\u00f3 que permanecer\u00e1 el filtro de seguridad en aquella zona de la entidad, con apoyo a\u00e9reo, adem\u00e1s de mantener estrecha coordinaci\u00f3n con las autoridades castrenses de Coahuila, Nuevo Le\u00f3n y Tamaulipas, para evitar el paso de grupos armados.<\/p>\n\n\n\n<p>\u201cCoahuila est\u00e1 unido, mantiene el control de la seguridad y no la vamos a perder. Toda la sociedad sabe perfectamente lo que hemos logrado.<\/p>\n\n\n\n<p>\u201cContamos con los mejores polic\u00edas, los m\u00e1s capacitados y de lealtad a toda prueba, por eso los respaldamos y apoyamos firmemente en su labor\u201d, indic\u00f3.<\/p>\n\n\n\n<p>Una vez m\u00e1s reiter\u00f3 su firme disposici\u00f3n de mantener sin descanso la batalla en contra de grupos delincuenciales que pretenden ingresar a Coahuila.<\/p>\n\n\n\n<p>Previamente, el gobernador Miguel Riquelme y el titular de la Junta de Gobierno del Congreso del Estado, diputado Eduardo Olmos Castro, encabezaron una Guardia de Honor ante el f\u00e9retro del oficial ca\u00eddo.<\/p>\n\n\n\n<p>Mientras que elementos del agrupamiento PAR dispararon una salva, y luego las autoridades, junto a la familia del extinto servidor p\u00fablico, encabezada por su esposa Diana, colocaron la placa con el nombre de Giovvani Jahaziel en el Muro de Honor y Gloria de la Corporaci\u00f3n.<\/p>\n\n\n\n<p>Por su parte, el Secretario de Gobierno, Fernando de las Fuentes Hern\u00e1ndez, resalt\u00f3 la valent\u00eda, el arrojo y determinaci\u00f3n del oficial, al momento que extern\u00f3 sus condolencias a los seres queridos del elemento de la Polic\u00eda Estatal ca\u00eddo en el cumplimiento de su&nbsp;deber.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Encabeza gobernador Miguel Riquelme homenaje p\u00f3stumo a oficial de la Polic\u00eda Estatal ca\u00eddo en enfrentamiento con criminales Saltillo, Coahuila de Zaragoza; a 27 de julio de 2023.- Al encabezar el homenaje p\u00f3stumo del polic\u00eda estatal Giovani Jahaziel, quien perdi\u00f3 la vida en enfrentamiento con civiles armados, el gobernador Miguel \u00c1ngel Riquelme Sol\u00eds expres\u00f3 que Coahuila mantiene el control de la seguridad y que prevalecer\u00e1n los operativos y acciones interinstitucionales en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":16431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,24],"tags":[],"class_list":["post-16430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-seguridad","wpcat-5-id","wpcat-15-id","wpcat-24-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=16430"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16430\/revisions"}],"predecessor-version":[{"id":16432,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/16430\/revisions\/16432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/16431"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=16430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=16430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=16430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}