{"id":17162,"date":"2023-09-17T23:24:44","date_gmt":"2023-09-18T05:24:44","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=17162"},"modified":"2023-09-17T23:24:45","modified_gmt":"2023-09-18T05:24:45","slug":"inicia-festival-de-la-manzana-en-arteaga","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/09\/17\/inicia-festival-de-la-manzana-en-arteaga\/","title":{"rendered":"INICIA FESTIVAL DE LA MANZANA, EN ARTEAGA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 15 de Septiembre de 2023.- Ayer por la tarde se inaugur\u00f3 el Festival de la Manzana en Arteaga, que se lleva a cabo del 14 al 17 de septiembre en la comunidad de San Antonio de las Alazanas, en el que se espera una asistencia de 40 mil personas de municipios de la regi\u00f3n, as\u00ed como de Monterrey, Nuevo Le\u00f3n, y de Dallas, Texas.<\/p>\n\n\n\n<p>La tradicional feria atrae a turistas y visitantes de la Regi\u00f3n Sureste y de otras partes del estado, y genera una importante derrama econ\u00f3mica en restaurantes, unidades de hospedaje y otros servicios, as\u00ed como a artesanos y productores locales.<\/p>\n\n\n\n<p>La inauguraci\u00f3n estuvo a cargo del alcalde Ramiro Dur\u00e1n Garc\u00eda, quien fue acompa\u00f1ado de la legisladora local Edna D\u00e1valos; regidores y funcionarios municipales, y la Directora de Pueblos M\u00e1gicos de SECTUR Coahuila, Melissa Owen.<\/p>\n\n\n\n<p>Tambi\u00e9n hubo una rodada y exhibici\u00f3n de tractores, se presentaron a las candidatas a reinas, se realiz\u00f3 un recorrido por el Pabell\u00f3n Agropecuario, y se cort\u00f3 el m\u00e1s grande pay de manzana de la regi\u00f3n.<\/p>\n\n\n\n<p>En el Teatro del Pueblo de San Antonio de las Alazanas, el grupo \u201cCuellos Rojos\u201d y \u201cLos J\u00faniors\u201d abrieron la cartelera de artistas que se presentar\u00e1n en esta fiesta del Pueblo M\u00e1gico; tambi\u00e9n actuar\u00e1n \u201cKik\u00edn y los Astros\u201d este viernes 15 de septiembre; \u201cLos Herederos de Nuevo Le\u00f3n\u201d, \u201cLa Sombra de Juan Gabriel\u201d y \u201cNorte\u00f1\u00edsimo\u201d, el s\u00e1bado 16, y el domingo 17 la Banda Brava.<\/p>\n\n\n\n<p>Adem\u00e1s hay juegos mec\u00e1nicos, venta de antojitos mexicanos, postres (especialmente pays de manzana), licores, conservas y artesan\u00edas.<\/p>\n\n\n\n<p><strong>SABINAS Y TORRE\u00d3N TAMBI\u00c9N CELEBRAN SUS FERIAS<\/strong><\/p>\n\n\n\n<p>Torre\u00f3n arranc\u00f3 su Feria el pasado 1 de septiembre y concluir\u00e1 el 1 de octubre; cuenta con una serie de atractivos como juegos mec\u00e1nicos, gastronom\u00eda, venta de artesan\u00edas y productos diversos, al igual que tiene atractivos como el Circo Atayde, espect\u00e1culos en el Teatro Mayagoitia y Las Jarras.&nbsp;<\/p>\n\n\n\n<p>En su cartelera musical destacan Bandazo Mundo B\u00e9lico, Natanael Cano, Los Dos Carnales, Conjunto Primavera, Marco Flores de la Jerez y Sonora Tropicana, entre otros.<\/p>\n\n\n\n<p>Mientras que en Sabinas, las Fiestas Grandes comenzaron el 8 de septiembre con la inauguraci\u00f3n de la Feriexpo y culminan este domingo 17. Su cartelera musical: Banda MS, Ed\u00e9n Mu\u00f1oz, M\u00e1quina Norte\u00f1a, Los Herederos de NL, Tropical\u00edsimo Apache, Chicos de Barrio, Tropa Estrella, La Firma, M\u00edster Chivo e Invasores de Nuevo Le\u00f3n.<\/p>\n\n\n\n<p>La realizaci\u00f3n exitosa de las tradicionales ferias en Coahuila es posible gracias al clima de seguridad y paz que impera en todo el estado, resultado del trabajo permanente del Gobierno de Miguel \u00c1ngel Riquelme Sol\u00eds.<\/p>\n\n\n\n<p>Para la Secretaria de Turismo y Desarrollo de Pueblos M\u00e1gicos, Azucena Ramos Ramos, la realizaci\u00f3n de las ferias en todo el territorio estatal en distintas fechas del a\u00f1o representa tradici\u00f3n, historia y sana convivencia familiar: \u201cAtraen turismo y dejan derrama econ\u00f3mica en los distintos municipios y regiones\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 15 de Septiembre de 2023.- Ayer por la tarde se inaugur\u00f3 el Festival de la Manzana en Arteaga, que se lleva a cabo del 14 al 17 de septiembre en la comunidad de San Antonio de las Alazanas, en el que se espera una asistencia de 40 mil personas de municipios de la regi\u00f3n, as\u00ed como de Monterrey, Nuevo Le\u00f3n, y de Dallas, Texas. La&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,34],"tags":[],"class_list":["post-17162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-turismo","wpcat-5-id","wpcat-15-id","wpcat-34-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=17162"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17162\/revisions"}],"predecessor-version":[{"id":17164,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17162\/revisions\/17164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/17163"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=17162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=17162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=17162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}