{"id":17617,"date":"2023-10-17T18:13:40","date_gmt":"2023-10-18T00:13:40","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=17617"},"modified":"2023-10-17T18:13:41","modified_gmt":"2023-10-18T00:13:41","slug":"presentaran-conferencia-el-hijo-desobediente-tin-tan-y-la-cultura-del-pachuco","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/10\/17\/presentaran-conferencia-el-hijo-desobediente-tin-tan-y-la-cultura-del-pachuco\/","title":{"rendered":"Presentar\u00e1n conferencia \u201cEl hijo desobediente, Tin Tan y la cultura del pachuco\u201d."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 17 de octubre de 2023.<\/p>\n\n\n\n<p>El Archivo Municipal de Torre\u00f3n presentar\u00e1 la conferencia \u201cEl hijo desobediente,<br>Tin Tan y la cultura del pachuco\u201d, a cargo del cronista urbano Alfredo Rojas<br>Hern\u00e1ndez, el pr\u00f3ximo jueves 19 de octubre a las 19:00 horas.<\/p>\n\n\n\n<p>Cinthia Gaspar Montero, directora del Archivo Municipal, coment\u00f3 que la invitaci\u00f3n<br>es abierta al p\u00fablico general y dio a conocer que el evento se llevar\u00e1 a cabo en las<br>instalaciones de la dependencia, ubicadas en calle Acu\u00f1a 140 sur.<\/p>\n\n\n\n<p>Por su parte Rojas Hern\u00e1ndez coment\u00f3 que la charla abordar\u00e1 distintos aspectos<br>de un personaje que para muchos fue s\u00f3lo un c\u00f3mico disonante y para otros un<br>\u00edcono nacional: Germ\u00e1n Vald\u00e9s, mejor conocido como Tin Tan, quien se\u00f1al\u00f3 fue<br>injustamente eclipsado por la intelectualidad de la \u00e9poca, el oficialismo y una<br>industria que acab\u00f3 en decadencia.<\/p>\n\n\n\n<p>\u201cEl Pachuco de oro\u201d se inmortaliz\u00f3 a s\u00ed mismo a trav\u00e9s de la cultura popular<br>mexicana, silenciada por el estridente \u00e1nimo de progreso, al apropiarse de sus<br>narrativas, sus arquetipos, sus infortunios y sus voces.<\/p>\n\n\n\n<p>En la actualidad, Tin Tan es una figura totalmente atemporal, posmoderna y<br>contempor\u00e1nea porque contin\u00faa encarnando al antih\u00e9roe, a esa parte de la<br>sociedad que persiste al margen y, por otro lado, a ese M\u00e9xico que se anticip\u00f3 a la<br>historia: transcultural, multi\u00e9tnico y pluricultural.<\/p>\n\n\n\n<p>En ese sentido, todo gran creador est\u00e1 vinculado siempre a otros artistas. Por lo<br>tanto, Tin Tan es un punto de referencia que nos obliga a revisar globalmente a<br>c\u00f3micos, m\u00fasicos y creadores, reflejo del estrepitoso virtuosismo de una era<br>disruptiva y en constante transici\u00f3n.<\/p>\n\n\n\n<p>Irreverente y camale\u00f3nico, Tin Tan entendi\u00f3 la relevancia de modelar personajes<br>populares que hablaban de otra identidad, no la oficial, ni la nacionalista. Sino la<br>compleja, del mestizaje y del sincretismo cultural.<\/p>\n\n\n\n<p>Con el tiempo, incluso la cr\u00edtica m\u00e1s especializada, reconoci\u00f3 las profundas<br>aportaciones culturales de su legado art\u00edstico.<\/p>\n\n\n\n<p>Su humor desnud\u00f3 los contrastes de la urbe, de la desigualdad, de la pobreza, las<br>clases sociales y la moralidad de un pa\u00eds contradictorio que se tropieza<br>estrepitosamente tras el ideal de modernidad, frente a su herencia ind\u00edgena y<br>colonial.<\/p>\n\n\n\n<p>La conferencia se suma a las actividades que prepara el Archivo Municipal, para<br>dar a conocer los datos hist\u00f3ricos del pa\u00eds y la regi\u00f3n, en los diferentes \u00e1mbitos<br>como es el cultural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 17 de octubre de 2023. El Archivo Municipal de Torre\u00f3n presentar\u00e1 la conferencia \u201cEl hijo desobediente,Tin Tan y la cultura del pachuco\u201d, a cargo del cronista urbano Alfredo RojasHern\u00e1ndez, el pr\u00f3ximo jueves 19 de octubre a las 19:00 horas. Cinthia Gaspar Montero, directora del Archivo Municipal, coment\u00f3 que la invitaci\u00f3nes abierta al p\u00fablico general y dio a conocer que el evento se llevar\u00e1 a cabo en lasinstalaciones&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-17617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=17617"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17617\/revisions"}],"predecessor-version":[{"id":17619,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/17617\/revisions\/17619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/17618"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=17617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=17617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=17617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}