{"id":1817,"date":"2021-04-27T19:14:56","date_gmt":"2021-04-28T00:14:56","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=1817"},"modified":"2021-04-27T19:14:57","modified_gmt":"2021-04-28T00:14:57","slug":"secretaria-de-seguridad-publica-del-estado-ssp-informa-2","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/04\/27\/secretaria-de-seguridad-publica-del-estado-ssp-informa-2\/","title":{"rendered":"Secretar\u00eda de Seguridad P\u00fablica del Estado (SSP) informa:"},"content":{"rendered":"\n<p>1.- A las 09:00 horas de hoy el sistema de emergencias recibi\u00f3 un reporte sobre dos personas lesionadas con arma de fuego en el Libramiento Jes\u00fas Mar\u00eda Ram\u00f3n, en esta ciudad.<\/p>\n\n\n\n<p>2.- De acuerdo con el reporte policiaco, elementos de la Fiscal\u00eda General del Estado (FGE) se trasladaron al lugar y al llegar se percataron que uno de ellos se encontraba sin vida y el otro gravemente herido, por lo que fue trasladado para recibir atenci\u00f3n m\u00e9dica. Dado su estado de salud no fue posible que diera testimonio de los hechos.<\/p>\n\n\n\n<p>3.- Al sito se present\u00f3 una persona de nombre Regina \u201cN\u201d, quien dijo conocer a la persona herida, a quien identific\u00f3 como Manuel \u201cN\u201d, originario de la Ciudad de Tijuana, Baja California.<\/p>\n\n\n\n<p>4.- Sobre la persona sin vida, inform\u00f3 que su nombre es Jorge \u201cN\u201d, originario de la Ciudad de Matamoros, Tamaulipas.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 adem\u00e1s que ambos llegaron a esta ciudad desde hace m\u00e1s de una semana.<\/p>\n\n\n\n<p>5.- Por lo anterior, la FGE inici\u00f3 con la respectiva Carpeta de Investigaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1.- A las 09:00 horas de hoy el sistema de emergencias recibi\u00f3 un reporte sobre dos personas lesionadas con arma de fuego en el Libramiento Jes\u00fas Mar\u00eda Ram\u00f3n, en esta ciudad. 2.- De acuerdo con el reporte policiaco, elementos de la Fiscal\u00eda General del Estado (FGE) se trasladaron al lugar y al llegar se percataron que uno de ellos se encontraba sin vida y el otro gravemente herido, por lo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,24],"tags":[],"class_list":["post-1817","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-gobierno-de-coahuila","category-seguridad","wpcat-5-id","wpcat-15-id","wpcat-24-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=1817"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1817\/revisions"}],"predecessor-version":[{"id":1818,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/1817\/revisions\/1818"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=1817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=1817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=1817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}