{"id":18361,"date":"2023-11-30T19:22:04","date_gmt":"2023-12-01T01:22:04","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=18361"},"modified":"2023-11-30T19:22:05","modified_gmt":"2023-12-01T01:22:05","slug":"me-voy-muy-tranquilo-del-coahuila-que-construimos-juntos-mars","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2023\/11\/30\/me-voy-muy-tranquilo-del-coahuila-que-construimos-juntos-mars\/","title":{"rendered":"\u2018ME VOY MUY TRANQUILO DEL COAHUILA QUE CONSTRUIMOS JUNTOS\u2019: MARS."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 30 de Noviembre de 2023.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds resalt\u00f3 el trabajo en unidad con las y los coahuilenses, el cual permiti\u00f3 al Estado alcanzar y sostener indicadores con los que hoy es referente nacional: \u201cMe voy tranquilo del Coahuila que construimos juntos\u201d.<\/p>\n\n\n\n<p>Lo anterior durante la ceremonia en la que se devel\u00f3 su retrato y se coloc\u00f3 en el Sal\u00f3n Gobernadores de Palacio de Gobierno, al concluir su mandato constitucional.<\/p>\n\n\n\n<p>Ante los titulares de las diferentes dependencias de su Administraci\u00f3n, as\u00ed como de los Poderes Legislativo y Judicial, Riquelme Sol\u00eds reiter\u00f3 su agradecimiento a todas y todos los trabajadores del Gobierno Estatal, as\u00ed como al pueblo de Coahuila, por darle el gran honor de gobernar el Estado.<\/p>\n\n\n\n<p>\u201cLos resultados que ha tenido Coahuila son por el trabajo en equipo\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Expres\u00f3 que durante toda su Administraci\u00f3n busc\u00f3 la unidad de las y los coahuilenses; record\u00f3 que su gesti\u00f3n inici\u00f3 con grandes retos y extern\u00f3 que hoy termina con muchas metas y objetivos cumplidos gracias al gran equipo de trabajo del Gobierno Estatal.<\/p>\n\n\n\n<p>\u201cUna Administraci\u00f3n que creci\u00f3 con la participaci\u00f3n de todas y todos, desde distintos frentes, y que impulsamos juntos a trav\u00e9s del tiempo con etapas que fueron cr\u00edticas, con decisiones que no fueron f\u00e1ciles\u201d, reconoci\u00f3.<\/p>\n\n\n\n<p>Miguel Riquelme destac\u00f3 que se deja un Estado equilibrado, con mucha seguridad, con generaci\u00f3n de empleo y desarrollo econ\u00f3mico, con los tres Poderes colaborando en conjunto para seguir creciendo.<\/p>\n\n\n\n<p>\u201cHoy, estoy ocupado por tener una entrega responsable por el bien de Coahuila, en la cual Manolo Jim\u00e9nez pueda continuar con la marcha del Estado y que no haya ning\u00fan comp\u00e1s de espera, ni jur\u00eddica ni pol\u00edtica ni operativamente\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Mencion\u00f3 que este es su \u00faltimo d\u00eda de Gobierno, y que a seis a\u00f1os de haber iniciado esta etapa de su vida, sigue creyendo en la unidad de las y los coahuilenses, sigue creyendo en el trabajo en equipo y en la participaci\u00f3n ciudadana.<\/p>\n\n\n\n<p>\u201cYo invito a todos a participar con el nuevo Gobierno, con Manolo Jim\u00e9nez, porque solamente la sociedad que est\u00e1 detr\u00e1s fortalece el trabajo diario de un Gobierno\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>Reiter\u00f3 su agradecimiento a los exgobernadores, porque pusieron su granito de arena para el Coahuila que hoy tenemos: \u201cEspero haberlo puesto yo tambi\u00e9n, con todo el equipo de trabajo\u201d.<\/p>\n\n\n\n<p>En esta ceremonia estuvieron presentes, Jos\u00e9 Mar\u00eda Fraustro Siller, Alcalde de Saltillo; Eduardo Olmos Castro, diputado Presidente de la Junta de Gobierno del Congreso local; Miguel Felipe Mery Ayup, magistrado Presidente del Tribunal Superior de Justicia, y Ver\u00f3nica Mart\u00ednez Garc\u00eda, senadora de la Rep\u00fablica.<\/p>\n\n\n\n<p>As\u00ed como los integrantes del Gabinete Legal y Ampliado del Ejecutivo, diputadas y diputados electos, y colaboradores del Gobierno estatal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 30 de Noviembre de 2023.- El gobernador Miguel \u00c1ngel Riquelme Sol\u00eds resalt\u00f3 el trabajo en unidad con las y los coahuilenses, el cual permiti\u00f3 al Estado alcanzar y sostener indicadores con los que hoy es referente nacional: \u201cMe voy tranquilo del Coahuila que construimos juntos\u201d. Lo anterior durante la ceremonia en la que se devel\u00f3 su retrato y se coloc\u00f3 en el Sal\u00f3n Gobernadores de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15],"tags":[],"class_list":["post-18361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","wpcat-5-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/18361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=18361"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/18361\/revisions"}],"predecessor-version":[{"id":18363,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/18361\/revisions\/18363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/18362"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=18361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=18361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=18361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}