{"id":19562,"date":"2024-02-27T19:17:41","date_gmt":"2024-02-28T01:17:41","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=19562"},"modified":"2024-02-27T19:17:42","modified_gmt":"2024-02-28T01:17:42","slug":"inicia-en-la-uadec-la-feria-virtual-de-posgrados","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/02\/27\/inicia-en-la-uadec-la-feria-virtual-de-posgrados\/","title":{"rendered":"Inicia en la UAdeC la \u201cFeria Virtual de Posgrados\u201d."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 27 de febrero de 2024. Con el fin de dar a conocer y<br>promocionar los programas de posgrado de las Unidades Saltillo, Torre\u00f3n y Norte<br>de la Universidad Aut\u00f3noma de Coahuila, inici\u00f3 la \u201cFeria Virtual de Posgrados\u201d que<br>impulsa la Direcci\u00f3n de Investigaci\u00f3n y Posgrado (DIP) y la cual se desarrolla del<br>27 de febrero al 1 de marzo de 2024 a trav\u00e9s de las p\u00e1ginas de Facebook<br>Universidad Aut\u00f3noma de Coahuila e Investigaci\u00f3n y Posgrado UAdeC.<\/p>\n\n\n\n<p>En el acto inaugural se cont\u00f3 con la presencia del rector de la m\u00e1xima casa de<br>estudios, Octavio Pimentel Mart\u00ednez, el director de Investigaci\u00f3n y Posgrado,<br>Crist\u00f3bal No\u00e9 Aguilar Gonz\u00e1lez, el subdirector de Posgrado, Jos\u00e9 Luis Mart\u00ednez<br>Hern\u00e1ndez, estudiantes, docentes, investigadores y p\u00fablico en general interesado<br>en el tema.<\/p>\n\n\n\n<p>En su mensaje el Rector dio la bienvenida a los participantes conectados v\u00eda<br>Microsoft Teams y por Facebook Live y destac\u00f3 que este tipo de eventos son<br>fundamentales para fomentar la participaci\u00f3n de los investigadores e informar a<br>los universitarios y a la comunidad sobre la oferta de posgrado con la que cuenta<br>la m\u00e1xima casa de estudios.<\/p>\n\n\n\n<p>Por su parte, el subdirector de Posgrado, Jos\u00e9 Luis Mart\u00ednez Hern\u00e1ndez, dijo que<br>la Feria se realiza en los meses de febrero\/marzo para el primer semestre y en<br>septiembre\/octubre para el segundo semestre, lo que permite mantener una<br>difusi\u00f3n constante de la oferta educativa de posgrados, atendiendo a uno de los<br>requerimientos necesarios para impulsar y dar a conocer la oferta educativa de<br>posgrados de la Universidad que involucra 83 programas.<\/p>\n\n\n\n<p>Por otro lado, la responsable de Validaci\u00f3n y Control Acad\u00e9mico-Administrativo de<br>Posgrado de la DIP, Olimpia Garay Santos, inform\u00f3 que, adem\u00e1s de proporcionar<br>informaci\u00f3n sobre cada programa educativo, en la Feria se orientar\u00e1 a los<br>interesados en el proceso de admisi\u00f3n y que para ello tambi\u00e9n pueden visitar el<br>sitio WEB <a href=\"http:\/\/www.investigacionyposgrado.uadec.mx\/feriavirtualdeposgrado\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.investigacionyposgrado.uadec.mx\/feriavirtualdeposgrado\/<\/a>.<\/p>\n\n\n\n<p>Durante el evento se imparti\u00f3 la conferencia \u201cConstruyendo el \u00e9xito, \u00bfc\u00f3mo elegir<br>el posgrado perfecto?\u201d, a cargo de la profesora investigadora de la Facultad de<br>Econom\u00eda y Mercadotecnia de la UAdeC, Dra. Berenice Ju\u00e1rez L\u00f3pez, durante la<br>cual se\u00f1al\u00f3 que para elegir un posgrado es necesario identificar las ventajas y<br>desventajas del lugar donde se encuentra la persona actualmente y evaluar la<br>historia acad\u00e9mica y laboral.<\/p>\n\n\n\n<p>Explic\u00f3 que al estudiar un posgrado se obtienen beneficios que nos ayudar\u00e1n a<br>cumplir con nuestros prop\u00f3sitos planteados y para ello debemos identificar<br>nuestros conocimientos y habilidades, adem\u00e1s, de definir si queremos una<br>especialidad, maestr\u00eda o doctorado.<\/p>\n\n\n\n<p>Posteriormente, se present\u00f3 el programa de posgrado de Doctorado en Ingenier\u00eda<br>Bioqu\u00edmica de la Facultad de Ciencias Biol\u00f3gicas Unidad Torre\u00f3n; Maestr\u00eda en<br>Administraci\u00f3n con acentuaci\u00f3n en Finanzas, Desarrollo de Nuevos Negocios y<br>Capital Humano y Maestr\u00eda en Contribuciones Tributarias de la Facultad de<br>Contadur\u00eda y Administraci\u00f3n de Monclova Unidad Norte; Maestr\u00eda en Ingenier\u00eda<br>Mec\u00e1nica de la Facultad de Ingenier\u00eda Mec\u00e1nica y El\u00e9ctrica Unidad Torre\u00f3n y<br>Maestr\u00eda en Arte y Dise\u00f1o de la Facultad de Artes Pl\u00e1sticas.<\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n sobre la Feria Virtual de Posgrados, visitar las p\u00e1ginas de<br>Facebook Universidad Aut\u00f3noma de Coahuila e Investigaci\u00f3n y Posgrado UAdeC,<br>escribir al correo electr\u00f3nico posgradouadec@uadec.edu.mx o llamar al tel\u00e9fono<br>(844) 414 85 82.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 27 de febrero de 2024. Con el fin de dar a conocer ypromocionar los programas de posgrado de las Unidades Saltillo, Torre\u00f3n y Nortede la Universidad Aut\u00f3noma de Coahuila, inici\u00f3 la \u201cFeria Virtual de Posgrados\u201d queimpulsa la Direcci\u00f3n de Investigaci\u00f3n y Posgrado (DIP) y la cual se desarrolla del27 de febrero al 1 de marzo de 2024 a trav\u00e9s de las p\u00e1ginas de FacebookUniversidad Aut\u00f3noma de Coahuila e&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-19562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=19562"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19562\/revisions"}],"predecessor-version":[{"id":19564,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19562\/revisions\/19564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/19563"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=19562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=19562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=19562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}