{"id":19584,"date":"2024-02-28T18:37:06","date_gmt":"2024-02-29T00:37:06","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=19584"},"modified":"2024-02-28T18:37:07","modified_gmt":"2024-02-29T00:37:07","slug":"invitan-a-nueva-actividad-en-el-archivo-municipal-de-torreon","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/02\/28\/invitan-a-nueva-actividad-en-el-archivo-municipal-de-torreon\/","title":{"rendered":"Invitan a nueva actividad en el Archivo Municipal de Torre\u00f3n."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 28 de febrero de 2024.<\/p>\n\n\n\n<p>El Archivo Municipal de Torre\u00f3n, en coordinaci\u00f3n con \u201cTres Hermanos Editores\u201d,<br>tiene programada la presentaci\u00f3n del libro\u00a0\u201cAnecdotario de Ciudad Lerdo\u201d, del<br>arquitecto Jos\u00e9 Antonio Fern\u00e1ndez Franco, el d\u00eda de ma\u00f1ana a las 19:00 horas,<br>con entrada libre.<\/p>\n\n\n\n<p>Cinthia Gaspar Montero, directora de la dependencia, inform\u00f3 que esta actividad<br>se inserta en el marco del 130 aniversario de la fundaci\u00f3n de ciudad Lerdo, y<br>contar\u00e1 con los comentarios del historiador Domingo Deras Torres y el editor Jos\u00e9<br>Miguel Ch\u00e1irez Carrillo.<\/p>\n\n\n\n<p>\u201cA trav\u00e9s de este anecdotario de relatos hist\u00f3ricos de la Hacienda de San<br>Fernando, Villa Lerdo y Ciudad Lerdo, Durango, nos adentraremos en los<br>antecedentes de ese municipio, una parte importante y medular en la construcci\u00f3n<br>de la identidad de la Comarca Lagunera\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Villa Lerdo fue hasta el 24 de julio de 1867 la Hacienda de San Fernando de La<br>Laguna, fecha en que fue erigida como villa, en honor al reformista y patriota<br>veracruzano Miguel Lerdo de Tejada.<\/p>\n\n\n\n<p>En esa \u00e9poca era la segunda poblaci\u00f3n del estado de Durango por su importancia<br>mercantil, por la elegancia de sus construcciones y por su floreciente industria.<br>Merece citarse el palacio municipal, el mercado o par\u00edan, la parroquia, la plaza de<br>toros y el jard\u00edn de la plaza principal.<\/p>\n\n\n\n<p>Jos\u00e9 Antonio Fern\u00e1ndez Franco, es egresado del ITESM Campus Monterrey. Su<br>trabajo est\u00e1 enfocado a la investigaci\u00f3n hist\u00f3rica desde hace 17 a\u00f1os, a trav\u00e9s de<br>diversos trabajos.<\/p>\n\n\n\n<p>Particip\u00f3 en 13 exposiciones de fotograf\u00eda retrospectiva de diferentes tem\u00e1ticas,<br>en la elaboraci\u00f3n de revistas sobre ciudad Lerdo y en la realizaci\u00f3n de dos<br>calendarios fotogr\u00e1ficos para la iglesia del Sagrado Coraz\u00f3n de Jes\u00fas.<\/p>\n\n\n\n<p>Incursion\u00f3 en el Festival Lerdantino 2017 y en la festividad del D\u00eda de Muertos en<br>el mismo a\u00f1o.<\/p>\n\n\n\n<p>Adem\u00e1s, integr\u00f3 el grupo de historia \u201cEl tranv\u00eda de G\u00f3mez Palacio\u201d. Ha realizado<br>diversas presentaciones sobre el reparto agrario de La Laguna en 1920; la familia<br>Gorosave y su historia; adem\u00e1s de la historia del tranv\u00eda de Lerdo a Torre\u00f3n; los<br>circos de 1900 con Ricardo Bell, clown favorito del general Porfirio D\u00edaz y las<br>bodas de \u00e9poca en Lerdo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 28 de febrero de 2024. El Archivo Municipal de Torre\u00f3n, en coordinaci\u00f3n con \u201cTres Hermanos Editores\u201d,tiene programada la presentaci\u00f3n del libro\u00a0\u201cAnecdotario de Ciudad Lerdo\u201d, delarquitecto Jos\u00e9 Antonio Fern\u00e1ndez Franco, el d\u00eda de ma\u00f1ana a las 19:00 horas,con entrada libre. Cinthia Gaspar Montero, directora de la dependencia, inform\u00f3 que esta actividadse inserta en el marco del 130 aniversario de la fundaci\u00f3n de ciudad Lerdo, ycontar\u00e1 con los comentarios&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,12,28,7],"tags":[],"class_list":["post-19584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-cultura","category-la-laguna","category-torreon","wpcat-5-id","wpcat-12-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=19584"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19584\/revisions"}],"predecessor-version":[{"id":19586,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19584\/revisions\/19586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/19585"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=19584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=19584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=19584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}