{"id":19623,"date":"2024-03-01T20:04:16","date_gmt":"2024-03-02T02:04:16","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=19623"},"modified":"2024-03-01T20:04:16","modified_gmt":"2024-03-02T02:04:16","slug":"rehabilitan-casetas-de-seguridad-en-varias-colonias-de-torreon","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/03\/01\/rehabilitan-casetas-de-seguridad-en-varias-colonias-de-torreon\/","title":{"rendered":"Rehabilitan casetas de seguridad en varias colonias de Torre\u00f3n."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.- Veintis\u00e9is\u00a0 meses y\u00a0 algunos d\u00edas m\u00e1s, le llev\u00f3 a la presente administraci\u00f3n municipal,\u00a0 volver\u00a0 a poner en marcha la\u00a0 operaci\u00f3n de casetas en puntos claves de la ciudad, generalmente en barrios y colonias\u00a0 con poblaci\u00f3n\u00a0 con problemas de inseguridad, estrategia\u00a0 que ubica en punto fijo\u00a0 la presencia polic\u00edaca y\u00a0 la prestaci\u00f3n de algunos servicios conexos a los vecinos de tales lugares.<\/p>\n\n\n\n<p>Esta ma\u00f1ana, el alcalde Rom\u00e1n Cepeda Gonz\u00e1lez,\u00a0puso en marcha, de nueva cuenta, y vecinos dicen que luego de 10 a\u00f1os y otros m\u00e1s que\u00a0 16, que\u00a0 la caseta ubicada en el parque de la Colonia Valle Dorado, es una de las 22 existentes en la ciudad, de las cuales 18\u00a0 a\u00fan restan por ser rehabilitadas y puestas en condiciones de\u00a0 servicio.<\/p>\n\n\n\n<p>Se espera que\u00a0 los vecinos, no solo de Valle Dorado, sino tambi\u00e9n\u00a0 la de Jardines de California y\u00a0 Eduardo Guerra\u00a0 \u00a0 sean cubiertas las necesidades de auxilio polic\u00edaco de manera expedita,\u00a0 al contar de nueva cuenta, con los servicios de seguridad p\u00fablica que puedan proporcionar esta estrategia\u00a0 y que estar\u00e1 siendo atendida por\u00a0 dos elementos, a\u00a0 lo largo de 24 horas diarias.<\/p>\n\n\n\n<p>El acto, celebrado en el lugar, cont\u00f3 con la presencia de representantes de la milicia vecinos y\u00a0 funcionarios de la administraci\u00f3n municipal, as\u00ed como la del titular de la Direcci\u00f3n\u00a0 de\u00a0 Seguridad P\u00fablica, C\u00e9sar Antonio Perales Esparza.\u00a0<\/p>\n\n\n\n<p>Correspondi\u00f3 al funcionario en su intervenci\u00f3n expresar que\u00a0 bajo el Programa de Recuperaci\u00f3n de Espacios y Atenci\u00f3n\u00a0 Ciudadana, &#8220;que se encontraban en situaci\u00f3n de abandono y vandalizadas, que al d\u00eda de hoy\u00a0 sumamos 11, de 18\u00a0 de una meta\u00a0 pre-establecida fijada\u00a0 para el presente a\u00f1o que, la que hoy ponemos en operaci\u00f3n dar\u00e1 servicio a las colonias Valle Dorado, Jardines de California, Eduardo Guerra, as\u00ed como las principales avenidas de este sector, sin dejar de pasar\u00a0a planteles educativos cercanos, f\u00e1bricas en la zona, as\u00ed como en los limites de los patios de maniobras de Ferrocarriles de Ferromex.<\/p>\n\n\n\n<p>&#8220;Despu\u00e9s de\u00a0 10 a\u00f1os de desuso de \u00e9sta caseta, la cual se encontraba en total abandono, ya rehabilitada en su totalidad contar\u00e1\u00a0 de dos\u00a0 elementos que estar\u00e1n 24 horas, los siete d\u00edas de la semana, los 365 d\u00edas del a\u00f1o, con una l\u00ednea\u00a0 telef\u00f3nica directa para recibir llamadas de emergencia y un sistema de enlace con patrullas del sector, con el fin de actuar de manera inmediata como primer respondiente&#8221;.\u00a0<\/p>\n\n\n\n<p>Por\u00a0 su parte el Alcalde Cepeda\u00a0 Gonz\u00e1lez en su intervenci\u00f3n, estim\u00f3 en\u00a0 20 mil vecinos los beneficiarios con esta acci\u00f3n.\u00a0\u00a0<\/p>\n\n\n\n<p>&#8220;Hoy nos ocupa la supervisi\u00f3n de la onceava caseta de seguridad&#8221;, \u00a0 recordando que su primer eje del gobierno tiene que ver con seguridad y orden, &#8220;de ah\u00ed que en consecuencia, los tiempos sean importantes, pero el compromiso es lo importante&#8221;.<\/p>\n\n\n\n<p>Dijo luego que, &#8220;pasar del abandono a la ocupaci\u00f3n es nuestra principal tarea, gracias por recibirnos aqu\u00ed, hay mucha tarea que hacer, en este\u00a0 orden y cualquier\u00a0 otro&#8221;.\u00a0<\/p>\n\n\n\n<p>&#8220;Con seguridad y orden, con certeza, habremos de llegar a todos lados&#8221;, asegur\u00f3 el edil, para destacar luego, &#8220;el que sigamos trabajando juntos sociedad y gobierno&#8221;,\u00a0sin dejar de recordar que, &#8220;en un proceso electoral ya en marcha\u00a0 que es importante\u00a0 decirles, que hay acotaciones de car\u00e1cter legal, pero no hay excusas para\u00a0 no seguir trabajando&#8221;.<\/p>\n\n\n\n<p>Seguiremos trabajando, asegur\u00f3 con\u00a0 acotaciones, &#8220;pero apegados siempre a derecho, respetando la ley, seguiremos trabajando duro, porque Torre\u00f3n no tiene tiempo que perder&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.- Veintis\u00e9is\u00a0 meses y\u00a0 algunos d\u00edas m\u00e1s, le llev\u00f3 a la presente administraci\u00f3n municipal,\u00a0 volver\u00a0 a poner en marcha la\u00a0 operaci\u00f3n de casetas en puntos claves de la ciudad, generalmente en barrios y colonias\u00a0 con poblaci\u00f3n\u00a0 con problemas de inseguridad, estrategia\u00a0 que ubica en punto fijo\u00a0 la presencia polic\u00edaca y\u00a0 la prestaci\u00f3n de algunos servicios conexos a los vecinos de tales lugares. Esta ma\u00f1ana, el alcalde Rom\u00e1n Cepeda Gonz\u00e1lez,\u00a0puso&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,24,7],"tags":[],"class_list":["post-19623","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-la-laguna","category-seguridad","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-24-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=19623"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19623\/revisions"}],"predecessor-version":[{"id":19624,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/19623\/revisions\/19624"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=19623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=19623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=19623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}