{"id":20010,"date":"2024-04-04T21:01:54","date_gmt":"2024-04-05T03:01:54","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=20010"},"modified":"2024-04-04T21:01:54","modified_gmt":"2024-04-05T03:01:54","slug":"continua-campana-roman-cepeda-en-colonia-lazaro-cardenas","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/04\/04\/continua-campana-roman-cepeda-en-colonia-lazaro-cardenas\/","title":{"rendered":"Contin\u00faa campa\u00f1a Rom\u00e1n Cepeda en colonia L\u00e1zaro C\u00e1rdenas."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.-\u00a0 A cuatro d\u00edas del inicio de su campa\u00f1a, esta tarde,\u00a0 el alcalde en busca de su reeleccion en tal cargo,\u00a0 Licenciado Rom\u00e1n Alberto Cepeda\u00a0 Gonz\u00e1lez, se hizo presente en\u00a0 una de las populosas calles\u00a0 de la Colonia L\u00e1zaro C\u00e1rdenas, para enfrentar\u00a0 y\u00a0 que promete superar, los rezagos que en materia de servicios p\u00fablicos \u00a0 ah\u00ed se registran, entre los que se encuentra, drenajes,\u00a0 agua potable,\u00a0 pavimentaci\u00f3n, limpieza, nomenclatura,\u00a0 entre otros.<\/p>\n\n\n\n<p>Tras su encuentro con hombres y mujeres que se concentraron en la intersecci\u00f3n de la Calle Francisco I. Madero\u00a0 y H\u00e9roes\u00a0 del R\u00edo Blanco, esperaban el arribo del aspirante de la denominada &#8220;Alianza por la Seguridad&#8221; \u00a0 escuchando los acordes \u00a0 festivos de un conjunto musical.<\/p>\n\n\n\n<p>Tras\u00a0 breve mensaje \u00a0 que dio pie a \u00a0 cerrado di\u00e1logo con los ah\u00ed presentes, que le hicieron la presentaci\u00f3n de las demandas de orden\u00a0 colectiva de esta colonia ubicada al sur de la ciudad, para luego buscar\u00a0 el dialogo para \u00a0 ser escuchados en sus problem\u00e1ticas personales, mismas que\u00a0 fueron canalizadas por el equipo de campa\u00f1a que lo\u00a0 esta acompa\u00f1ando en sus\u00a0 recorridos sobre territorio.<\/p>\n\n\n\n<p>Destac\u00f3 esta tarde, los se\u00f1alamientos puntuales, con\u00a0 puntos muy concretos de los problemas que generan tramos de\u00a0 un drenaje\u00a0 colapsado, prometiendo \u00a0 la\u00a0 soluci\u00f3n a los afectados.<\/p>\n\n\n\n<p><strong>CON LOS MEDIOS.<\/strong><\/p>\n\n\n\n<p>Enseguida, el candidato\u00a0 sostuvo un breve encuentro con los representantes de los Medios que siguen de cerca su campa\u00f1a, abordando entre otros temas, \u00a0 &#8220;que es la confianza dela ciudadan\u00eda, que sigue pagando sus impuestos, confianza generada porque\u00a0 ven obras&#8221;.<\/p>\n\n\n\n<p>En cuanto al tema de su probable\u00a0 participaci\u00f3n en\u00a0 los debates, algunos obligadamente se encuentran contemplados en la ley electoral vigente, manifest\u00f3 no saber, pues\u00a0 tal tema lo trae su Coordinador de Campa\u00f1a, si bien agreg\u00f3 que, &#8220;yo lo he dicho,\u00a0 en el tema del debate, no es primero en el que participo. Yo voy a hacer un debate de propuesta, de nivel. Torre\u00f3n es lo que merece&#8221;.<\/p>\n\n\n\n<p>Agregaba luego que, &#8220;yo estoy listo para ello, si bien desconozco si ya hay fecha, lugar para ello, pero siempre que se garantice\u00a0 la institucionalidad de un debate serio y responsable. Ah\u00ed estar\u00e9&#8221;.<\/p>\n\n\n\n<p>.Preguntado\u00a0 sobre el\u00a0 desencuentro que se genera en el \u00e1mbito de la contienda\u00a0 presidencial, la exhibici\u00f3n profusa en video de las limitaciones o debilidades documentadas \u00a0 de uno de los v\u00e1stagos de la candidata X\u00f3chitl \u00a0 G\u00e1lvez\u00a0 con fines obvios en la ya m\u00e1s que enrarecido clima\u00a0 pol\u00edtico electoral que se registra en amplias zonas del pa\u00eds.<\/p>\n\n\n\n<p>Tras decir no estar suficientemente\u00a0 informado al respecto, &#8220;porque estoy clavado en la campa\u00f1a, al final es lamentable. Hay cosas que no se tocan y creo que es importante\u00a0 que en un pa\u00eds, en un Estado y en un municipio que lo que queremos es certidumbre, certezas, tranquilidad, generar m\u00e1s incertidumbre\u00a0 de que ya hay en el pa\u00eds, ya no&#8221;.<\/p>\n\n\n\n<p>Hoy, agregaba, &#8220;tenemos y necesitamos debate de altura, candidatos de altura, la gente lo que necesita son resultados, no solo propuestas, pero avaladas con resultados en el entendido de que hay limitaciones presupuestales, pero con responsabilidad\u00a0 y compromiso se puede cumplir&#8221;.<\/p>\n\n\n\n<p>Es lamentable, repiti\u00f3, &#8220;que se utilice siempre, cualquier mecanismos de denostaci\u00f3n, incluso para los mismos candidatos\u00a0 no ha sido nunca mi estilo y no los ser\u00e1, lo rechazo totalmente&#8221;.<\/p>\n\n\n\n<p>Dijo luego al ser preguntado\u00a0 sobre la carga adicional\u00a0 que como candidato le genera a su tiempo diario,\u00a0 destinarlos, como destina\u00a0 seis horas al hilo a\u00a0 su funci\u00f3n como alcalde y el resto, a la campa\u00f1a por la reeeleci\u00f3n,\u00a0 diciendo que, &#8220;yo estoy\u00a0 bien,\u00a0 porque he notado mucho \u00e1nimo, como lo han dicho, es una campa\u00f1a abierta, donde la gente se expresa, reconociendo lo que se ha hecho, pero tambi\u00e9n manifestando lo que falta, pues hay mucho por hacer todav\u00eda&#8221;.<\/p>\n\n\n\n<p>Eso, afirm\u00f3, &#8220;es\u00a0 la parte a lo que yo vengo, acabo de estar cerquita\u00a0 de este lugar,\u00a0 he estado en el oriente, en el poniente, el primer cuadro, donde el escuchar a Torre\u00f3n es el tomar las decisiones correctas y eso es lo que seguimos haciendo, como alcalde lo seguir\u00e9 haciendo y como candidato tambi\u00e9n&#8221;.<\/p>\n\n\n\n<p>En relaci\u00f3n a como se desempe\u00f1a\u00a0no su equipo de campa\u00f1a, sino el equipo de trabajo de la administraci\u00f3n municipal a su cargo\u00a0 en estas circunstancia,\u00a0 diciendo que, &#8220;afortunadamente\u00a0 tenemos gente buena que ha quedado al frente de quienes\u00a0 decidieron pedir licencia para buscar el tema de una aspiraci\u00f3n, pero lo m\u00e1s importante es que Torre\u00f3n no se debe detener, tenemos que seguir perforando m\u00e1s pozos para darle agua a Torre\u00f3n, ha sido una inversi\u00f3n extraordinaria seguir pavimentando Torre\u00f3n, llevamos m\u00e1s de 2 millones de metros cuadrados y hoy llevamos 500 mil metros en este\u00a0 primer\u00a0 trimestre del a\u00f1o y es un tema siempre importante&#8221;.<\/p>\n\n\n\n<p>Nosotros, dijo,\u00a0&#8220;siempre estamos tapando, bacheando\u00a0 lo que\u00a0 hace un tiempo no se hac\u00eda. Torre\u00f3n no se detiene ni se debe detener&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.-\u00a0 A cuatro d\u00edas del inicio de su campa\u00f1a, esta tarde,\u00a0 el alcalde en busca de su reeleccion en tal cargo,\u00a0 Licenciado Rom\u00e1n Alberto Cepeda\u00a0 Gonz\u00e1lez, se hizo presente en\u00a0 una de las populosas calles\u00a0 de la Colonia L\u00e1zaro C\u00e1rdenas, para enfrentar\u00a0 y\u00a0 que promete superar, los rezagos que en materia de servicios p\u00fablicos \u00a0 ah\u00ed se registran, entre los que se encuentra, drenajes,\u00a0 agua potable,\u00a0 pavimentaci\u00f3n, limpieza, nomenclatura,\u00a0&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,5,28,16,7],"tags":[],"class_list":["post-20010","post","type-post","status-publish","format-standard","hentry","category-campanas","category-coahuila","category-la-laguna","category-pri","category-torreon","wpcat-20-id","wpcat-5-id","wpcat-28-id","wpcat-16-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=20010"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20010\/revisions"}],"predecessor-version":[{"id":20011,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20010\/revisions\/20011"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=20010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=20010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=20010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}