{"id":20600,"date":"2024-05-15T18:52:18","date_gmt":"2024-05-16T00:52:18","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=20600"},"modified":"2024-05-15T18:52:18","modified_gmt":"2024-05-16T00:52:18","slug":"todo-listo-para-el-foro-inn-3-quedan-muy-pocos-lugares","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/05\/15\/todo-listo-para-el-foro-inn-3-quedan-muy-pocos-lugares\/","title":{"rendered":"Todo listo para el Foro INN 3; quedan muy pocos lugares."},"content":{"rendered":"\n<p>Torre\u00f3n, Coah. Mi\u00e9rcoles 15 de mayo de 2024.- La C\u00e1mara Nacional de la Industria de<br>Desarrollo y Promoci\u00f3n de Vivienda Delegaci\u00f3n Comarca Lagunera (CANADEVI Laguna)<br>informa que todo est\u00e1 listo para la Tercera Edici\u00f3n del Foro Inmobiliario del Norte. &#8220;El<br>Poder de Construir el Futuro de M\u00e9xico&#8221;, para el cual quedan muy pocos boletos<br>disponibles para quienes deseen asistir.<\/p>\n\n\n\n<p>El Foro INN es el encuentro inmobiliario m\u00e1s importante del norte de M\u00e9xico y tiene<br>como objetivo compartir conocimientos sobre el sector inmobiliario para tomar<br>decisiones m\u00e1s informadas, enfrentar desaf\u00edos y aprovechar oportunidades dentro del<br>sector.<\/p>\n\n\n\n<p>Jos\u00e9 Pi\u00f1a \u00c1lvarez, Presidente de CANADEVI Laguna dijo que el Foro INN 3<br>\u201creunir\u00e1 a todas las personas con alg\u00fan inter\u00e9s en el sector inmobiliario que<br>pretendan darle mayor valor a su participaci\u00f3n en este importante sector de la<br>econom\u00eda regional y nacional\u201d.<\/p>\n\n\n\n<p>El Foro INN 3 est\u00e1 dirigido a empresarios desarrolladores de vivienda,<br>desarrolladores inmobiliarios comerciales, industriales y de servicios, ejecutivos de<br>empresas inmobiliarias, agentes inmobiliarios, empresarios y ejecutivos del sector de la<br>construcci\u00f3n, arquitectos, ingenieros civiles y urbanistas, estudiantes de carreras<br>relacionadas con el sector inmobiliario, y empresarios y ejecutivos de otras ramas con<br>inter\u00e9s en el sector inmobiliario.<\/p>\n\n\n\n<p>El Foro INN 3 se llevar\u00e1 a cabo en el Centro de Convenciones de Torre\u00f3n,<br>Coahuila, y arrancar\u00e1 este jueves 16 de mayo a las 2.00 pm y concluir\u00e1 el viernes 17<br>de mayo de 2024.<\/p>\n\n\n\n<p>Entre los ponentes destacados del Foro INN 3 se encuentran expertos como Luis<br>Carlos Ugalde, Director General de Integralia; Jorge \u00c1valos Carpinteyro, Presidente<br>de AMPIP M\u00e9xico; Arnoldo de la Garza Hurtado, Director Fiduciario en BANCREA;<br>Minerva Alvarado, Subdirectora de Promoci\u00f3n Fiduciaria en BANCREA; Baloys<br>Tiburcio Navarro, Director Comercial de Orange Investments; Marisol Becerra,<br>Directora de Tinsa, y Axel Estrada Media, Socio Fundador de Newlex, entre otros.<br>Adem\u00e1s de los paneles y ponencias, se llevar\u00e1 a cabo un evento de networking<br>exclusivo entre empresarios, autoridades y ponentes.<\/p>\n\n\n\n<p>Jos\u00e9 Pi\u00f1a \u00c1lvarez dijo que &#8220;el Foro INN 3 es una gran oportunidad para que la<br>comunidad inmobiliaria del norte de M\u00e9xico comparta conocimientos, establezca<br>conexiones y explore nuevas oportunidades en el sector. Con este Foro, avanzamos<br>en los objetivos que como CANADEVI Laguna nos hemos puesto: contribuir a hacer<\/p>\n\n\n\n<p>de La Laguna un polo de desarrollo inmobiliario industrial para que pueda obtener el<br>mayor beneficio del nearshoring&#8221;.<\/p>\n\n\n\n<p>El Presidente de CANADEVI Laguna agradeci\u00f3 a los patrocinadores del Foro INN 3:<br>Bancrea, Surman, VentAcero, Las Villas del Cardenchal, Banregio, Guti\u00e9rrez<br>Ferreteros, Alta Genetics, Notar\u00eda 69 y Comex. \u201cSin el apoyo de nuestros<br>patrocinadores y la gran coordinaci\u00f3n con el Gobierno de Coahuila y el Ayuntamiento<br>de Torre\u00f3n no ser\u00eda posible llevar a cabo este Foro\u201d, coment\u00f3 Pi\u00f1a \u00c1lvarez.<br>Quedan muy pocos boletos disponibles a trav\u00e9s de Boletea en <a href=\"http:\/\/www.boletea.com\" data-type=\"link\" data-id=\"http:\/\/www.boletea.com\" target=\"_blank\" rel=\"noreferrer noopener\">www.boletea.com<\/a> y<br>al tel\u00e9fono 871 722 35 25 y 26.<\/p>\n\n\n\n<p>Para mayores informes, comunicarse a CANADEVI Laguna a trav\u00e9s de<br>eventoslaguna@canadevi.com.mx o por WhatsApp: 871 465 15 16.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coah. Mi\u00e9rcoles 15 de mayo de 2024.- La C\u00e1mara Nacional de la Industria deDesarrollo y Promoci\u00f3n de Vivienda Delegaci\u00f3n Comarca Lagunera (CANADEVI Laguna)informa que todo est\u00e1 listo para la Tercera Edici\u00f3n del Foro Inmobiliario del Norte. &#8220;ElPoder de Construir el Futuro de M\u00e9xico&#8221;, para el cual quedan muy pocos boletosdisponibles para quienes deseen asistir. El Foro INN es el encuentro inmobiliario m\u00e1s importante del norte de M\u00e9xico y tienecomo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101,5,28,7],"tags":[],"class_list":["post-20600","post","type-post","status-publish","format-standard","hentry","category-canadevi","category-coahuila","category-la-laguna","category-torreon","wpcat-101-id","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=20600"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20600\/revisions"}],"predecessor-version":[{"id":20601,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20600\/revisions\/20601"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=20600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=20600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=20600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}