{"id":20764,"date":"2024-05-24T17:17:26","date_gmt":"2024-05-24T23:17:26","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=20764"},"modified":"2024-05-24T17:17:27","modified_gmt":"2024-05-24T23:17:27","slug":"se-coordinan-los-3-ordenes-de-gobierno-para-garantizar-un-proceso-electoral-en-paz","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/05\/24\/se-coordinan-los-3-ordenes-de-gobierno-para-garantizar-un-proceso-electoral-en-paz\/","title":{"rendered":"SE COORDINAN LOS 3 \u00d3RDENES DE GOBIERNO PARA GARANTIZAR UN PROCESO ELECTORAL EN PAZ."},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>Se integran el IEC y el INE&nbsp;&nbsp;a la mesa de Seguridad Estatal para coordinar la seguridad en el pr\u00f3ximo proceso electoral<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 24 de mayo de 2024.- Durante la reuni\u00f3n de la Mesa de Coordinaci\u00f3n Estatal para la Construcci\u00f3n de la Paz y Seguridad, el gobernador Manolo Jim\u00e9nez Salinas resalt\u00f3 la coordinaci\u00f3n&nbsp;&nbsp;de los tres \u00f3rdenes de gobierno de&nbsp;&nbsp;trabajar de manera estrecha para garantizar que la jornada electoral del pr\u00f3ximo 2 de junio se desarrolle en completa calma.<\/p>\n\n\n\n<p>\u201cLlevamos a cabo la Mesa de Coordinaci\u00f3n Estatal para la Construcci\u00f3n de Paz y Seguridad, donde dimos seguimiento a las estrategias de coordinaci\u00f3n para que el pr\u00f3ximo proceso electoral aqu\u00ed en Coahuila se lleve a cabo en paz y en orden. Gracias a la coordinaci\u00f3n con los tres \u00f3rdenes de gobierno hemos logrado que nuestro Estado sea un referente nacional en seguridad y estado de derecho\u201d, destac\u00f3.&nbsp;<\/p>\n\n\n\n<p>Agreg\u00f3 que en esta mesa estuvieron presentes el Instituto Electoral de Coahuila y el Instituto Nacional Electoral, quienes se sumaron a la coordinaci\u00f3n institucional para garantizar a las y los coahuilenses un proceso en paz y con tranquilidad.&nbsp;<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez pidi\u00f3 que esta coordinaci\u00f3n que ha ayudado a mantener a Coahuila como uno de los estados m\u00e1s seguros del pa\u00eds, de igual manera ayude a mantener una jornada electoral c\u00edvica y ejemplar, que es a lo que aspiran las y los coahuilenses.<\/p>\n\n\n\n<p>A esta sesi\u00f3n acudieron representantes del Instituto Nacional Electoral y del Instituto Electoral de Coahuila, quienes explicaron las diferentes acciones y actividades que se llevar\u00e1n a cabo antes, durante y despu\u00e9s del proceso electoral.<\/p>\n\n\n\n<p>Se inform\u00f3 que en Coahuila podr\u00e1n votar dos millones 410 mil 665 ciudadanos en el pr\u00f3ximo proceso electoral, y que nuestra entidad es la segunda en todo el pa\u00eds con una mayor participaci\u00f3n de ciudadanos observadores electorales, lo que habla de la participaci\u00f3n de la sociedad coahuilense en esta pr\u00f3xima jornada.<\/p>\n\n\n\n<p>Los representantes del INE y del IEC agradecieron todas las atenciones que se les ha brindado de parte de todas las instituciones federales y estatales en la preparaci\u00f3n de la pr\u00f3xima elecci\u00f3n.<\/p>\n\n\n\n<p>Asimismo, en esta Mesa de Coordinaci\u00f3n para la Construcci\u00f3n de la Paz y Seguridad se coment\u00f3 que la entrega de programas sociales, tanto federales como estatales, se han suspendido hasta despu\u00e9s de que pase el proceso electoral.<\/p>\n\n\n\n<p>De la misma manera, al tocar el tema de incendios forestales, se destac\u00f3 el \u00e9xito que ha tenido el programa de combate a \u00e9stos, luego de que los que se han suscitado en la entidad, han quedado liquidados a la brevedad gracias a la coordinaci\u00f3n y a la implementaci\u00f3n de los protocolos acordados.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez reconoci\u00f3 los resultados que se han obtenido en temas como el de seguridad y migraci\u00f3n, en los que se trabaja en coordinaci\u00f3n con las instancias federales y estatales.<\/p>\n\n\n\n<p>\u201cAgradecerles a todas las instituciones por su colaboraci\u00f3n para este pr\u00f3ximo proceso electoral; encargarles que nos apoyen a blindar Coahuila y darle seguimiento a todo lo que se platic\u00f3 este d\u00eda para que, a final de cuentas, nuestra gente pueda tener una mejor calidad de vida y que Coahuila pueda tener buenos resultados en todos los indicadores relacionados en los temas que se tocaron en esta Mesa\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez llam\u00f3 a todos quienes participan en esta mesa a&nbsp;&nbsp;continuar trabajando en total coordinaci\u00f3n, tal y como se ha hecho hasta el&nbsp;&nbsp;momento, y estar<\/p>\n\n\n\n<p>muy al pendiente en estos pocos d\u00edas que faltan para las elecciones que se desarrollar\u00e1n el 2 de junio, para&nbsp;&nbsp;mantener la paz, la tranquilidad, la estabilidad y la gobernabilidad en Coahuila.<\/p>\n\n\n\n<p>En esta reuni\u00f3n estuvieron presentes representantes de instituciones estatales, federales; mandos del Ej\u00e9rcito Mexicano, y de la Guardia Nacional; las fiscal\u00edas de la Rep\u00fablica y del Estado; los poderes Legislativo y Judicial; as\u00ed como los representantes del INE, del IEC y de la FEPADE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Se integran el IEC y el INE&nbsp;&nbsp;a la mesa de Seguridad Estatal para coordinar la seguridad en el pr\u00f3ximo proceso electoral Saltillo, Coahuila de Zaragoza; a 24 de mayo de 2024.- Durante la reuni\u00f3n de la Mesa de Coordinaci\u00f3n Estatal para la Construcci\u00f3n de la Paz y Seguridad, el gobernador Manolo Jim\u00e9nez Salinas resalt\u00f3 la coordinaci\u00f3n&nbsp;&nbsp;de los tres \u00f3rdenes de gobierno de&nbsp;&nbsp;trabajar de manera estrecha para garantizar que la jornada&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,42,15,94],"tags":[],"class_list":["post-20764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-elecciones","category-gobierno-de-coahuila","category-ine","wpcat-5-id","wpcat-42-id","wpcat-15-id","wpcat-94-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=20764"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20764\/revisions"}],"predecessor-version":[{"id":20766,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20764\/revisions\/20766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/20765"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=20764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=20764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=20764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}