{"id":20830,"date":"2024-05-29T19:10:00","date_gmt":"2024-05-30T01:10:00","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=20830"},"modified":"2024-05-29T19:10:00","modified_gmt":"2024-05-30T01:10:00","slug":"salud-municipal-fortalece-acciones-contra-garrapatas","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/05\/29\/salud-municipal-fortalece-acciones-contra-garrapatas\/","title":{"rendered":"Salud Municipal fortalece acciones contra garrapatas."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 29 de mayo de 2024.<\/p>\n\n\n\n<p>Para evitar afectaciones en personas y animales, la Direcci\u00f3n de Salud Municipal<br>implementa acciones en diferentes colonias y ejidos para prevenir y eliminar la<br>presencia de garrapatas.<\/p>\n\n\n\n<p>Jorge Mario Galv\u00e1n Zerme\u00f1o, titular de la dependencia, inform\u00f3 que la presencia<br>de garrapatas aumenta durante esta \u00e9poca del a\u00f1o, por lo que se le hace frente<br>desde la prevenci\u00f3n, con la atenci\u00f3n de los animales de compa\u00f1\u00eda en el Centro<br>Veterinario Municipal, as\u00ed como con la implementaci\u00f3n de acciones para su<br>eliminaci\u00f3n a trav\u00e9s del \u00e1rea de vectores.<\/p>\n\n\n\n<p>Dijo que esta semana y la anterior se fumigaron colonias como La Rosita, Ex<br>Hacienda La Perla, Divisi\u00f3n del Norte y La Merced, as\u00ed como los ejidos La Uni\u00f3n y<br>San Antonio de los Bravos.<\/p>\n\n\n\n<p>Adem\u00e1s, en el Centro Comunitario de la colonia La Dalia y el edificio de Seguridad<br>P\u00fablica Municipal, tambi\u00e9n se realiz\u00f3 fumigaci\u00f3n.<\/p>\n\n\n\n<p>Galv\u00e1n Zerme\u00f1o dijo que los veterinarios de la dependencia recomiendan revisar<br>de manera peri\u00f3dica a los animales, para detectar la posible presencia de<br>par\u00e1sitos y retirarlos.<\/p>\n\n\n\n<p>Agreg\u00f3 que otra medida para combatir la existencia de estos par\u00e1sitos en el<br>cuerpo de los animales, es mediante un ba\u00f1o con alg\u00fan producto especial o la<br>administraci\u00f3n peri\u00f3dica de f\u00e1rmacos desparasitantes que permitan eliminar<br>pulgas y garrapatas v\u00eda manera interna y externa.<\/p>\n\n\n\n<p>El funcionario explic\u00f3 que la garrapata es transmisora de una enfermedad<br>conocida como \u201cehrlichiosis\u201d, una infecci\u00f3n que puede contagiar tanto a animales<br>como a humanos.<\/p>\n\n\n\n<p>El director detall\u00f3 que a trav\u00e9s del \u00e1rea de vectores se realizan fumigaciones con<br>un producto que es capaz de eliminar a este tipo de par\u00e1sitos.<\/p>\n\n\n\n<p>Finalmente se\u00f1al\u00f3 que los interesados en cuidar del bienestar de sus animales o<br>solicitar el servicio de fumigaci\u00f3n pueden comunicarse al tel\u00e9fono 871 713 47 80<br>donde personal de la Direcci\u00f3n de Salud Municipal los atender\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 29 de mayo de 2024. Para evitar afectaciones en personas y animales, la Direcci\u00f3n de Salud Municipalimplementa acciones en diferentes colonias y ejidos para prevenir y eliminar lapresencia de garrapatas. Jorge Mario Galv\u00e1n Zerme\u00f1o, titular de la dependencia, inform\u00f3 que la presenciade garrapatas aumenta durante esta \u00e9poca del a\u00f1o, por lo que se le hace frentedesde la prevenci\u00f3n, con la atenci\u00f3n de los animales de compa\u00f1\u00eda en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-20830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=20830"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20830\/revisions"}],"predecessor-version":[{"id":20832,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/20830\/revisions\/20832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/20831"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=20830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=20830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=20830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}