{"id":21234,"date":"2024-06-25T18:18:15","date_gmt":"2024-06-26T00:18:15","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21234"},"modified":"2024-06-25T18:22:00","modified_gmt":"2024-06-26T00:22:00","slug":"congreso-del-estado-de-coahuila-informa-62","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/06\/25\/congreso-del-estado-de-coahuila-informa-62\/","title":{"rendered":"Congreso del Estado de Coahuila informa:"},"content":{"rendered":"\n<p>Las Diputadas y los Diputados de la Sexag\u00e9sima Tercera Legislatura del<br>Congreso del Estado de Coahuila de Zaragoza, llevaron a cabo el d\u00eda de hoy la<br>D\u00e9cima Octava Sesi\u00f3n del Primer Periodo Ordinario de Sesiones, correspondiente<br>al Primer A\u00f1o de Ejercicio Constitucional.<\/p>\n\n\n\n<p>En esta Sesi\u00f3n Diputados y Diputadas, presentaron las siguientes<br>Iniciativas:<\/p>\n\n\n\n<p>1.- Iniciativa con Proyecto de Decreto que plantea se adicione un \u00faltimo<br>p\u00e1rrafo al art\u00edculo 7\u00ba de la Constituci\u00f3n Pol\u00edtica del Estado de Coahuila de<br>Zaragoza.<\/p>\n\n\n\n<p>2.- Iniciativa con Proyecto de Decreto para reformar diversas disposiciones<br>de la Ley de Turismo del Estado<\/p>\n\n\n\n<p>3.- Iniciativa con Proyecto de Decreto que propone reformar la fracci\u00f3n<br>XXVII y adicionar la fracci\u00f3n XXVIII del art\u00edculo 9, de la Ley Estatal de Educaci\u00f3n<br>del Estado.<\/p>\n\n\n\n<p>4.- Iniciativa con Proyecto de Decreto para que se adicionen, la fracci\u00f3n VIII<br>al art\u00edculo 56, y la fracci\u00f3n V al art\u00edculo 59, de la Ley Estatal de Salud.<\/p>\n\n\n\n<p>5.- Propuesta de Iniciativa con Proyecto de Decreto que plantea se reforme<br>la Ley General en Materia de Desaparici\u00f3n Forzada de Personas, Desaparici\u00f3n<br>Cometida por Particulares y del Sistema Nacional de B\u00fasqueda de Personas.<\/p>\n\n\n\n<p>6.- Iniciativa con Proyecto de Decreto que plantea se adicione el inciso d) a<br>la fracci\u00f3n I del art\u00edculo 5; y, se reformen el inciso f) de la fracci\u00f3n II y el inciso c)<br>de la fracci\u00f3n V del art\u00edculo 18, as\u00ed como la fracci\u00f3n II del art\u00edculo 22, de la Ley<br>para el Impulso Emprendedor del Estado.<\/p>\n\n\n\n<p>Las Diputadas y los Diputados aprobaron por unanimidad de votos, los<br>siguientes dict\u00e1menes:<\/p>\n\n\n\n<p>1.- Dictamen de la Comisi\u00f3n de Hacienda con Proyecto de Decreto por el<br>que se reforma el Decreto n\u00famero 646 publicado en el Peri\u00f3dico Oficial del<br>Gobierno del Estado de fecha 22 de diciembre de 2023, mediante el cual se<br>aprobaron las Tablas de Valores Unitarios de Suelo y Construcci\u00f3n del Municipio<br>de General Cepeda, Coahuila, para el Ejercicio Fiscal 2024, con objeto de derogar<br>la \u201cTabla de Valores para Explotaci\u00f3n de Energ\u00eda E\u00f3lica\u201d.<\/p>\n\n\n\n<p>2.- Dictamen de la Comisi\u00f3n de J\u00f3venes y Ni\u00f1ez, con Proyecto de Decreto<br>por el que se reforma el segundo p\u00e1rrafo del Art\u00edculo 8 de la Ley del Sistema<br>Estatal para la Garant\u00eda de los Derechos Humanos de Ni\u00f1os y Ni\u00f1as del Estado<br>de Coahuila de Zaragoza, con objeto de establecer que el Consejo para la<br>Garant\u00eda de los Derechos Humanos de Ni\u00f1as y Ni\u00f1os contar\u00e1 con una Secretar\u00eda<br>Ejecutiva, la cual estar\u00e1 a cargo de la Procuradur\u00eda para Ni\u00f1os, Ni\u00f1as y la Familia<br>del Estado de Coahuila de Zaragoza, a iniciativa del Gobernador Constitucional<br>del Estado, Ingeniero Manolo Jim\u00e9nez Salinas.<\/p>\n\n\n\n<p>3.- Dictamen de la Comisi\u00f3n de Educaci\u00f3n, Cultura, Familias, Desarrollo<br>Humano y Actividades C\u00edvicas, con Proyecto de Decreto para que se inscriba con<br>letras doradas en el Muro de Honor del Sal\u00f3n de Sesiones del Recinto Oficial del<br>Congreso del Estado, la siguiente leyenda: \u201cCoahuila, 200 A\u00f1os de Grandeza\u201d, a<br>iniciativa del Gobernador Constitucional del Estado, Ingeniero Manolo Jim\u00e9nez<br>Salinas.<\/p>\n\n\n\n<p>Asimismo, el Proyecto de Decreto se\u00f1ala que el Pleno del Congreso del<br>Estado definir\u00e1 la fecha y el protocolo que se llevar\u00e1 a cabo, para cumplir con lo<br>se\u00f1alado en el Art\u00edculo \u00danico de este Decreto. Asimismo, la inscripci\u00f3n con letras<br>doradas en el Muro de Honor se har\u00e1 en sesi\u00f3n solemne, a la cual concurrir\u00e1n<br>los representantes del Poder Ejecutivo, Poder Legislativo y Poder Judicial, as\u00ed<br>como los dem\u00e1s que se consideren por parte del Pleno del Congreso del Estado.<\/p>\n\n\n\n<p>El Ejecutivo del Estado, en la exposici\u00f3n de motivos de su iniciativa, entre<br>otras cosas se\u00f1ala: \u201cUn Estado rico en historia y semillero de grandes personajes<br>ilustres para lo que hoy es nuestro pa\u00eds, y este a\u00f1o 2024, se cumplen los primeros<br>200 a\u00f1os de su integraci\u00f3n como parte de la federaci\u00f3n mexicana, por lo que esta<br>fecha no debe pasar desapercibida en el Estado, siendo este gran acontecimiento<br>parte medular de lo que hoy buscamos para mejorar el futuro como pa\u00eds. Por lo<br>anterior, en el marco del Bicentenario de Coahuila, y como recordatorio<br>permanente para todos los ciudadanos, de la lucha continua que se ha vivido para<br>consolidar al Estado y al pa\u00eds en lo que ahora somos, se propone la<br>inmortalizaci\u00f3n de este gran suceso a trav\u00e9s de su inscripci\u00f3n en letras doradas<br>en el recinto que alberga el Poder Legislativo de nuestro Estado\u201d.<\/p>\n\n\n\n<p>4.- Dictamen con Punto de Acuerdo de la Comisi\u00f3n de Educaci\u00f3n, Cultura,<br>Familias, Desarrollo Humano y Actividades C\u00edvicas, con el objeto de exhortar<br>respetuosamente a la Titular de la Secretar\u00eda de Educaci\u00f3n P\u00fablica del Gobierno<br>Federal, para que fortalezca las medidas de implementaci\u00f3n y seguimiento de los<br>lineamientos, para el protocolo de erradicaci\u00f3n del acoso escolar en educaci\u00f3n<br>b\u00e1sica (preescolar, primaria y secundaria), incorporando al efecto, los programas y<br>proyectos necesarios a fin de que responda de manera decisiva a prevenir,<br>identificar y erradicar la violencia escolar en todo el pa\u00eds.<\/p>\n\n\n\n<p>Por otra parte, las Diputadas y los Diputados presentaron diversas<br>proposiciones con Punto de las cuales se aprobaron las siguientes, al<br>considerarse como de urgente y obvia resoluci\u00f3n:<\/p>\n\n\n\n<p>1.- Proposici\u00f3n con Punto de Acuerdo para hacer un atento exhorto al<br>Banco de M\u00e9xico, as\u00ed como al Banco del Bienestar, para que realicen convenios<br>con otras instituciones bancarias y\/o cadenas comerciales, para evitar el cobro de<br>comisiones, y ampliar las opciones para retiro y consulta de los beneficiarios de la<br>Pensi\u00f3n del Bienestar<\/p>\n\n\n\n<p>2.- Proposici\u00f3n con Punto de Acuerdo para exhortar respetuosamente a la<br>Secretar\u00eda de Seguridad P\u00fablica del Estado a establecer medidas para prevenir<br>los delitos de violencia de g\u00e9nero, acoso y delitos contra la salud en universidades<br>del estado.<\/p>\n\n\n\n<p>3.- Proposici\u00f3n con Punto de Acuerdo para exhortar a los 38 Municipios del<br>Estado a fin de que, conforme a sus atribuciones, expidan, o en su caso,<br>actualicen sus reglamentos de protecci\u00f3n civil.<\/p>\n\n\n\n<p>4.-Proposici\u00f3n con Punto de Acuerdo con objeto de exhortar<br>respetuosamente a los 38 Ayuntamientos del Estado a fin de que, a trav\u00e9s de sus<br>direcciones correspondientes y en coordinaci\u00f3n con las c\u00e1maras y grupos<br>empresariales, impulsen talleres de informaci\u00f3n sobre la apertura de negocios y<br>comercios con el objetivo de impulsar el emprendimiento local.<\/p>\n\n\n\n<p>5.- Proposici\u00f3n con Punto de Acuerdo con el fin de exhortar<br>respetuosamente a la Secretar\u00eda de Educaci\u00f3n P\u00fablica, a la Secretar\u00eda de<br>Bienestar, a la Secretar\u00eda de Cultura, al Sistema Nacional para el Desarrollo<br>Integral de la Familia (DIF Nacional), a la Comisi\u00f3n Nacional de Cultura F\u00edsica y<br>Deporte y a la Subsecretar\u00eda de Derechos Humanos de la Secretar\u00eda de<br>Gobernaci\u00f3n del Gobierno Federal, as\u00ed como a la Comisi\u00f3n Nacional de Derechos<br>Humanos, para que en el \u00e1mbito de sus respectivas atribuciones y en su<br>constante compromiso con la promoci\u00f3n de los derechos humanos de las ni\u00f1as,<br>ni\u00f1os y adolescentes y en cumplimiento de los art\u00edculos 4\u00b0 y 7\u00b0 de la Constituci\u00f3n<br>Pol\u00edtica de los Estados Unidos Mexicanos, coadyuven con las autoridades locales<br>respectivas, para garantizar una oferta integral de cursos de verano incluyentes y<br>con disponibilidad suficiente, dirigidos a la infancias y adolescencia y se evite<br>cualquier forma de discriminaci\u00f3n por motivos sociales o econ\u00f3micos, en el<br>Estado.<\/p>\n\n\n\n<p>6.- Proposici\u00f3n con Punto de Acuerdo para exhortar respetuosamente al<br>Ejecutivo Federal a que, a trav\u00e9s de las instancias correspondientes y en<br>coordinaci\u00f3n con el estado y los municipios, consolide mediante el pr\u00f3ximo<br>presupuesto de egresos, los recursos necesarios para la creaci\u00f3n de centros<br>especializados en tratamiento, atenci\u00f3n y rehabilitaci\u00f3n en materia de<br>farmacodependencia, con el fin de garantizar la atenci\u00f3n definida en el programa<br>contra la farmacodependencia de la Ley General de Salud.<\/p>\n\n\n\n<p>7.- Proposici\u00f3n con Punto de Acuerdo con objeto de exhortar al titular de la<br>Secretar\u00eda de la Defensa Nacional, as\u00ed como a la titular de Protecci\u00f3n Civil<br>Nacional para que en coordinaci\u00f3n con las instancias de protecci\u00f3n civil de<br>Coahuila, se elabore un plan integral para prevenir, hasta donde sea posible,<br>todas las afectaciones generadas por la temporada de huracanes, incluyendo los<br>planes necesarios para atender de manera oportuna los problemas que se<br>presenten de forma inevitable.<\/p>\n\n\n\n<p>En esta D\u00e9cima Octava Sesi\u00f3n se realiz\u00f3 la elecci\u00f3n de la Diputaci\u00f3n<br>Permanente que estar\u00e1 en funciones durante el Segundo Periodo, los meses de<br>julio y agosto de 2024, del Primer A\u00f1o de Ejercicio Constitucional de la<br>Sexag\u00e9sima Tercera Legislatura, integrada en la forma siguiente:<\/p>\n\n\n\n<p>Cargo Propietario Suplente<br>Presidencia: Beatriz Eugenia Fraustro D\u00e1vila Guillermo Ruiz Guerra<br>Vicepresidencia: Gerardo Abraham Aguado G\u00f3mez Blanca Rub\u00ed Lamas Vel\u00e1zquez<br>Secretar\u00eda: Jos\u00e9 Alberto Hurtado Vera Antonio Attolini Murra<br>Secretar\u00eda: Norma Garc\u00eda Mariscal Olivia Mart\u00ednez Leyva<br>Vocal\u00eda: Ra\u00fal Onofre Contreras Sergio Zen\u00f3n Vel\u00e1zquez V\u00e1zquez<br>Vocal\u00eda: Claudia Elizabeth Aldrete Garc\u00eda Jes\u00fas Alfredo Paredes L\u00f3pez<br>Vocal\u00eda: Magaly Hern\u00e1ndez Aguirre Delia Aurora Hern\u00e1ndez<\/p>\n\n\n\n<p>Alvarado<\/p>\n\n\n\n<p>Vocal\u00eda: Felipe Eduardo Gonz\u00e1lez Miranda Mar\u00eda Guadalupe Oyervides<\/p>\n\n\n\n<p>Valdez<\/p>\n\n\n\n<p>Vocal\u00eda Jorge Arturo Vald\u00e9s Flores Antonio Flores Guerra<br>Vocal\u00eda Edna Ileana D\u00e1valos Elizondo \u00c1lvaro Moreira Vald\u00e9s<br>Vocal\u00eda Mar\u00eda del Mar Trevi\u00f1o Garza Luz Elena Guadalupe Morales<br>N\u00fa\u00f1ez<\/p>\n\n\n\n<p>Una vez electa la Diputaci\u00f3n Permanente, se aprob\u00f3 la expedici\u00f3n del<br>Acuerdo para autorizarla a que tramite y resuelva los asuntos pendientes y los<br>que se presenten durante su funcionamiento, con excepci\u00f3n de los que requieran<br>estrictamente la intervenci\u00f3n directa del Pleno del Congreso y de los<br>correspondientes a iniciativas para la expedici\u00f3n o reforma de leyes.<\/p>\n\n\n\n<p>Acto seguido, el Presidente de la Mesa Directiva, Diputado Jes\u00fas Alfredo<br>Paredes L\u00f3pez procedi\u00f3 a clausurar el Primer Per\u00edodo Ordinario de Sesiones,<br>comprendido del 1 de marzo al 30 de junio de 2024, correspondiente al Primer<\/p>\n\n\n\n<p>A\u00f1o de Ejercicio Constitucional de la Sexag\u00e9sima Tercera Legislatura, y<br>mandamiento para la expedici\u00f3n del Acuerdo en que se d\u00e9 cuenta de lo anterior y<br>se disponga informar a los Poderes Ejecutivo y Judicial del Estado, sobre la<br>clausura de este per\u00edodo.<\/p>\n\n\n\n<p>Finalmente, la Diputada Beatriz Eugenia Fraustro D\u00e1vila procedi\u00f3 a hacer<br>la declaratoria de instalaci\u00f3n de la Diputaci\u00f3n Permanente y se cit\u00f3 a las y los<br>diputados integrantes de la misma, para sesionar a las 11:00 horas del martes 2<br>de julio de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Diputadas y los Diputados de la Sexag\u00e9sima Tercera Legislatura delCongreso del Estado de Coahuila de Zaragoza, llevaron a cabo el d\u00eda de hoy laD\u00e9cima Octava Sesi\u00f3n del Primer Periodo Ordinario de Sesiones, correspondienteal Primer A\u00f1o de Ejercicio Constitucional. En esta Sesi\u00f3n Diputados y Diputadas, presentaron las siguientesIniciativas: 1.- Iniciativa con Proyecto de Decreto que plantea se adicione un \u00faltimop\u00e1rrafo al art\u00edculo 7\u00ba de la Constituci\u00f3n Pol\u00edtica del Estado de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,21],"tags":[],"class_list":["post-21234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-congreso-del-estado","wpcat-5-id","wpcat-21-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21234"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21234\/revisions"}],"predecessor-version":[{"id":21235,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21234\/revisions\/21235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/21239"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}