{"id":21276,"date":"2024-06-27T19:43:55","date_gmt":"2024-06-28T01:43:55","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21276"},"modified":"2024-06-27T19:43:55","modified_gmt":"2024-06-28T01:43:55","slug":"presentan-programa-torreon-seguro","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/06\/27\/presentan-programa-torreon-seguro\/","title":{"rendered":"Presentan programa &#8220;Torre\u00f3n Seguro&#8221;."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.- &#8220;Torre\u00f3n Seguro&#8221;,\u00a0 campa\u00f1a\u00a0 preventiva\u00a0 para la atenci\u00f3n y la\u00a0 erradicaci\u00f3n de la violencia contra las mujeres, que esta ma\u00f1ana\u00a0 se dieron a conocer las estrategias y \u00a0la promoci\u00f3n publicitaria \u00a0 bajo la cual se estar\u00e1 desarrollando en este municipio, ante el crecimiento\u00a0 en ascenso de las estad\u00edsticas que dan seguimiento de tal tema.<\/p>\n\n\n\n<p>En rueda de prensa encabezada por la Secretaria del Ayuntamiento, Licenciada Natalia Fern\u00e1ndez, \u00a0 acompa\u00f1ada de la\u00a0 Subsecretaria de la\u00a0 Secretar\u00eda de la Mujer en el Estado Maribel\u00a0 Rodr\u00edguez, la\u00a0 Directora\u00a0 del Instituto\u00a0 Municipal de las Mujeres, licenciada\u00a0 Andrea Hern\u00e1ndez y el Comisario C\u00e9sar Antonio Perales Esparza\u00a0de la Direcci\u00f3n de Seguridad\u00a0 P\u00fablica,\u00a0 y el Director de Comunicaci\u00f3n Gubernamental Luis Rayas que estar\u00e1n trabajando en estrecha coordinaci\u00f3n \u00a0 para implementar y\u00a0 verificar los impactos que se alcancen\u00a0 en\u00a0 este tema.<\/p>\n\n\n\n<p>Toc\u00f3 a la Licenciada Fern\u00e1ndez, dar a conocer algunas de las estad\u00edsticas que registra el Instituto Municipal de las Mujeres al tema\u00a0 motivo del encuentro medi\u00e1tico, entre las que destac\u00f3 las relativas a\u00a0 atenci\u00f3n emocional\u00a0 y atenci\u00f3n jur\u00eddicas, aportadas de manera cotidiana en la instituci\u00f3n citada y que ambas \u00a0 suman a la fecha en este a\u00f1o, 324\u00a0 mujeres.\u00a0<\/p>\n\n\n\n<p>La mayor\u00eda de los casos atendidos,\u00a0 tienen como motivo \u00a0 seg\u00fan denuncias a violencia psicol\u00f3gica, violencia f\u00edsica en un\u00a070%  de violencia sexual y violencia dom\u00e9stica\u00a0 en un 30%.<\/p>\n\n\n\n<p>Indic\u00f3 luego que &#8220;las acciones previstas, de orden\u00a0 psicol\u00f3gico para el\u00a0 a\u00f1o 2022, eran mil atenciones\u00a0 y en el \u00e1rea jur\u00eddica, eran 500, pero tuvimos ese a\u00f1o\u00a0 en el primer caso\u00a0 915 \u00a0 y 695 jur\u00eddicas. Este incremento importante aumento en el 2023, con 2,522 atenciones y 736 atenciones jur\u00eddicas y\u00a0 en lo que va del a\u00f1o 1,357 psicol\u00f3gicas y 494 jur\u00eddicas, lo que nos hace esperar que en estos temas registremos al t\u00e9rmino\u00a0 del presente a\u00f1o un aumento del 200%&#8221;.<\/p>\n\n\n\n<p>En relaci\u00f3n\u00a0 a c\u00f3mo se est\u00e1 atendiendo el tema de la violencia en este municipio, inform\u00f3 que\u00a0&#8220;se realiza a trav\u00e9s de la Unidad de V\u00edctimas de la violencia a cargo de la Direcci\u00f3n de Seguridad P\u00fablica, las cuales atienden\u00a0 casos de emergencia\u00a0 luego de solicitar\u00a0 intervenci\u00f3n de la posible v\u00edctima a trav\u00e9s del 911, que \u00a0 verificadas son canalizadas posteriormente al Ministerio P\u00fablico&#8221;.<\/p>\n\n\n\n<p>&#8220;En la Unidad de Atenci\u00f3n a V\u00edctimas \u00a0 tiene capacitaci\u00f3n\u00a0 y el entrenamiento necesario para atender\u00a0 \u00a0 y canalizarlas\u00a0 al Centro de Justicia y Empoderamiento de la Mujer&#8221;.\u00a0<\/p>\n\n\n\n<p>Revel\u00f3 luego otras cifras preocupantes, &#8220;el aumento hasta de un 40 %\u00a0 que acuden\u00a0 en demanda de\u00a0 conducci\u00f3n y auxilio al Instituto Municipal de la Mujer&#8221;.<\/p>\n\n\n\n<p><strong>TORRE\u00d3N SEGURO.<\/strong><\/p>\n\n\n\n<p>Ante\u00a0 la contundencia de las cifras antes citadas\u00a0 y asumiendo la responsabilidad\u00a0 que corresponde en el tema a las autoridades, se presenta, &#8220;Torre\u00f3n Seguro&#8221;\u00a0 tiene  ya en\u00a0 operaci\u00f3n, acceso inmediato, desde un celular\u00a0 con la aplicaci\u00f3n\u00a0 digital &#8220;Torre\u00f3n Seguro&#8221; \u00a0 ante situaciones de violencia\u00a0 podr\u00e1n acceder a solicitar \u00a0 auxilio y canalizar, seg\u00fan\u00a0 a la\u00a0 Unidad de Atenci\u00f3n a\u00a0 V\u00edctimas, o bien\u00a0 seg\u00fan sea el caso\u00a0 a un Ministerio P\u00fablico.\u00a0<\/p>\n\n\n\n<p>Correspondi\u00f3 luego a la titular del Instituto Municipal de las Mujeres Licenciada Andrea Herrn\u00e1ndez\u00a0 ampliar los contenidos\u00a0 diciendo que la instituci\u00f3n a su cargo, ha incrementado un 40% la atenci\u00f3n a v\u00edctimas y a trav\u00e9s de entrevistas se canalizan a otras instituciones especializadas en su atenci\u00f3n.<\/p>\n\n\n\n<p>Violencia y hostigamientos se registran tanto en el espacio p\u00fablico como en el privado\u00a0 y tiene m\u00faltiples factores, afirmando\u00a0 luego que &#8220;la violencia no distingue, por lo tanto es\u00a0 problema que no se puede resolver por una persona, sino que requiere de esfuerzos colectivos&#8221;.<\/p>\n\n\n\n<p>Por su parte, el\u00a0 titular de la Direcci\u00f3n de Seguridad P\u00fablica, Comandante C\u00e9sar Antonio Perales Esparza \u00a0 afirm\u00f3 trabajar en estrecha\u00a0 coordinaci\u00f3n con las instituciones participantes en este programa, en especial desempe\u00f1ando de manera importante el acompa\u00f1amiento\u00a0 y\u00a0 custodia que\u00a0 prestan a las mujeres v\u00edctimas de violencia\u00a0 familiar o de pareja,\u00a0 asi como dar el servicio requerido que\u00a0 se\u00a0 genere a trav\u00e9s de llamada\u00a0 al 911 o a otros tel\u00e9fonos de la Direcci\u00f3n a su cargo.<\/p>\n\n\n\n<p>Cit\u00f3 luego la aplicaci\u00f3n &#8220;Torre\u00f3n Seguro&#8221;,\u00a0 que actua cual bot\u00f3n de p\u00e1nico, que puesto en marcha genera una respuesta inmediata por parte de quienes integran el grupo especializado en la atenci\u00f3n de este tema, al interior de la DSPM.<\/p>\n\n\n\n<p>Tuvo luego breve intervenci\u00f3n, enfatizando la tarea de coordinaci\u00f3n en todo el Estado de las pol\u00edticas que el gobierno\u00a0 estatal\u00a0 han puesto en marcha a trav\u00e9s de la Secretar\u00eda de la Mujer, de la\u00a0 cual es\u00a0 Subsecretaria la licenciada\u00a0 Maribel Rodr\u00edguez, cerrando las participaciones\u00a0 el\u00a0 Licenciado Luis Rayas,\u00a0 que dio a conocer los\u00a0 mecanismos de distribuci\u00f3n de la promoci\u00f3n\u00a0 que profundice el conocimiento\u00a0 y acceso de las mujeres que asi lo requieran a este programa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.- &#8220;Torre\u00f3n Seguro&#8221;,\u00a0 campa\u00f1a\u00a0 preventiva\u00a0 para la atenci\u00f3n y la\u00a0 erradicaci\u00f3n de la violencia contra las mujeres, que esta ma\u00f1ana\u00a0 se dieron a conocer las estrategias y \u00a0la promoci\u00f3n publicitaria \u00a0 bajo la cual se estar\u00e1 desarrollando en este municipio, ante el crecimiento\u00a0 en ascenso de las estad\u00edsticas que dan seguimiento de tal tema. En rueda de prensa encabezada por la Secretaria del Ayuntamiento, Licenciada Natalia Fern\u00e1ndez, \u00a0 acompa\u00f1ada&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,48,28,24,7],"tags":[],"class_list":["post-21276","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-genero","category-la-laguna","category-seguridad","category-torreon","wpcat-5-id","wpcat-48-id","wpcat-28-id","wpcat-24-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21276"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21276\/revisions"}],"predecessor-version":[{"id":21277,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21276\/revisions\/21277"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}