{"id":21297,"date":"2024-06-30T20:39:24","date_gmt":"2024-07-01T02:39:24","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21297"},"modified":"2024-06-30T20:39:25","modified_gmt":"2024-07-01T02:39:25","slug":"se-esperan-lluvias-fuertes-en-algunas-regiones-de-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/06\/30\/se-esperan-lluvias-fuertes-en-algunas-regiones-de-coahuila\/","title":{"rendered":"SE ESPERAN LLUVIAS FUERTES EN ALGUNAS REGIONES DE COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; 30 de junio de 2024 &#8211; La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) informa que, para esta tarde, se esperan intervalos de chubascos con lluvias puntuales fuertes en las regiones Sureste, Laguna, Centro y Carbon\u00edfera, adem\u00e1s de la posibilidad de vientos con rachas de entre 50 a 70 km\/h con posibles tolvaneras en Coahuila.<\/p>\n\n\n\n<p>Seg\u00fan el pron\u00f3stico del Servicio Meteorol\u00f3gico Nacional (SMN), se esperan temperaturas m\u00e1ximas de 35 a 40 \u00b0C, adem\u00e1s de que las lluvias podr\u00edan provocar encharcamientos, inundaciones y deslaves, incremento en los niveles de r\u00edos y arroyos, as\u00ed como ca\u00eddas de \u00e1rboles y anuncios.<\/p>\n\n\n\n<p>Se recomienda a la poblaci\u00f3n mantenerse informada y seguir las indicaciones de las autoridades.<\/p>\n\n\n\n<p>La tormenta Beryl se ha intensificado y se ha convertido en hurac\u00e1n; se encuentra a 3,700 km al este-sureste de las costas de Quintana Roo. Por el momento, no representa peligro para el territorio mexicano.<\/p>\n\n\n\n<p>Ante la ola de calor, Protecci\u00f3n Civil emite las siguientes recomendaciones:<\/p>\n\n\n\n<p>Evitar exponerse entre las 11 AM y las 4 PM, ya que durante ese periodo se alcanzan las temperaturas m\u00e1s altas.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Usar ropa de tonos claros y de preferencia manga larga.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Tomar abundantes l\u00edquidos, de preferencia agua simple, aun cuando no se tenga sed.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Usar bloqueador solar con FPS mayor a 15.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;No realizar actividades bajo el sol.<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Evitar realizar ejercicio intenso en las horas m\u00e1s intensas de sol.<\/p>\n\n\n\n<p>Ante el pron\u00f3stico de lluvia y fuertes vientos, se exhorta a la poblaci\u00f3n a tomar precauciones y estar atenta a los avisos emitidos por el Servicio Meteorol\u00f3gico Nacional.<\/p>\n\n\n\n<p>EN TU VIVIENDA<\/p>\n\n\n\n<p>&#8211; Cierra y asegura puertas, ventanas o toldos.<\/p>\n\n\n\n<p>&#8211; Retira todos aquellos objetos que puedan caer a la calle y provocar un accidente.<\/p>\n\n\n\n<p>&#8211; Si los vidrios de las ventanas no son tan fuertes, coloca cinta adhesiva transparente en la parte interior para evitar que al romperse los vidrios provoquen da\u00f1os.<\/p>\n\n\n\n<p>&#8211; Evita salir de casa si no es necesario.<\/p>\n\n\n\n<p>EN LA CALLE O EL CAMPO<\/p>\n\n\n\n<p>&#8211; Al\u00e9jate de cornisas, muros o \u00e1rboles que puedan desprenderse.<\/p>\n\n\n\n<p>&#8211; Toma precauciones frente a edificaciones en construcci\u00f3n o en mal estado.<\/p>\n\n\n\n<p>&#8211; Abstente de subir andamios sin las adecuadas medidas de protecci\u00f3n.<\/p>\n\n\n\n<p>&#8211; No te resguardes del viento en zonas cercanas a muros, \u00e1rboles o edificios en mal estado o en construcci\u00f3n.<\/p>\n\n\n\n<p>SI EST\u00c1S CONDUCIENDO<\/p>\n\n\n\n<p>&#8211; Evita manejar por \u00e1reas inundadas y agua estancada.<\/p>\n\n\n\n<p>&#8211; Ten precauci\u00f3n, ya que son frecuentes los cortes en v\u00edas debido a la ca\u00edda de \u00e1rboles y cables el\u00e9ctricos.<\/p>\n\n\n\n<p>&#8211; Conduce con precauci\u00f3n debido a la posibilidad de formaci\u00f3n de nubes de polvo.<\/p>\n\n\n\n<p>&#8211; Si tu auto se ve afectado por la fuerza del viento, evita los rebases y ten precauci\u00f3n en los cruces y puentes.<\/p>\n\n\n\n<p>&#8211; Conduce con precauci\u00f3n, disminuyendo la velocidad y con las luces encendidas si la visibilidad es escasa.<\/p>\n\n\n\n<p>&#8211; Ten precauci\u00f3n al adelantar veh\u00edculos de carga pesada, ya que pueden hacer movimientos imprevistos.<\/p>\n\n\n\n<p>&#8211; Localiza con anticipaci\u00f3n los Refugios Temporales habilitados por las autoridades en la p\u00e1gina&nbsp;<a href=\"http:\/\/proteccioncivil.sfpcoahuila.gob.mx\/modulo22.php?opcion=8\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/proteccioncivil.sfpcoahuila.gob.mx\/modulo22.php?opcion=8<\/a>.<\/p>\n\n\n\n<p>En caso de emergencia, la ciudadan\u00eda puede llamar al 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; 30 de junio de 2024 &#8211; La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado (PC) informa que, para esta tarde, se esperan intervalos de chubascos con lluvias puntuales fuertes en las regiones Sureste, Laguna, Centro y Carbon\u00edfera, adem\u00e1s de la posibilidad de vientos con rachas de entre 50 a 70 km\/h con posibles tolvaneras en Coahuila. Seg\u00fan el pron\u00f3stico del Servicio Meteorol\u00f3gico Nacional (SMN), se esperan temperaturas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5,15,54],"tags":[],"class_list":["post-21297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","category-coahuila","category-gobierno-de-coahuila","category-proteccion-civil","wpcat-27-id","wpcat-5-id","wpcat-15-id","wpcat-54-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21297"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21297\/revisions"}],"predecessor-version":[{"id":21299,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21297\/revisions\/21299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/21298"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}