{"id":21444,"date":"2024-07-09T19:09:59","date_gmt":"2024-07-10T01:09:59","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21444"},"modified":"2024-07-09T19:09:59","modified_gmt":"2024-07-10T01:09:59","slug":"anuncia-alcalde-reestructuracion-administrativa-en-direcciones-del-ayuntamiento","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/07\/09\/anuncia-alcalde-reestructuracion-administrativa-en-direcciones-del-ayuntamiento\/","title":{"rendered":"Anuncia alcalde reestructuraci\u00f3n administrativa en Direcciones del Ayuntamiento."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila.- El alcalde\u00a0 Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, anuncia a solo\u00a0poco menos de seis meses de concluir su actual periodo, que este mismo a\u00f1o, realizara toda una reestructura administrativa, en todas sus Direcciones\u00a0y todo el ordenamiento vigente en este municipio\u00a0 que obedezca a un Torre\u00f3n\u00a0 que se ajuste a los a\u00f1os venideros, y que puede abarcar desde el pr\u00f3ximo 20\/25, hasta el 20\/40.<\/p>\n\n\n\n<p>Agreg\u00f3 que tales cambios, &#8220;no significan que los temas cambien, pues seguir\u00e1n siendo los mismos porque las necesidades de Torre\u00f3n\u00a0 en materia de obra p\u00fablica, servicios\u00a0 p\u00fablicos, salud, desarrollo\u00a0 econ\u00f3mico, seguridad, son temas hist\u00f3ricos&#8221;.<\/p>\n\n\n\n<p>Se plane\u00f3, dijo, &#8220;una Direcci\u00f3n en funci\u00f3n de las necesidades de un Torre\u00f3n de 1980, o del 1970, pero estamos en el 2025 pr\u00e1cticamente y esto anticipa\u00a0 un mejoramiento, eficiencia, pero lo importante es estar adecuado a lo que la ciudadan\u00eda necesita&#8221;.\u00a0<\/p>\n\n\n\n<p>En lo financiero, manifest\u00f3, &#8220;el estudio va dirigido\u00a0 a recapitular el Presupuesto\u00a0 en lo que se ocupe, pero tambi\u00e9n en funci\u00f3n de una estructura operativa administrativa que de a la ciudadan\u00eda un mejor servicio&#8221;.<\/p>\n\n\n\n<p>&#8220;Todo esto\u00a0 es para mejorar, menos tramites, modernizaci\u00f3n, pues as\u00ed como hemos hecho una eficiencia recaudatoria, \u00a0 hay que hacer un mejoramiento administrativo&#8221;.<\/p>\n\n\n\n<p>En relaci\u00f3n si estos cambios van en concordancia\u00a0 con los cambios que su vez\u00a0 anuncia y ya pone en marcha el gobierno del Estado\u00a0 esa misma semana:\u00a0<\/p>\n\n\n\n<p>&#8220;Mira, lo que yo creo y estoy convencido\u00a0 de que con esto, le podemos ayudar a que el Gobernador -Jim\u00e9nez \u00a0 Salinas-, que es nuestro gran aliado pueda descansar,\u00a0 porque en Torre\u00f3n estamos haciendo las cosas de manera eficiente\u00a0 tanto en la parte que es m\u00e1s compleja, que es la de seguridad, obra p\u00fablica para poder coordinar los esfuerzos como lo hemos venido haciendo hasta ahorita y que el Gobernador sienta que en Torre\u00f3n tiene un aliado, un amigo que est\u00e1 haciendo bien las cosas, una administraci\u00f3n comprometida\u00a0 con la sociedad&#8221;.<\/p>\n\n\n\n<p>Inform\u00f3 incluso que las comisiones del cabildo trabajan ya en los cambios en marcha, &#8220;precisamente\u00a0 estamos haciendo un estudio comparativo, con otros municipios del pa\u00eds o de otros lugares que pueden ser los m\u00e1s modernos en funci\u00f3n de su operaci\u00f3n, adecuar a Torre\u00f3n,\u00a0 que esto se pueda empatar en los estudios que est\u00e1n haciendo\u00a0 las Direcciones, el IMPLAN y\u00a0 los integrantes del cabildo&#8221;.<\/p>\n\n\n\n<p>Anticip\u00f3 que tales cambios tendr\u00e1n como consecuencia que algunas de las actuales direcciones, crezcan y otras se fusionen.<\/p>\n\n\n\n<p>El objetivo, reiter\u00f3, &#8220;es constru\u00edr una administraci\u00f3n\u00a0 moderna, con miras al 2040&#8221;.<\/p>\n\n\n\n<p>No dej\u00f3 de \u00a0 indicar que &#8220;el presupuesto -federal- nos lo van a recortar y la unica forma de\u00a0 que podamos seguir haciendo lo mismo, es con eficiencia administrativa,\u00a0 recaudatoria\u00a0 y financiera. No hay de otra&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila.- El alcalde\u00a0 Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, anuncia a solo\u00a0poco menos de seis meses de concluir su actual periodo, que este mismo a\u00f1o, realizara toda una reestructura administrativa, en todas sus Direcciones\u00a0y todo el ordenamiento vigente en este municipio\u00a0 que obedezca a un Torre\u00f3n\u00a0 que se ajuste a los a\u00f1os venideros, y que puede abarcar desde el pr\u00f3ximo 20\/25, hasta el 20\/40. Agreg\u00f3 que tales cambios, &#8220;no significan que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-21444","post","type-post","status-publish","format-standard","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21444"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21444\/revisions"}],"predecessor-version":[{"id":21445,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21444\/revisions\/21445"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}