{"id":21508,"date":"2024-07-14T22:49:20","date_gmt":"2024-07-15T04:49:20","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21508"},"modified":"2024-07-14T22:49:21","modified_gmt":"2024-07-15T04:49:21","slug":"dara-ciudad-judicial-mejor-atencion-a-la-gente","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/07\/14\/dara-ciudad-judicial-mejor-atencion-a-la-gente\/","title":{"rendered":"DAR\u00c1 CIUDAD JUDICIAL MEJOR ATENCI\u00d3N A LA GENTE."},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>El proyecto integral de la Ciudad Judicial mejorar\u00e1 la atenci\u00f3n al ciudadano, al tener en un solo lugar todo lo relacionado a su tr\u00e1mite legal.<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 13 de julio de 2024.- El gobernador Manolo Jim\u00e9nez Salinas y el alcalde Jos\u00e9 Mar\u00eda Fraustro Siller acompa\u00f1aron a Miguel Felipe Mery Ayup, magistrado presidente del Tribunal Superior de Justicia del Estado, en la visita de supervisi\u00f3n de lo que ser\u00e1 la Ciudad Judicial en la capital del Estado.<\/p>\n\n\n\n<p>En esta visita de obra se inform\u00f3 que al momento, este proyecto registra un 60 por ciento de avance en su construcci\u00f3n, y que se tiene contemplado est\u00e9 terminado al 100 por ciento antes de finalizar el 2024.<\/p>\n\n\n\n<p>\u201cEste proyecto es una gran idea porque tiene que ver con lo que padece mucha gente en cuanto a la resoluci\u00f3n de problemas y la realizaci\u00f3n de tr\u00e1mites, y el tiempo y dinero que los ciudadanos invierten en ello\u201d, mencion\u00f3 el Mandatario estatal.<\/p>\n\n\n\n<p>Dijo que la idea de tener todo en un solo lugar facilita mucho estos procesos en tiempo y forma. Coment\u00f3 que, con este proyecto integral de la Ciudad Judicial, se mejorar\u00e1 la atenci\u00f3n a la gente.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez coment\u00f3 que la Ciudad Judicial es un proyecto muy positivo que har\u00e1 m\u00e1s eficiente la labor de todos los funcionarios del poder judicial, adem\u00e1s de dar confianza a la gente con m\u00e1s cercan\u00eda, y que se traduzca esto en que las y los coahuilenses vivan mejor, que tengan un acceso m\u00e1s f\u00e1cil y r\u00e1pido a la justicia.<\/p>\n\n\n\n<p>Reiter\u00f3 el apoyo de su administraci\u00f3n para que esto se pueda concretar y que se haga de la mejor manera.<\/p>\n\n\n\n<p>Por su parte, el magistrado Miguel Mery record\u00f3 que en esta Ciudad Judicial trabajar\u00e1n alrededor de 750 funcionarios, y que se recibir\u00e1n mil 250 personas diariamente, de manera aproximada.<\/p>\n\n\n\n<p>Contar\u00e1 con 14 salas de audiencia, 15 salas de mediaci\u00f3n, un aula de capacitaci\u00f3n para 80 personas, un sal\u00f3n de usos m\u00faltiples para 200 personas; juzgados civiles, laborales, mercantiles, familiares; asesores jur\u00eddicos, mediadores, evaluadoras psicosociales; archivo judicial, oficinas de la Oficial\u00eda Mayor, de la Secretar\u00eda T\u00e9cnica, del Instituto de Especializaci\u00f3n Judicial, y del Centro de Conciliaci\u00f3n Laboral.<\/p>\n\n\n\n<p>\u201cAdem\u00e1s, esto habla del estado de derecho; al tener una Ciudad Judicial como esta le da fortaleza a las inversiones que se est\u00e1n anclando en la regi\u00f3n sureste\u201d, expres\u00f3.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Mery Ayup dijo que esta Ciudad Judicial es un paso que los lleva al siguiente nivel en el tema de la justicia. Agreg\u00f3 que pr\u00e1cticamente ser\u00e1 mucho m\u00e1s moderno, con una combinaci\u00f3n de eliminar protocolos judiciales, de incorporar m\u00e1s sistemas judiciales, de darle calidez a la gente.<\/p>\n\n\n\n<p>Record\u00f3 que en Saltillo se concentra el 40 por ciento de los asuntos judiciales en el estado, y que con este centro se busca un mejor acercamiento con la gente, darle un mejor servicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;El proyecto integral de la Ciudad Judicial mejorar\u00e1 la atenci\u00f3n al ciudadano, al tener en un solo lugar todo lo relacionado a su tr\u00e1mite legal. Saltillo, Coahuila de Zaragoza; a 13 de julio de 2024.- El gobernador Manolo Jim\u00e9nez Salinas y el alcalde Jos\u00e9 Mar\u00eda Fraustro Siller acompa\u00f1aron a Miguel Felipe Mery Ayup, magistrado presidente del Tribunal Superior de Justicia del Estado, en la visita de supervisi\u00f3n de lo que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15,75],"tags":[],"class_list":["post-21508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","category-obra","wpcat-5-id","wpcat-15-id","wpcat-75-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21508"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21508\/revisions"}],"predecessor-version":[{"id":21510,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21508\/revisions\/21510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/21509"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}