{"id":21887,"date":"2024-08-15T22:29:07","date_gmt":"2024-08-16T04:29:07","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=21887"},"modified":"2024-08-15T22:29:08","modified_gmt":"2024-08-16T04:29:08","slug":"renuevan-clinica-en-facultad-de-odontologia-de-la-uadec-con-22-nuevas-unidades-dentales","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/08\/15\/renuevan-clinica-en-facultad-de-odontologia-de-la-uadec-con-22-nuevas-unidades-dentales\/","title":{"rendered":"Renuevan Cl\u00ednica en Facultad de Odontolog\u00eda de la UAdeC con 22 Nuevas Unidades Dentales."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 15 de agosto de 2024. Con 22 nuevas Unidades Dentales,<br>fue inaugurada la Cl\u00ednica Operatoria de la Facultad de Odontolog\u00eda Unidad Saltillo,<br>por el rector de la Universidad Aut\u00f3noma de Coahuila Octavio Pimentel Mart\u00ednez,<br>como un esfuerzo conjunto de la Facultad y el respaldo de la Administraci\u00f3n<br>Central.<\/p>\n\n\n\n<p>Previamente dio la bienvenida a los 45 nuevos alumnos y alumnas a quienes<br>felicit\u00f3 por lograr entre m\u00e1s de 600 aspirantes a integrarse a una facultad<br>certificada, de calidad, de las mejores de M\u00e9xico y con un gran equipo de trabajo,<br>encabezado por su directora Shaila Esquivel \u00c1lvarez, de quien dijo, ha sabido<br>llevar a cabo proyectos y planes a beneficio de su comunidad universitaria.<\/p>\n\n\n\n<p>Pimentel Mart\u00ednez, exhort\u00f3 a los nuevos Lobos a sentirse orgullosos de entrar a la<br>comunidad de la Universidad Aut\u00f3noma de Coahuila, a formar un gran equipo con<br>un objetivo com\u00fan de crecimiento, de aprendizaje, de disfrutar las herramientas<br>que se les brinda para su capacitaci\u00f3n acad\u00e9mica profesional, e integral, deportiva<br>y cultural.<\/p>\n\n\n\n<p>\u201cAprovechen al m\u00e1ximo su estancia en la UAdeC, v\u00edvanla, disfr\u00fatenla, inviertan en<br>el deporte, en la cultura, en la actualizaci\u00f3n profesional y trabajen siempre en<br>equipo, con un objetivo com\u00fan: el de transformar la realidad que vivimos afuera,<br>con buenas acciones, con servicio, \u00e9tica y con amor a la camiseta de los Lobos\u201d,<br>expres\u00f3 el Rector.<\/p>\n\n\n\n<p>Afirm\u00f3 que, con esta adquisici\u00f3n, la Facultad de Odontolog\u00eda Unidad Saltillo de la<br>UAdeC reafirma su compromiso con la excelencia acad\u00e9mica y el servicio a la<br>comunidad, adem\u00e1s de que refrenda su posici\u00f3n como una de las principales<br>instituciones educativas en el \u00e1rea de la salud dental de la regi\u00f3n y del pa\u00eds.<\/p>\n\n\n\n<p>Por su parte, la directora Shaila Esquivel, agradeci\u00f3 al Rector el apoyo brindado y<br>el esfuerzo que llevan en conjunto para mejorar las instalaciones de la Facultad de<br>Odontolog\u00eda, pues las 22 unidades dentales se suman a las 56 unidades nuevas<br>con las que las Cl\u00ednicas se han ido renovando.<\/p>\n\n\n\n<p>Agradeci\u00f3 tambi\u00e9n al director de Planeaci\u00f3n Alberto Montalvo Morales, por la<br>apertura y el trabajo conjunto en la gesti\u00f3n de recursos para emprender proyectos<br>que mejoran la infraestructura de la Facultad de Odontolog\u00eda.<\/p>\n\n\n\n<p>Las autoridades universitarias recorrieron las seis cl\u00ednicas dentales con las que<br>cuenta el plantel, y que brindan servicios a la comunidad desde limpieza dental,<br>resinas, pr\u00f3tesis total, fija, removible, extracciones, endodoncia, tratamiento de<br>enc\u00eda y ortodoncia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 15 de agosto de 2024. Con 22 nuevas Unidades Dentales,fue inaugurada la Cl\u00ednica Operatoria de la Facultad de Odontolog\u00eda Unidad Saltillo,por el rector de la Universidad Aut\u00f3noma de Coahuila Octavio Pimentel Mart\u00ednez,como un esfuerzo conjunto de la Facultad y el respaldo de la Administraci\u00f3nCentral. Previamente dio la bienvenida a los 45 nuevos alumnos y alumnas a quienesfelicit\u00f3 por lograr entre m\u00e1s de 600 aspirantes a integrarse a una&#8230;<\/p>\n","protected":false},"author":1,"featured_media":21888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-21887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=21887"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21887\/revisions"}],"predecessor-version":[{"id":21889,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/21887\/revisions\/21889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/21888"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=21887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=21887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=21887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}