{"id":22109,"date":"2024-08-29T17:54:32","date_gmt":"2024-08-29T23:54:32","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=22109"},"modified":"2024-08-29T17:54:32","modified_gmt":"2024-08-29T23:54:32","slug":"busca-uadec-la-acreditacion-de-30-programas-academicos-de-las-unidades-saltillo-torreon-y-norte","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/08\/29\/busca-uadec-la-acreditacion-de-30-programas-academicos-de-las-unidades-saltillo-torreon-y-norte\/","title":{"rendered":"Busca UAdeC la Acreditaci\u00f3n de 30 Programas Acad\u00e9micos de las Unidades Saltillo, Torre\u00f3n y Norte."},"content":{"rendered":"\n<p>ARTEAGA, Coahuila. 29 de agosto de 2024. Para acreditar 30 programas educativos<br>de las Escuelas y Facultades de las Unidades Saltillo, Torre\u00f3n y Norte de la<br>Universidad Aut\u00f3noma de Coahuila, se present\u00f3 a trav\u00e9s de la Direcci\u00f3n de<br>Planeaci\u00f3n, el Marco General de Evaluaci\u00f3n 2024 desarrollado por los Comit\u00e9s<br>Interinstitucionales para la Evaluaci\u00f3n de la Educaci\u00f3n Superior (CIEES).<\/p>\n\n\n\n<p>En la Infoteca de Campus Arteaga estuvieron presentes el director general de los<br>CIEES, Miguel \u00c1ngel Tamayo Taype; el rector de la UAdeC, Octavio Pimentel<br>Mart\u00ednez, el director de Planeaci\u00f3n, Jes\u00fas Alberto Montalvo Morales; los<br>coordinadores de Unidad Saltillo, Torre\u00f3n y Norte, Eva Kerena Hern\u00e1ndez Mart\u00ednez,<br>Sandra L\u00f3pez Chavarr\u00eda y Luis Carlos Talamantes Arredondo, funcionariado de la<br>administraci\u00f3n central, directivos y docentes de las diversas unidades acad\u00e9micas<br>que llevaran a cabo el proceso de acreditaci\u00f3n.<\/p>\n\n\n\n<p>En su mensaje de bienvenida, el director de Planeaci\u00f3n, Jes\u00fas Alberto Montalvo,<br>destac\u00f3 la importancia de la evaluaci\u00f3n y acreditaci\u00f3n de los programas educativos<br>de la Universidad como parte de un compromiso con la Ley General de Educaci\u00f3n<br>Superior y las exigencias del sector empleador.<\/p>\n\n\n\n<p>Agradeci\u00f3 el apoyo del Rector y de los directivos y docentes que formar\u00e1n parte de<br>los comit\u00e9s interinstitucionales en este proceso, y se\u00f1al\u00f3 que el objetivo principal de<br>la evaluaci\u00f3n es identificar fortalezas y \u00e1reas de oportunidad, aline\u00e1ndose con los<br>lineamientos federales y estatales.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que la UAdeC tiene como objetivo iniciar la acreditaci\u00f3n de 30 programas<br>educativos, diez de la unidad Saltillo, 11 a la Unidad Torre\u00f3n y nueve a la Unidad<br>Norte, por lo que subray\u00f3 la importancia del papel de los Coordinadores en este<br>proceso, ya que, lograr estas acreditaciones, junto con los 20 programas ya<br>acreditados y los 11 adicionales en proceso con el Consejo para Acreditaci\u00f3n de la<br>Educaci\u00f3n Superior A.C.(COPAES), alcanzar\u00edan m\u00e1s del 90% de la matr\u00edcula<br>acreditada en calidad.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, el director general de los CIEES, Miguel \u00c1ngel Tamayo Taype;<br>explic\u00f3 que la metodolog\u00eda de evaluaci\u00f3n utilizada se compone de varias etapas<br>clave, para asegurar una valoraci\u00f3n exhaustiva de la informaci\u00f3n proporcionada por<br>las instituciones educativas y sus programas; el proceso comienza con una<br>autoevaluaci\u00f3n interna realizada por la comunidad acad\u00e9mica de la instituci\u00f3n o<br>programa, utilizando un instrumento dise\u00f1ado por los CIEES.<\/p>\n\n\n\n<p>La segunda etapa es la visita de evaluadores externos, quienes, como pares<br>acad\u00e9micos, revisan y verifican el cumplimiento de los criterios establecidos en el<br>instrumento de evaluaci\u00f3n, aportando recomendaciones para fortalecer la calidad<br>educativa y la tercera etapa es la dictaminaci\u00f3n por un comit\u00e9 interinstitucional, que<br>emite un veredicto sobre la acreditaci\u00f3n y determina su vigencia, con base en las<br>evidencias y valoraciones obtenidas en las etapas anteriores.<\/p>\n\n\n\n<p>Por su parte, el rector de la UAdeC, Octavio Pimentel Mart\u00ednez destac\u00f3 la<br>importancia de trabajar en equipo, especialmente en el contexto de la acreditaci\u00f3n<br>de los 30 programas educativos, pues dijo que este proceso es esencial para<br>generar certidumbre tanto dentro como fuera de la Universidad.<\/p>\n\n\n\n<p>Adem\u00e1s, se\u00f1al\u00f3 que es importante que todos en la UAdeC est\u00e9n preparados y<br>familiarizados con los procesos para lograr la certificaci\u00f3n de los programas<br>educativos, por lo que hizo un llamado a la comunidad universitaria a comprometerse<br>a trabajar en equipo con los gobiernos y los organismos de acreditaci\u00f3n, siempre<br>priorizando los intereses de la universidad.<\/p>\n\n\n\n<p>Los CIEES es un organismo establecido en 1991 para promover el mejoramiento de<br>los programas y de instituciones de educaci\u00f3n superior, creado en acuerdo de la<br>Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y la Asociaci\u00f3n Nacional de Universidades e<br>Instituciones de Educaci\u00f3n Superior (ANUIES) como un programa, en un primer<br>momento, dependiente y alojado en la propia ANUIES.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ARTEAGA, Coahuila. 29 de agosto de 2024. Para acreditar 30 programas educativosde las Escuelas y Facultades de las Unidades Saltillo, Torre\u00f3n y Norte de laUniversidad Aut\u00f3noma de Coahuila, se present\u00f3 a trav\u00e9s de la Direcci\u00f3n dePlaneaci\u00f3n, el Marco General de Evaluaci\u00f3n 2024 desarrollado por los Comit\u00e9sInterinstitucionales para la Evaluaci\u00f3n de la Educaci\u00f3n Superior (CIEES). En la Infoteca de Campus Arteaga estuvieron presentes el director general de losCIEES, Miguel \u00c1ngel Tamayo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":22110,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-22109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=22109"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22109\/revisions"}],"predecessor-version":[{"id":22111,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22109\/revisions\/22111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/22110"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=22109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=22109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=22109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}