{"id":22370,"date":"2024-09-12T19:02:29","date_gmt":"2024-09-13T01:02:29","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=22370"},"modified":"2024-09-12T19:02:29","modified_gmt":"2024-09-13T01:02:29","slug":"con-mujeres-echadas-padelante-inspira-empodera-a-las-mujeres-de-coahuila","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/09\/12\/con-mujeres-echadas-padelante-inspira-empodera-a-las-mujeres-de-coahuila\/","title":{"rendered":"CON \u2018MUJERES ECHADAS PA\u2019DELANTE\u2019, INSPIRA EMPODERA A LAS MUJERES DE COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 12 de septiembre de 2024.- Con la convicci\u00f3n de que la educaci\u00f3n es la mejor herramienta que se le puede brindar a las y los coahuilenses para su crecimiento y desarrollo personal que abone a una mejor calidad de vida, el Gobierno del Estado a trav\u00e9s de la Oficina Inspira Coahuila ha detonado una serie de acciones y programas encaminados al empoderamiento de las mujeres de nuestro estado.<\/p>\n\n\n\n<p>Paola Rodr\u00edguez L\u00f3pez, presidenta honoraria de Inspira Coahuila, inform\u00f3 que el programa \u201cMujeres Echadas Pa\u2019delante\u201d, es un programa insignia del Gobierno de Coahuila que busca, entre otros objetivos, lograr el empoderamiento educativo de las mujeres coahuilenses con la intenci\u00f3n de que realicen sus estudios de nivel preparatoria de manera gratuita.<\/p>\n\n\n\n<p>Mencion\u00f3 que el programa de preparatoria abierta comprende un total de 26 m\u00f3dulos: 22 m\u00f3dulos acad\u00e9micos y 4 m\u00f3dulos que comprenden talleres de desarrollo socioemocional que les ayudar\u00e1n no solo con su crecimiento acad\u00e9mico sino personal.<\/p>\n\n\n\n<p>Paola Rodr\u00edguez record\u00f3 que las convocatorias para que las mujeres puedan obtener una beca de preparatoria \u201cMujeres Echadas Pa\u2019delante\u201d se dividen en etapas, y que en la primera se inscribieron un total de mil 491 mujeres.<\/p>\n\n\n\n<p>Este n\u00famero se distribuy\u00f3 por municipios de la siguiente manera: Saltillo, 586; Torre\u00f3n, 298; Monclova, 50; Sabinas, 31; Piedras Negras, 526.<\/p>\n\n\n\n<p>Por su parte, Cecilia de la Garza Mart\u00ednez, directora general de Inspira, explic\u00f3 que en Saltillo inici\u00f3 el curso de inducci\u00f3n el primero de julio, y las clases el 31 de agosto, y que terminar\u00e1n su prepa aproximadamente en julio de 2025.<\/p>\n\n\n\n<p>\u201cEn el caso de las mujeres inscritas en Torre\u00f3n y Sabinas est\u00e1n empezando clases esta semana, a partir del 10 de septiembre, y en pr\u00f3ximos d\u00edas iniciar\u00e1n tambi\u00e9n las mujeres de Monclova y Piedras Negras\u201d, afirm\u00f3.<\/p>\n\n\n\n<p>Agreg\u00f3 que se abrir\u00e1 una segunda etapa de inscripci\u00f3n en el mes de enero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 12 de septiembre de 2024.- Con la convicci\u00f3n de que la educaci\u00f3n es la mejor herramienta que se le puede brindar a las y los coahuilenses para su crecimiento y desarrollo personal que abone a una mejor calidad de vida, el Gobierno del Estado a trav\u00e9s de la Oficina Inspira Coahuila ha detonado una serie de acciones y programas encaminados al empoderamiento de las mujeres&#8230;<\/p>\n","protected":false},"author":1,"featured_media":22371,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,48,15],"tags":[],"class_list":["post-22370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-genero","category-gobierno-de-coahuila","wpcat-5-id","wpcat-48-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=22370"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22370\/revisions"}],"predecessor-version":[{"id":22372,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22370\/revisions\/22372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/22371"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=22370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=22370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=22370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}