{"id":22406,"date":"2024-09-16T17:48:23","date_gmt":"2024-09-16T23:48:23","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=22406"},"modified":"2024-09-16T17:48:23","modified_gmt":"2024-09-16T23:48:23","slug":"con-un-gran-estado-de-fuerza-coordinacion-y-voluntad-mantenemos-a-coahuila-seguro-manolo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/09\/16\/con-un-gran-estado-de-fuerza-coordinacion-y-voluntad-mantenemos-a-coahuila-seguro-manolo\/","title":{"rendered":"CON UN GRAN ESTADO DE FUERZA, COORDINACI\u00d3N Y VOLUNTAD MANTENEMOS A COAHUILA SEGURO: MANOLO."},"content":{"rendered":"\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong><em>Junto al Ej\u00e9rcito Mexicano, el Poder Judicial, el Poder Legislativo y el Alcalde de la Capital Coahuilense, el Gobernador del Estado presidi\u00f3 el desfile C\u00edvico Militar conmemorativo al 214 aniversario del inicio de la Independencia de M\u00e9xico<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 16 de septiembre de 2024.- Durante el desfile c\u00edvico militar con el que se conmemor\u00f3 el 214 aniversario del inicio de la Independencia de M\u00e9xico, el gobernador Manolo Jim\u00e9nez Salinas destac\u00f3 el estado de fuerza, la voluntad y la coordinaci\u00f3n con que se trabaja en Coahuila en el tema de la seguridad.&nbsp;<\/p>\n\n\n\n<p>&#8220;Hoy y siempre celebramos el orgullo de ser mexicanos. Junto a cientos de familias, disfrutamos en Saltillo el tradicional Desfile C\u00edvico Militar en honor al 214 aniversario de nuestra Independencia Nacional, donde los tres \u00f3rdenes de Gobierno y el Ej\u00e9rcito Mexicano estuvimos presentes; resaltando nuestros valores patrios, nuestro estado de fuerza y la firme voluntad de seguir manteniendo a Coahuila como uno de los estados m\u00e1s seguros de M\u00e9xico&#8221;, destac\u00f3.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez resalt\u00f3 que en equipo con el Ej\u00e9rcito Mexicano, la Guardia Nacional, las polic\u00edas municipales, las fiscal\u00edas, la Polic\u00eda Estatal, se tiene una gran fuerza para blindar nuestro estado y mantenerlo como uno de los m\u00e1s seguros de M\u00e9xico.<\/p>\n\n\n\n<p>Junto al General Vicente P\u00e9rez L\u00f3pez, Comandante de la Sexta Zona Militar, los titulares de los poderes Legislativo y Judicial, as\u00ed como el Alcalde de Saltillo, el Mandatario estatal presidi\u00f3, en la capital del estado, este desfile conmemorativo.<\/p>\n\n\n\n<p>Luego de una gran fiesta ciudadana que se vivi\u00f3 la noche previa en la plaza de armas con la ceremonia del Grito de Independencia, miles de coahuilenses disfrutaron el paso de los contingentes encabezados por la Secretar\u00eda de la Defensa Nacional.<\/p>\n\n\n\n<p>Desde el templete instalado frente al Ateneo Fuente, en el cruce del bulevar Venustiano Carranza y avenida Universidad, Manolo Jim\u00e9nez observ\u00f3 y salud\u00f3 a su paso a todos los participantes en este desfile c\u00edvico militar.<\/p>\n\n\n\n<p>Por parte del Ej\u00e9rcito Mexicano, tomaron parte una bandera de guerra, un jefe, cuatro oficiales, 266 de tropa, 11 veh\u00edculos y tres canes.<\/p>\n\n\n\n<p>Un inspector, dos oficiales, 124 de escala b\u00e1sica de la Guardia Nacional; 13 soldados del Servicio Militar Nacional; 55 rurales y 10 veh\u00edculos del primer cuerpo de infanter\u00eda de defensa rurales.<\/p>\n\n\n\n<p>Adem\u00e1s de 343 elementos, 58 veh\u00edculos y 25 canes pertenecientes a la Secretar\u00eda de Seguridad P\u00fablica; 261 elementos y 25 veh\u00edculos de la Comisar\u00eda de Seguridad y Protecci\u00f3n Ciudadana de Saltillo; 50 elementos de Protecci\u00f3n Civil y Bomberos de Saltillo; 300 alumnos del sistema educativo de Saltillo.<\/p>\n\n\n\n<p>Al finalizar el desfile, Manolo Jim\u00e9nez destac\u00f3 el saldo blanco reportado durante los festejos por el grito de independencia en los 38 municipios de Coahuila<\/p>\n\n\n\n<p>\u201cUn gran grito de independencia, un grito con la participaci\u00f3n de la ciudadan\u00eda al interior de Palacio de Gobierno; convivimos con las y los coahuilenses que ganaron el \u201cgiveaway\u201d para vivir esta experiencia del grito\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>Jim\u00e9nez Salinas celebr\u00f3 que tuvo la oportunidad de convivir con miles de saltillenses y coahuilenses que asistieron a la plaza de armas, alrededor de 20 mil personas, y que la gente estuvo muy animada y emocionada durante el Grito de Independencia, lo cual se puede lograr gracias a la tranquilidad con la que se vive en toda las regiones de Coahuila.<\/p>\n\n\n\n<p>Acompa\u00f1aron al gobernador, Jos\u00e9 Mar\u00eda Fraustro Siller, presidente Municipal de Saltillo; Luz Elena Morales N\u00fa\u00f1ez, diputada presidenta de la Junta de Gobierno del Gobierno del Estado; Miguel Felipe Mery Ayup, magistrado presidente del Tribunal Superior de Justicia; Jeric\u00f3 Abramo Masso, diputado federal; Javier D\u00edaz Gonz\u00e1lez, presidente municipal electo de Saltillo; \u00d3scar Pimentel Gonz\u00e1lez, secretario de Gobierno; Gerardo M\u00e1rquez Guevara, fiscal General del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Junto al Ej\u00e9rcito Mexicano, el Poder Judicial, el Poder Legislativo y el Alcalde de la Capital Coahuilense, el Gobernador del Estado presidi\u00f3 el desfile C\u00edvico Militar conmemorativo al 214 aniversario del inicio de la Independencia de M\u00e9xico Saltillo, Coahuila de Zaragoza; a 16 de septiembre de 2024.- Durante el desfile c\u00edvico militar con el que se conmemor\u00f3 el 214 aniversario del inicio de la Independencia de M\u00e9xico, el gobernador Manolo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":22407,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,15],"tags":[],"class_list":["post-22406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-gobierno-de-coahuila","wpcat-5-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=22406"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22406\/revisions"}],"predecessor-version":[{"id":22408,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22406\/revisions\/22408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/22407"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=22406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=22406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=22406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}