{"id":22415,"date":"2024-09-17T17:44:10","date_gmt":"2024-09-17T23:44:10","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=22415"},"modified":"2024-09-17T17:44:10","modified_gmt":"2024-09-17T23:44:10","slug":"tiene-nueva-directora-facultad-de-ciencias-sociales-de-la-uadec","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/09\/17\/tiene-nueva-directora-facultad-de-ciencias-sociales-de-la-uadec\/","title":{"rendered":"Tiene Nueva Directora Facultad de Ciencias Sociales de la UAdeC."},"content":{"rendered":"\n<p>SALTILLO, Coahuila. 17 de septiembre de 2024. Ante el Consejo Directivo,<br>estudiantes y docentes de la Facultad de Ciencias Sociales de la Universidad<br>Aut\u00f3noma de Coahuila, el rector Octavio Pimentel Mart\u00ednez, asisti\u00f3 al tercer informe<br>de actividades del director saliente Dr. Jos\u00e9 Gustavo Gonz\u00e1lez Flores y tom\u00f3<br>protesta a la Dra. Machelly Flores Reyna como nueva directora del plantel para el<br>periodo 2024-2027.<\/p>\n\n\n\n<p>Acompa\u00f1ado por la coordinadora de Unidad Saltillo, Eva Kerena Hern\u00e1ndez<br>Mart\u00ednez, el Rector, refrend\u00f3 el apoyo de la administraci\u00f3n central con cada uno de<br>los proyectos que se emprendan en la Facultad de Ciencias Sociales, al tiempo que<br>agradeci\u00f3 al Dr. Jos\u00e9 Gustavo Gonz\u00e1lez por su labor y valent\u00eda ante tiempos<br>complejos y por los logros y avances durante su gesti\u00f3n.<\/p>\n\n\n\n<p>\u201cEl trabajo en equipo es una prioridad que demanda la sociedad, as\u00ed como de tener<br>una Universidad abierta, en donde se permita la diferencia de opiniones para<br>construir un beneficio para la instituci\u00f3n y la sociedad, por ello, hagamos a un lado la<br>polarizaci\u00f3n y pongamos los intereses de la instituci\u00f3n por delante de los personales,<br>trabajemos en unidad y llevemos a la Universidad al nivel que se merece que es el<br>de la excelencia, para que pegue la L de Lucha por una mejor sociedad, de Libertad<br>de pensamiento, de Logros, de Lealtad a la instituci\u00f3n y de los Lobos de la UAdeC\u201d,<br>dijo.<\/p>\n\n\n\n<p>Por su parte, la directora Machelly Flores Reyna, dijo que es un honor y una gran<br>responsabilidad asumir el cargo, \u201cEs una oportunidad invaluable y un reto enorme<br>para fortalecer el papel de la historia en la sociedad, agradezco a los ex directores<br>por la labor que realizaron durante sus administraciones, ya que hay una necesidad<br>urgente de integrar a m\u00e1s historiadores en los grupos interdisciplinarios que abordan<br>problemas sociales, pues es necesaria una comprensi\u00f3n profunda del pasado para<br>atender las problem\u00e1ticas actuales\u201d.<\/p>\n\n\n\n<p>Enfatiz\u00f3 que durante su gesti\u00f3n se trabajar\u00e1 en un entorno acad\u00e9mico en el que la<br>curiosidad intelectual pueda florecer en un ambiente de respeto, impulsando el<br>trabajo en equipo para fortalecer a la Facultad, promoviendo la excelencia<br>acad\u00e9mica y la actualizaci\u00f3n en la comprensi\u00f3n y el uso de las nuevas tecnolog\u00edas.<\/p>\n\n\n\n<p>Durante su intervenci\u00f3n, el Dr. Jos\u00e9 Gustavo Gonz\u00e1lez Flores, present\u00f3 su informe<br>de actividades, el cual dividi\u00f3 en: 1. Los estudiantes, 2. Los profesores-<br>investigadores, 3. Personal administrativo y manual, 4. Convenios, extensi\u00f3n y<br>acercamiento a la comunidad y 5. Situaci\u00f3n financiera.<\/p>\n\n\n\n<p>Destac\u00f3 que fue un periodo de arduo trabajo en equipo, con el objetivo de buscar la<br>excelencia acad\u00e9mica, por ello, agradeci\u00f3 a docentes, personal administrativo y<\/p>\n\n\n\n<p>manual, as\u00ed como a la comunidad estudiantil por siempre brindarle apoyo y haber<br>sido parte de su plan de trabajo.<\/p>\n\n\n\n<p>Comparti\u00f3 que la Facultad de Ciencias Sociales se distingue por cumplir con las<br>exigencias de la Universidad de ofrecer tutor\u00edas a sus estudiantes, por lo que a lo<br>largo de su gesti\u00f3n se cubrieron en su totalidad las tutor\u00edas institucionales y se\u00f1al\u00f3<br>que de las labores m\u00e1s importantes del Comit\u00e9 de Tutor\u00edas fue reconocer y abordar<br>problemas como el estr\u00e9s, ansiedad y depresi\u00f3n, as\u00ed como la necesidad de buscar<br>ayuda adecuada y profesional para los estudiantes.<\/p>\n\n\n\n<p>Tambi\u00e9n dio a conocer que para para incentivar el trabajo colaborativo<br>interinstitucional, el plantel estableci\u00f3 de septiembre de 2023 a septiembre de 2024<br>un acuerdo de colaboraci\u00f3n y una carta interinstitucional de colaboraci\u00f3n con<br>entidades internas y externas a la UAdeC: Carta interinstitucional de colaboraci\u00f3n<br>con el Archivo para la Memoria de la Universidad Iberoamericana Centro de<br>Extensi\u00f3n Saltillo y colaboraci\u00f3n con la Librer\u00eda Carlos Monsiv\u00e1is del Fondo de<br>Cultura Econ\u00f3mica donde se exhiben publicaciones y se realizan actividades<br>acad\u00e9micas de la Facultad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALTILLO, Coahuila. 17 de septiembre de 2024. Ante el Consejo Directivo,estudiantes y docentes de la Facultad de Ciencias Sociales de la UniversidadAut\u00f3noma de Coahuila, el rector Octavio Pimentel Mart\u00ednez, asisti\u00f3 al tercer informede actividades del director saliente Dr. Jos\u00e9 Gustavo Gonz\u00e1lez Flores y tom\u00f3protesta a la Dra. Machelly Flores Reyna como nueva directora del plantel para elperiodo 2024-2027. Acompa\u00f1ado por la coordinadora de Unidad Saltillo, Eva Kerena Hern\u00e1ndezMart\u00ednez, el Rector,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":22416,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-22415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=22415"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22415\/revisions"}],"predecessor-version":[{"id":22417,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22415\/revisions\/22417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/22416"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=22415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=22415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=22415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}