{"id":22740,"date":"2024-10-06T18:09:14","date_gmt":"2024-10-07T00:09:14","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=22740"},"modified":"2024-10-06T18:09:14","modified_gmt":"2024-10-07T00:09:14","slug":"se-esperan-chubascos-y-lluvias-fuertes-en-coahuila-2","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/10\/06\/se-esperan-chubascos-y-lluvias-fuertes-en-coahuila-2\/","title":{"rendered":"SE ESPERAN CHUBASCOS Y LLUVIAS FUERTES EN COAHUILA."},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; 5 de octubre de 2024 \u2013 La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado informa que, durante la tarde, se prev\u00e9 un ambiente templado a c\u00e1lido en gran parte del territorio coahuilense, acompa\u00f1ado de un aumento en la nubosidad, lo que podr\u00eda generar chubascos y rachas de viento de 40 a 60 km\/h.<\/p>\n\n\n\n<p>De acuerdo con el pron\u00f3stico del Servicio Meteorol\u00f3gico Nacional, se esperan intervalos de chubascos y lluvias fuertes, con acumulaciones de hasta 50 mm. Estas condiciones podr\u00edan ocasionar encharcamientos, inundaciones, deslaves y un aumento en los niveles de r\u00edos y arroyos. Adem\u00e1s, las rachas de viento podr\u00edan derribar \u00e1rboles y anuncios publicitarios.<\/p>\n\n\n\n<p>Se exhorta a la poblaci\u00f3n a tomar precauciones, mantenerse atenta a los avisos del Servicio Meteorol\u00f3gico Nacional y seguir las indicaciones de las autoridades.<\/p>\n\n\n\n<p><strong>EN TU VIVIENDA<\/strong><\/p>\n\n\n\n<p>\u2022\u2060\u2060Cierra y asegura puertas, ventanas o toldos.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Retira todos aquellos objetos que puedan caer a la calle y provocar un accidente.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Si los vidrios de las ventanas no son tan fuertes, coloca cinta adhesiva transparente en la parte interior para evitar que al romperse los vidrios provoquen da\u00f1os.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Evita salir de casa si no es necesario.<\/p>\n\n\n\n<p><strong>EN LA CALLE O EL CAMPO<\/strong><\/p>\n\n\n\n<p>\u2022\u2060\u2060Al\u00e9jate de cornisas, muros o \u00e1rboles que puedan desprenderse.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Toma precauciones frente a edificaciones en construcci\u00f3n o en mal estado.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Abstente de subir andamios sin las adecuadas medidas de protecci\u00f3n.<\/p>\n\n\n\n<p>\u2022\u2060\u2060No te resguardes del viento en zonas cercanas a muros, \u00e1rboles o edificios en mal estado o en construcci\u00f3n.<\/p>\n\n\n\n<p><strong>SI EST\u00c1S CONDUCIENDO<\/strong><\/p>\n\n\n\n<p>\u2022\u2060\u2060Evita manejar por \u00e1reas inundadas y agua estancada.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Ten precauci\u00f3n, ya que son frecuentes los cortes en v\u00edas debido a la ca\u00edda de \u00e1rboles y cables el\u00e9ctricos.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Conduce con precauci\u00f3n debido a la posibilidad de formaci\u00f3n de nubes de polvo.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Si tu auto se ve afectado por la fuerza del viento, evita los rebases y ten precauci\u00f3n en los cruces y puentes.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Conduce con precauci\u00f3n, disminuyendo la velocidad y con las luces encendidas si la visibilidad es escasa.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Ten precauci\u00f3n al adelantar veh\u00edculos de carga pesada, ya que pueden hacer movimientos imprevistos.<\/p>\n\n\n\n<p>\u2022\u2060\u2060Localiza con anticipaci\u00f3n los Refugios Temporales habilitados por las autoridades en la p\u00e1gina\u00a0<a href=\"http:\/\/proteccio\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/proteccio<\/a><a href=\"http:\/\/ncivil.sfpcoahuila.gob.mx\/modulo22.php?opcion=8\" target=\"_blank\" rel=\"noreferrer noopener\">ncivil.sfpcoahuila.gob.mx\/modulo22.php?opcion=8<\/a>.<\/p>\n\n\n\n<p>En caso de emergencia, la ciudadan\u00eda puede llamar al 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; 5 de octubre de 2024 \u2013 La Subsecretar\u00eda de Protecci\u00f3n Civil del Estado informa que, durante la tarde, se prev\u00e9 un ambiente templado a c\u00e1lido en gran parte del territorio coahuilense, acompa\u00f1ado de un aumento en la nubosidad, lo que podr\u00eda generar chubascos y rachas de viento de 40 a 60 km\/h. De acuerdo con el pron\u00f3stico del Servicio Meteorol\u00f3gico Nacional, se esperan intervalos de chubascos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":22741,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,5,15,54],"tags":[],"class_list":["post-22740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima","category-coahuila","category-gobierno-de-coahuila","category-proteccion-civil","wpcat-27-id","wpcat-5-id","wpcat-15-id","wpcat-54-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=22740"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22740\/revisions"}],"predecessor-version":[{"id":22742,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/22740\/revisions\/22742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/22741"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=22740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=22740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=22740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}