{"id":23256,"date":"2024-11-04T18:04:56","date_gmt":"2024-11-05T00:04:56","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23256"},"modified":"2024-11-04T18:04:56","modified_gmt":"2024-11-05T00:04:56","slug":"proteccion-civil-emite-recomendaciones-a-quienes-practican-senderismo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/11\/04\/proteccion-civil-emite-recomendaciones-a-quienes-practican-senderismo\/","title":{"rendered":"Protecci\u00f3n Civil emite recomendaciones a quienes practican senderismo."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila a 4 de noviembre de 2024.<\/p>\n\n\n\n<p>Debido a los riesgos que pueden correr quienes practican el senderismo, la<br>Direcci\u00f3n de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n emiti\u00f3 una serie de<br>recomendaciones para evitar que ocurra alguna emergencia.<\/p>\n\n\n\n<p>Jorge Luis Ju\u00e1rez Llanas, director de la dependencia, se\u00f1al\u00f3 que en el mes de<br>octubre se registraron diversos rescates de personas, que incluso algunas iban<br>acompa\u00f1adas de sus mascotas, y que suben al cerro sin las adecuadas<br>previsiones.<\/p>\n\n\n\n<p>\u201cHemos acudido a rescates de personas que se desorientan porque al no conocer<br>la ruta se llegan a perder, adem\u00e1s de que no acuden con la hidrataci\u00f3n necesaria<br>y con ello surgen reacciones en el cuerpo que los debilitan\u201d, expuso.<\/p>\n\n\n\n<p>Dijo que es importante que quienes pretenden realizar esta actividad den aviso a<br>la direcci\u00f3n para estar atentos a que regresen con bien.<\/p>\n\n\n\n<p>Dijo que la Ruta de las Noas, es una de las m\u00e1s frecuentadas por quienes<br>practican el senderismo, por lo que ah\u00ed se han colocado se\u00f1alamientos que les<br>sirven de gu\u00eda. Sin embargo, lo aconsejable se\u00f1al\u00f3, es que suban acompa\u00f1ados<br>de una persona que conozca el recorrido, que avisen a familiares y tambi\u00e9n a la<br>direcci\u00f3n de Protecci\u00f3n Civil para poder estar atentos a que su ida y regreso sea<br>sin incidentes.<\/p>\n\n\n\n<p>Otras de las recomendaciones que manifest\u00f3 el director es que est\u00e1 actividad se<br>haga por la ma\u00f1ana muy temprano o ya por la tarde despu\u00e9s de las horas m\u00e1s<br>intensas de sol, mantenerse hidratados y vestir ropa adecuada.<\/p>\n\n\n\n<p>\u201cEl tiempo del recorrido es algo largo, aunque son pocos kil\u00f3metros y si acuden<br>de noche se hace m\u00e1s tardada la subida y bajada por el cerro y se pueden perder,<br>por eso es importante acudir con personas que conozcan bien la ruta\u201d, insisti\u00f3 el<br>funcionario.<\/p>\n\n\n\n<p>Dijo que para las personas que no cuentan con mucha condici\u00f3n f\u00edsica o est\u00e1n<br>empezando en esta actividad, es mejor subir a un nivel bajo o medio de la ruta e<br>incrementar paulatinamente el ascenso en posteriores visitas.<\/p>\n\n\n\n<p>Mencion\u00f3 que para cualquier situaci\u00f3n de emergencia, se pueden comunicar al<br>tel\u00e9fono de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n al 871 712 00 66 o al 911.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila a 4 de noviembre de 2024. Debido a los riesgos que pueden correr quienes practican el senderismo, laDirecci\u00f3n de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n emiti\u00f3 una serie derecomendaciones para evitar que ocurra alguna emergencia. Jorge Luis Ju\u00e1rez Llanas, director de la dependencia, se\u00f1al\u00f3 que en el mes deoctubre se registraron diversos rescates de personas, que incluso algunas ibanacompa\u00f1adas de sus mascotas, y que suben al cerro sin&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23257,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-23256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23256"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23256\/revisions"}],"predecessor-version":[{"id":23258,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23256\/revisions\/23258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23257"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}