{"id":23329,"date":"2024-11-07T19:11:36","date_gmt":"2024-11-08T01:11:36","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23329"},"modified":"2024-11-07T19:11:36","modified_gmt":"2024-11-08T01:11:36","slug":"convoca-escuela-de-psicologia-de-la-uadec-unidad-norte-a-su-primer-foro-de-investigacion","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/11\/07\/convoca-escuela-de-psicologia-de-la-uadec-unidad-norte-a-su-primer-foro-de-investigacion\/","title":{"rendered":"Convoca Escuela de Psicolog\u00eda de la UAdeC Unidad Norte a su Primer Foro de Investigaci\u00f3n."},"content":{"rendered":"\n<p>MONCLOVA, Coahuila. 7 de noviembre de 2024. Con el objetivo de promover el<br>inter\u00e9s por la investigaci\u00f3n cient\u00edfica y compartir los proyectos de docentes y<br>alumnos, la Escuela de Psicolog\u00eda de la Universidad Aut\u00f3noma de Coahuila de la<br>Unidad Norte, invita al Primer Foro de Investigaci\u00f3n, este viernes 8 de noviembre en<br>la Unidad de Seminarios del Campus Monclova.<\/p>\n\n\n\n<p>A partir de las 10:00 horas a las 13:00 horas, en el Foro se tendr\u00e1 la exposici\u00f3n de<br>investigaciones generadas en el aula dentro de la materia Psicolog\u00eda de la Salud a<br>cargo de la Mtra. Liliana Mayela Alonso Ramos, entre ellas: &#8220;Lo que no sabes del<br>tabaco&#8221;, &#8220;Juntos sin drogas&#8221;, &#8220;Uso del cond\u00f3n y prevenci\u00f3n del embarazo&#8221;, &#8220;La<br>importancia de una vida sexual saludable&#8221;, &#8220;La otra cara del Alcoholismo&#8221; y &#8220;Los<br>accidentes suceden\u2026&#8221;<\/p>\n\n\n\n<p>Habr\u00e1 la presentaci\u00f3n del Club de Investigaci\u00f3n Psicoeducativa por la Dra. Beatriz<br>Arianna Trevi\u00f1o Garza, quien explicar\u00e1 lo que realizan en el club, en donde se<br>emprenden trabajos de investigaci\u00f3n, as\u00ed como la impartici\u00f3n de talleres y<br>conferencias, se abrir\u00e1 el espacio para que m\u00e1s estudiantes se integren.<\/p>\n\n\n\n<p>Asimismo, durante el Foro, se desarrollar\u00e1 el Panel de tesistas dirigido por la Mtra.<br>Edna Gabriela D\u00edaz B\u00e1ez, donde participar\u00e1n las alumnas Ileana Mariely Sanmiguel<br>Ju\u00e1rez, de 7\u00b0 semestre, Samantha Abigail Marcial Rodr\u00edguez, de 7\u00b0 semestre y Edith<br>Maribel Astorga Santos, de 9\u00b0 semestre.<\/p>\n\n\n\n<p>El registro es a partir de las 9:00 horas en la Sala de Seminarios del Campus<br>Monclova.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONCLOVA, Coahuila. 7 de noviembre de 2024. Con el objetivo de promover elinter\u00e9s por la investigaci\u00f3n cient\u00edfica y compartir los proyectos de docentes yalumnos, la Escuela de Psicolog\u00eda de la Universidad Aut\u00f3noma de Coahuila de laUnidad Norte, invita al Primer Foro de Investigaci\u00f3n, este viernes 8 de noviembre enla Unidad de Seminarios del Campus Monclova. A partir de las 10:00 horas a las 13:00 horas, en el Foro se tendr\u00e1&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23330,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-23329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23329"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23329\/revisions"}],"predecessor-version":[{"id":23331,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23329\/revisions\/23331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23330"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}