{"id":2334,"date":"2021-05-20T17:06:30","date_gmt":"2021-05-20T22:06:30","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=2334"},"modified":"2021-05-20T17:06:31","modified_gmt":"2021-05-20T22:06:31","slug":"celebra-marcela-gorgon-50-aniversario-del-cree-saltillo","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2021\/05\/20\/celebra-marcela-gorgon-50-aniversario-del-cree-saltillo\/","title":{"rendered":"CELEBRA MARCELA GORG\u00d3N 50 ANIVERSARIO DEL CREE SALTILLO."},"content":{"rendered":"\n<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<strong><em>DIF Coahuila conmemora los 59 a\u00f1os del CREE Saltillo de atenci\u00f3n a la salud y rehabilitaci\u00f3n de la personas con discapacidad<\/em><\/strong><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; a 20 de Mayo de 2021.- La Presidenta Honoraria del DIF Coahuila, Marcela Gorg\u00f3n, y el Secretario de Gobierno, Fernando de Las Fuentes Hern\u00e1ndez (en representaci\u00f3n del Gobernador Miguel \u00c1ngel Riquelme Sol\u00eds), develaron la placa conmemorativa del 50 Aniversario del Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial (CREE Saltillo).<\/p>\n\n\n\n<p>En la ceremonia, Marcela Gorg\u00f3n se\u00f1al\u00f3 que para el DIF Coahuila es una prioridad apoyar a las personas que viven con alg\u00fan tipo de discapacidad, ya sea temporal o permanente.<\/p>\n\n\n\n<p>Para ello, indic\u00f3 que el Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial de Saltillo ha sido una pieza fundamental para mejorar la salud y calidad de vida de ni\u00f1as, ni\u00f1os, j\u00f3venes y adultos que han sufrido alg\u00fan tipo de padecimiento que ha afectado su movilidad.<\/p>\n\n\n\n<p>En ese contexto, reconoci\u00f3 la entrega y profesionalismo de doctores, terapeutas, enfermeros, voluntarios y personal administrativo que ha consolidado al CREE como una noble instituci\u00f3n al servicio de las y los coahuilenses durante sus 50 a\u00f1os de vida.<\/p>\n\n\n\n<p>De Las Fuentes Hern\u00e1ndez, hijo de la se\u00f1ora Elsa Hern\u00e1ndez de De Las Fuentes, fundadora de este centro, se\u00f1al\u00f3 que el Sistema para el Desarrollo Integral de la Familia, y particularmente el Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial, requieren al frente grandes almas y enormes corazones, mismos que sin duda posee la se\u00f1ora Marcela.<\/p>\n\n\n\n<p>El funcionario estatal subray\u00f3 que Coahuila est\u00e1 comprometido con el apoyo a las personas que viven alguna situaci\u00f3n de discapacidad, y prueba de ello es el fortalecimiento de los centros especializados de rehabilitaci\u00f3n y habilitaci\u00f3n con atenci\u00f3n profesional especializada a cada tipo de discapacidad de las personas y a sus familiares.<\/p>\n\n\n\n<p>\u201cEs derecho de todas las personas con discapacidad acceder a una rehabilitaci\u00f3n integral respetando sus necesidades y posibilidades espec\u00edficas, para que gocen una vida cada vez m\u00e1s aut\u00f3noma e independiente en su capacidad f\u00edsica, mental y vocacional, as\u00ed como la inclusi\u00f3n y participaci\u00f3n plena en todos los aspectos de la vida\u201d, dijo.<\/p>\n\n\n\n<p>Record\u00f3 que para hacer frente a las vulnerabilidades que viven las personas con discapacidad en la salud, en Coahuila se han dise\u00f1ado y apoyado estrategias accesibles, inclusivas, que fomenten el desenvolvimiento de la vida de las personas con discapacidad, como UNEDIF y los Centros de Rehabilitaci\u00f3n y Unidades B\u00e1sicas de Rehabilitaci\u00f3n, as\u00ed como la entrega de sillas de ruedas, de pr\u00f3tesis y de \u00f3rtesis, y tiene que ver con una pol\u00edtica de acceso a los derechos humanos de las personas en situaci\u00f3n de vulnerabilidad.<\/p>\n\n\n\n<p>Extern\u00f3 tambi\u00e9n el reconocimiento por su actuaci\u00f3n durante esta pandemia, que de ninguna manera paraliz\u00f3 la gran tarea que realizan.<\/p>\n\n\n\n<p>\u201cEsta situaci\u00f3n permiti\u00f3 involucrar m\u00e1s a las familias en la rehabilitaci\u00f3n de sus miembros con discapacidad, e hizo necesario el desarrollo de nuevas habilidades en los trabajadores del CREE para abordar la rehabilitaci\u00f3n de pacientes post Covid-19\u201d.<\/p>\n\n\n\n<p>El Secretario de Gobierno y Marcela Gorg\u00f3n, acompa\u00f1ados tambi\u00e9n de los secretarios de&nbsp; Salud y&nbsp; Educaci\u00f3n en Coahuila, Roberto Bernal G\u00f3mez e Higinio Gonz\u00e1lez Calder\u00f3n, respectivamente, as\u00ed como de la diputada local Martha Loera Ar\u00e1mbula; Marco Flores, representante del alcalde Manolo Jim\u00e9nez Salinas, y el Director General del Sistema DIF Coahuila, Jos\u00e9 Roberto C\u00e1rdenas Zavala, entregaron un&nbsp; reconocimiento especial al personal del Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial por sus 20 y 30 a\u00f1os de trayectoria, y gran labor que han realizado en beneficio de las personas con discapacidad.<\/p>\n\n\n\n<p>C\u00e1rdenas Zavala, titular del DIF Coahuila, record\u00f3 que en 1971 se iniciaron los primeros servicios de rehabilitaci\u00f3n f\u00edsica en Saltillo a la poblaci\u00f3n infantil con secuelas de poliomielitis, par\u00e1lisis cerebral y secuelas de meningitis, entre otros.<\/p>\n\n\n\n<p>Fue hasta el a\u00f1o de 1979 cuando se iniciaron las actividades del Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial en Saltillo, edificio que actualmente ocupa y en donde se ofrecen servicios de Medicina de Rehabilitaci\u00f3n, Neurolog\u00eda,&nbsp; Medicina del Deporte, Comunicaci\u00f3n Humana, Psicolog\u00eda, Traumatolog\u00eda y Ortopedia.<\/p>\n\n\n\n<p>El Centro de Rehabilitaci\u00f3n y Educaci\u00f3n Especial ofrece tambi\u00e9n servicios de terapia f\u00edsica, ocupacional y de lenguaje, trabajo social, psicolog\u00eda, integraci\u00f3n social educativa y al empleo, y cuenta con un M\u00f3dulo de Atenci\u00f3n a Ni\u00f1os con Trastorno del Espectro Autista, as\u00ed como un taller para la fabricaci\u00f3n y reparaci\u00f3n de pr\u00f3tesis y \u00f3rtesis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00b7\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0DIF Coahuila conmemora los 59 a\u00f1os del CREE Saltillo de atenci\u00f3n a la salud y rehabilitaci\u00f3n de la personas con discapacidad Saltillo, Coahuila de Zaragoza; a 20 de Mayo de 2021.- La Presidenta Honoraria del DIF Coahuila, Marcela Gorg\u00f3n, y el Secretario de Gobierno, Fernando de Las Fuentes Hern\u00e1ndez (en representaci\u00f3n del Gobernador Miguel \u00c1ngel Riquelme Sol\u00eds), develaron la placa conmemorativa del 50 Aniversario del Centro de Rehabilitaci\u00f3n y Educaci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,26,15],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-dif","category-gobierno-de-coahuila","wpcat-5-id","wpcat-26-id","wpcat-15-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":2336,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions\/2336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}