{"id":23380,"date":"2024-11-11T19:04:30","date_gmt":"2024-11-12T01:04:30","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23380"},"modified":"2024-11-11T19:04:30","modified_gmt":"2024-11-12T01:04:30","slug":"el-rector-de-la-uadec-toma-protesta-a-la-primera-directora-mujer-de-la-escuela-de-medicina-unidad-norte","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/11\/11\/el-rector-de-la-uadec-toma-protesta-a-la-primera-directora-mujer-de-la-escuela-de-medicina-unidad-norte\/","title":{"rendered":"El Rector de la UAdeC Toma Protesta a la Primera Directora Mujer de la Escuela de Medicina Unidad Norte."},"content":{"rendered":"\n<p>PIEDRAS NEGRAS, Coahuila. 11 de noviembre de 2024. Como un s\u00edmbolo de<br>avance, de inclusi\u00f3n y de cambio para la Universidad Aut\u00f3noma de Coahuila, el<br>rector Octavio Pimentel Mart\u00ednez, tom\u00f3 protesta a la primera directora de la historia<br>de los tres planteles de medicina con los que cuenta la m\u00e1xima casa de estudios, a<br>la Dra. Georgina Rodr\u00edguez Bustos de la Escuela de Medicina Unidad Norte.<\/p>\n\n\n\n<p>En gira de trabajo por la UN, el Rector acompa\u00f1ado por el coordinador, Luis Carlos<br>Talamantes Arredondo y el director saliente, Juan Manuel Cardona, afirm\u00f3 que la<br>toma de protesta de la Dra. Rodr\u00edguez Bustos es muestra del esfuerzo al<br>compromiso institucional con la igualdad y equidad de g\u00e9nero.<\/p>\n\n\n\n<p>Dijo que este logro no es solo un reconocimiento a una trayectoria destacada, sino<br>un triunfo de todas las mujeres que han luchado para abrir espacios en la ciencia, en<br>la medicina, en la academia y la pol\u00edtica universitaria, y la Dra. Rodr\u00edguez Bustos,<br>con su liderazgo y compromiso, se convierte en un referente y un ejemplo para las<br>generaciones que vienen detr\u00e1s e inspiraci\u00f3n de estudiantes y docentes.<\/p>\n\n\n\n<p>Pimentel Mart\u00ednez, expres\u00f3 a la directora que, en la Universidad Aut\u00f3noma de<br>Coahuila, los principios que sostienen el desarrollo acad\u00e9mico, son la Lucha, la<br>Libertad, el Legado, el Liderazgo y la Lealtad, por lo que encuentran en su<br>nombramiento un sentido profundo y renovado, en una gesti\u00f3n que sin duda ser\u00e1<br>una manifestaci\u00f3n de liderazgo integral y de lealtad hacia las mujeres universitarias.<\/p>\n\n\n\n<p>Al director saliente, el Dr. Juan Manuel Cardona, el Rector le reconoci\u00f3 su liderazgo<br>que permiti\u00f3 generar avances en la consolidaci\u00f3n de cuerpos acad\u00e9micos, impuls\u00f3<br>la creaci\u00f3n de nuevos departamentos de investigaci\u00f3n, logr\u00f3 hist\u00f3ricamente acreditar<br>nacional e internacionalmente el programa de estudios y su labor invaluable en<br>programas como &#8220;Lobos al Rescate&#8221; y en el \u00e1rea de Vinculaci\u00f3n Social.<\/p>\n\n\n\n<p>Por su parte, la directora Georgina Rodr\u00edguez Bustos, rememor\u00f3 su llegada al<br>plantel, en donde dijo, encontr\u00f3 adem\u00e1s de colegas m\u00e9dicos, compa\u00f1eros docentes,<br>personal administrativo, encontr\u00f3 amigos, universitarios de coraz\u00f3n como el Dr.<br>Tomas Palomo P\u00e9rez, uno de sus m\u00e1s grandes mentores.<\/p>\n\n\n\n<p>\u201cEncontr\u00e9 mujeres valientes como la Dra. Irma Vald\u00e9s, que, gracias a su trabajo, se<br>ha dado voz y visibilidad a las mujeres en esta escuela, permiti\u00e9ndonos alcanzar<br>nuestro potencial y brillar en espacios que hist\u00f3ricamente nos fueron negados, hoy<br>es un d\u00eda de gran importancia en mi vida profesional y personal, asumo el honor y la<br>responsabilidad de dirigir esta escuela de medicina, una instituci\u00f3n que no solo<br>forma m\u00e9dicos, sino que construye el futuro de la salud y el bienestar de nuestra<br>sociedad\u201d, afirm\u00f3 Rodr\u00edguez Bustos.<\/p>\n\n\n\n<p>Agradeci\u00f3 el apoyo de su equipo de trabajo, el de su familia, de estudiantes y<br>docentes que le permiten emprender una responsabilidad tan importante como la de<\/p>\n\n\n\n<p>dirigir a la Escuela de Medicina Unidad Norte, por compartir su entusiasmo e<br>inspiraci\u00f3n de aprender, y por el compromiso y dedicaci\u00f3n en la ense\u00f1anza.<\/p>\n\n\n\n<p>\u201cEl entorno de la educaci\u00f3n m\u00e9dica actual es din\u00e1mico, retador y exige de nosotros<br>una visi\u00f3n innovadora y un compromiso con la excelencia, nuestra misi\u00f3n es clara:<br>formar profesionales de la salud con conocimientos s\u00f3lidos, habilidades cl\u00ednicas<br>sobresalientes y una profunda sensibilidad humana\u201d, afirm\u00f3 la Dra. Georgina.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que el compromiso con la excelencia no se logra de manera aislada, el<br>liderazgo debe ser compartido, inclusivo y debe enfocarse en escuchar, aprender y<br>construir colectivamente, por ello asume el desaf\u00edo de integrar la investigaci\u00f3n, la<br>ense\u00f1anza y la pr\u00e1ctica m\u00e9dica, para que cada egresado se convierta en un agente<br>de cambio positivo en la sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIEDRAS NEGRAS, Coahuila. 11 de noviembre de 2024. Como un s\u00edmbolo deavance, de inclusi\u00f3n y de cambio para la Universidad Aut\u00f3noma de Coahuila, elrector Octavio Pimentel Mart\u00ednez, tom\u00f3 protesta a la primera directora de la historiade los tres planteles de medicina con los que cuenta la m\u00e1xima casa de estudios, ala Dra. Georgina Rodr\u00edguez Bustos de la Escuela de Medicina Unidad Norte. En gira de trabajo por la UN, el&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23381,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-23380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uadec","wpcat-2-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23380"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23380\/revisions"}],"predecessor-version":[{"id":23382,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23380\/revisions\/23382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23381"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}