{"id":23702,"date":"2024-12-03T20:27:00","date_gmt":"2024-12-04T02:27:00","guid":{"rendered":"https:\/\/www.aquilaguna.com\/?p=23702"},"modified":"2024-12-03T20:34:13","modified_gmt":"2024-12-04T02:34:13","slug":"roman-alberto-cepeda-gonzalez-entrego-al-cabildo-el-tercer-informe-sobre-el-estado-que-guarda-la-administracion-municipal","status":"publish","type":"post","link":"https:\/\/www.aquilaguna.com\/index.php\/2024\/12\/03\/roman-alberto-cepeda-gonzalez-entrego-al-cabildo-el-tercer-informe-sobre-el-estado-que-guarda-la-administracion-municipal\/","title":{"rendered":"Rom\u00e1n Alberto Cepeda Gonz\u00e1lez entreg\u00f3 al Cabildo, el Tercer Informe sobre el estado que guarda la Administraci\u00f3n Municipal."},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 3 de diciembre de 2024.<\/p>\n\n\n\n<p>El alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez entreg\u00f3 durante la Novena Sesi\u00f3n<br>Solemne de Cabildo, el Tercer Informe de Resultados sobre el estado que guarda<br>la Administraci\u00f3n P\u00fablica Municipal, en donde destac\u00f3: las finanzas sanas,<br>inversi\u00f3n hist\u00f3rica en infraestructura, seguridad, as\u00ed como la proyecci\u00f3n nacional e<br>internacional de Torre\u00f3n que se traducen en atracci\u00f3n tur\u00edstica y desarrollo<br>econ\u00f3mico.<\/p>\n\n\n\n<p>La ceremonia fue la ma\u00f1ana de este martes en la Sala de Cabildo de Presidencia<br>Municipal, y ante la presencia de directores municipales e invitados especiales,<br>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez entreg\u00f3 el libro que contiene el informe al primer<br>regidor, Luis Jorge Cuerda Serna.<\/p>\n\n\n\n<p>En su mensaje, el edil dijo que con voluntad, trabajo y compromiso, la<br>Administraci\u00f3n logr\u00f3 cumplir al 100 por ciento con los compromisos municipales.<br>\u00a0<br>Dentro de su informe, el Presidente Municipal dio cuenta de la productividad<br>lograda por el Cabildo de Torre\u00f3n durante el periodo 2022-2023-2024, con la<br>realizaci\u00f3n de m\u00e1s de 60 sesiones, incluyendo las extraordinarias y solemnes.<br>\u00a0<br>Resultado de las sesiones del \u00f3rgano colegiado, el edil indic\u00f3 que se lograron<br>tomar m\u00e1s de 700 acuerdos, de los cuales m\u00e1s del 88 por ciento fueron por<br>unanimidad, lo que refleja un s\u00f3lido consenso en favor de la construcci\u00f3n de un<br>mejor Torre\u00f3n.<br>\u00a0<br>Por otro lado, el Alcalde indic\u00f3 que durante la actual Administraci\u00f3n Municipal<br>2022-2023-2024, se crearon y fortalecieron consejos ciudadanos para garantizar<br>pol\u00edticas p\u00fablicas diversas, transparentes e incluyentes, como el comit\u00e9 ciudadano<br>para el proceso de Entrega-Recepci\u00f3n.<br>\u00a0<br>Adem\u00e1s, inform\u00f3 que por cinco trimestres consecutivos, se obtuvo el 100 por<br>ciento de cumplimiento en las evaluaciones de transparencia.<br>\u00a0<br>\u201cEn esta Administraci\u00f3n, logramos resultados que mejoran la confianza ciudadana,<br>y hoy Torre\u00f3n se posiciona como una de las ciudades m\u00e1s seguras de M\u00e9xico,<br>gracias a pol\u00edticas efectivas y al fortalecimiento de la seguridad\u201d, se\u00f1al\u00f3.<br>\u00a0<br>De igual forma, resalt\u00f3 la inversi\u00f3n hist\u00f3rica en infraestructura con m\u00e1s de mil 300<br>millones de pesos destinados a obra p\u00fablica, marcando un hecho sin precedentes<\/p>\n\n\n\n<p>en el desarrollo de la ciudad como el Giro Independencia; y en colaboraci\u00f3n con el<br>Gobierno del Estado, el Sistema Vial Cuatro Caminos.<\/p>\n\n\n\n<p>Tambi\u00e9n hizo un recuento de otras obras importantes como el bulevar Torre\u00f3n-<br>Norte, la primera etapa del Paso Villa Florida, el nuevo Centro de Justicia<br>Municipal, el edificio de Tr\u00e1nsito y Vialidad, la rehabilitaci\u00f3n de la avenida Ju\u00e1rez,<br>las bases para el nuevo Centro Cultural del Norte, la colocaci\u00f3n de m\u00e1s de 2 mil<br>barreras de concreto, la rehabilitaci\u00f3n de 450 plazas, la construcci\u00f3n de 60<br>nuevas, la creaci\u00f3n de m\u00e1s de 50 techumbres, as\u00ed como la rehabilitaci\u00f3n de sitios<br>emblem\u00e1ticos como la Alameda Zaragoza, Unidad Deportiva, y Bosque Urbano,<br>entre otras acciones.<br>\u00a0<br>Cepeda Gonz\u00e1lez inform\u00f3 que se pavimentaron m\u00e1s de 3 millones de metros<br>cuadrados en la ciudad.<br>\u00a0<br>Acerca de la atracci\u00f3n de inversiones, el Alcalde mencion\u00f3 que m\u00e1s de 20<br>grandes empresas se instalaron o expandieron sus operaciones en Torre\u00f3n,<br>generando empleo y oportunidades econ\u00f3micas.<br>\u00a0<br>Tambi\u00e9n dijo que comenz\u00f3 la construcci\u00f3n de siete nuevos parques industriales,<br>consolidando a Torre\u00f3n como un polo estrat\u00e9gico para la industria.<br>\u00a0<br>Por otra parte, el Presidente Municipal inform\u00f3 sobre la incorporaci\u00f3n a la red de<br>31 pozos de agua; la instalaci\u00f3n de m\u00e1s de 50 mil metros lineales de drenaje, y<br>del programa de reparaci\u00f3n a fugas con el que se logr\u00f3 un ahorro equivalente a<br>cinco pozos nuevos.<br>\u00a0<br>En cuanto al posicionamiento nacional e internacional de la ciudad, el edil destac\u00f3<br>que se puso a Torre\u00f3n en los ojos de M\u00e9xico y el mundo, al ser sede de eventos<br>de talla mundial, destacando la capacidad para competir en el escenario global,<br>con la realizaci\u00f3n de eventos como la celebraci\u00f3n del eclipse total solar, con miles<br>de visitantes de todo el mundo.<br>\u00a0<br>\u201cGracias al programa cultural, en estos tres a\u00f1os han acudido m\u00e1s de 2.3 millones<br>de visitas a nuestros eventos, un n\u00famero r\u00e9cord de nuestro municipio\u201d, dijo el<br>mun\u00edcipe.<br>\u00a0<br>Cepeda Gonz\u00e1lez se\u00f1al\u00f3 tambi\u00e9n que durante su Administraci\u00f3n se logr\u00f3 activar a<br>m\u00e1s de 200 mil torreonenses en el tema deportivo. Se cre\u00f3 el programa de<br>Unidades M\u00e9dicas M\u00f3viles y hoy Torre\u00f3n es referente por contar con el primer<br>banco municipal de sangre del pa\u00eds.<br>\u00a0<br>En la labor a trav\u00e9s del DIF Torre\u00f3n, el Alcalde destac\u00f3 acciones como los<br>programas: \u201cUn Nuevo Paso\u201d, \u201cDe Ruedas Coraz\u00f3n\u201d, y el de \u201cT\u00fa Tambi\u00e9n Puedes<br>Ver y Escuchar\u201d.<br>\u00a0<\/p>\n\n\n\n<p>Tambi\u00e9n se instituy\u00f3 el D\u00eda del Empacador Voluntario, y en un hecho hist\u00f3rico, dijo<br>el edil, ser\u00e1 inaugurada ma\u00f1ana la Casa Nana.<br>&nbsp;<br>Cepeda Gonz\u00e1lez agreg\u00f3 que los logros en su gesti\u00f3n, no solo reflejan el esfuerzo<br>de la Administraci\u00f3n, sino tambi\u00e9n la colaboraci\u00f3n y compromiso de toda la<br>ciudadan\u00eda, y que todo fue posible por un uso responsable de los recursos<br>p\u00fablicos al tener Torre\u00f3n finanzas sanas.<br>&nbsp;<br>\u201cMi agradecimiento a todos y cada uno de ustedes por su invaluable participaci\u00f3n<br>durante esta Administraci\u00f3n. Su compromiso con el debate respetuoso de ideas, la<br>b\u00fasqueda constante del consenso y la disposici\u00f3n para construir acuerdos en<br>beneficio de Torre\u00f3n han sido fundamentales para lograr avances significativos en<br>nuestra ciudad\u201d, expres\u00f3 al Cabildo.<br>&nbsp;<br>Reiter\u00f3 que gracias al trabajo y dedicaci\u00f3n del \u00f3rgano colegiado, se logr\u00f3<br>consolidar pol\u00edticas p\u00fablicas, que se centraron en el bienestar de la comunidad.<br>&nbsp;<br>\u201cEl trabajo no se detiene. Desde nuestras trincheras, desde cualquier lugar donde<br>nos encontremos, Torre\u00f3n siempre requerir\u00e1 de nuestro compromiso, nuestra<br>dedicaci\u00f3n y nuestra voluntad para construir una mejor ciudad. Hoy renovamos<br>nuestra convicci\u00f3n de que, con esfuerzo y colaboraci\u00f3n, \u00a1siempre se puede!<br>Sigamos adelante, porque el futuro de nuestra ciudad nos necesita a todos\u201d, dijo<br>Rom\u00e1n Alberto Cepeda Gonz\u00e1lez.<br>&nbsp;<br>Al inicio de la Sesi\u00f3n Solemne, se realizaron los Honores a la Bandera, a cargo de<br>la Escolta y Banda de Guerra de la XI Regi\u00f3n Militar y la entonaci\u00f3n del Himno<br>Nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 3 de diciembre de 2024. El alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez entreg\u00f3 durante la Novena Sesi\u00f3nSolemne de Cabildo, el Tercer Informe de Resultados sobre el estado que guardala Administraci\u00f3n P\u00fablica Municipal, en donde destac\u00f3: las finanzas sanas,inversi\u00f3n hist\u00f3rica en infraestructura, seguridad, as\u00ed como la proyecci\u00f3n nacional einternacional de Torre\u00f3n que se traducen en atracci\u00f3n tur\u00edstica y desarrolloecon\u00f3mico. La ceremonia fue la ma\u00f1ana de este martes en la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":23703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,28,7],"tags":[],"class_list":["post-23702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coahuila","category-la-laguna","category-torreon","wpcat-5-id","wpcat-28-id","wpcat-7-id"],"_links":{"self":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/comments?post=23702"}],"version-history":[{"count":1,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23702\/revisions"}],"predecessor-version":[{"id":23704,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/posts\/23702\/revisions\/23704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media\/23703"}],"wp:attachment":[{"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/media?parent=23702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/categories?post=23702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aquilaguna.com\/index.php\/wp-json\/wp\/v2\/tags?post=23702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}